{"id":44403,"date":"2023-03-10T02:25:14","date_gmt":"2023-03-10T02:25:14","guid":{"rendered":"https:\/\/thailand.worldtradeshow.tv\/?p=44403"},"modified":"2023-03-10T02:25:14","modified_gmt":"2023-03-10T02:25:14","slug":"akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/thai\/video\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\/","title":{"rendered":"[\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 57 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2566] \u0e44\u0e01\u0e48\u0e2d\u0e32\u0e04\u0e34\u0e15\u0e30\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e17\u0e2d\u0e07 Hinaiji - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2d\u0e32\u0e01\u0e34\u0e15\u0e30 \u0e23\u0e35\u0e44\u0e27\u0e17\u0e31\u0e25\u0e44\u0e25\u0e40\u0e0b\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14"},"content":{"rendered":"<p>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2d\u0e32\u0e01\u0e34\u0e15\u0e30 \u0e23\u0e35\u0e44\u0e27\u0e17\u0e31\u0e25\u0e44\u0e25\u0e40\u0e0b\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e08\u0e31\u0e14\u0e41\u0e2a\u0e14\u0e07 \u0e44\u0e01\u0e48\u0e2d\u0e32\u0e04\u0e34\u0e15\u0e30\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e17\u0e2d\u0e07 Hinaiji \u0e17\u0e35\u0e48 \u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 57 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2566.<\/p>\n<\/p>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/smts_2023_02\/smts_2023_02_12-1.jpg\"><\/div>\n<div class=\"caption_text\">\u0e09\u0e31\u0e19\u0e21\u0e32\u0e08\u0e32\u0e01\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2d\u0e32\u0e04\u0e34\u0e15\u0e30 \u0e08\u0e32\u0e01 Akita Revitalization Co.<br \/>\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e19\u0e33\u0e0a\u0e38\u0e14\u0e04\u0e34\u0e23\u0e34\u0e17\u0e31\u0e21\u0e42\u0e1b\u0e30 (\u0e04\u0e34\u0e23\u0e34\u0e17\u0e31\u0e21\u0e42\u0e1b\u0e30\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e49\u0e01\u0e02\u0e49\u0e32\u0e27) \u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32\u0e17\u0e32\u0e21\u0e32\u0e40\u0e15\u0e1a\u0e32\u0e42\u0e01\u0e30\u0e41\u0e25\u0e30\u0e2e\u0e34\u0e44\u0e19\u0e08\u0e34\u0e42\u0e14\u0e23\u0e34\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07 (\u0e44\u0e01\u0e48\u0e2e\u0e34\u0e44\u0e19)<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/smts_2023_02\/smts_2023_02_12-8.jpg\"><\/div>\n<div class=\"caption_text\">\u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e36\u0e49\u0e19\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e42\u0e04\u0e42\u0e23\u0e19\u0e32\u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e44\u0e01\u0e48 Hinai Jidori \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e1f\u0e43\u0e19\u0e23\u0e49\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2d\u0e35\u0e01\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e41\u0e25\u0e30\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e01\u0e34\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19\u0e40\u0e23\u0e32\u0e08\u0e36\u0e07\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e17\u0e33\u0e1a\u0e32\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e44\u0e01\u0e48 Hinai Jidori<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/smts_2023_02\/smts_2023_02_12-22.jpg\"><\/div>\n<div class=\"caption_text\">\u0e21\u0e31\u0e19\u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e19\u0e34\u0e22\u0e21\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e17\u0e33\u0e01\u0e32\u0e23\u0e02\u0e32\u0e22\u0e21\u0e31\u0e19<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/smts_2023_02\/smts_2023_02_12-29.jpg\"><\/div>\n<div class=\"caption_text\">\u0e40\u0e23\u0e32\u0e22\u0e31\u0e07\u0e04\u0e07\u0e43\u0e0a\u0e49\u0e27\u0e31\u0e15\u0e16\u0e38\u0e40\u0e08\u0e37\u0e2d\u0e1b\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e43\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2d\u0e32\u0e04\u0e34\u0e15\u0e30 \u0e40\u0e0a\u0e48\u0e19 \u0e40\u0e01\u0e25\u0e37\u0e2d \u0e01\u0e23\u0e30\u0e40\u0e17\u0e35\u0e22\u0e21 \u0e41\u0e25\u0e30\u0e0b\u0e35\u0e2d\u0e34\u0e4a\u0e27\u0e08\u0e32\u0e01\u0e23\u0e49\u0e32\u0e19\u0e02\u0e32\u0e22\u0e0b\u0e35\u0e2d\u0e34\u0e4a\u0e27\u0e43\u0e19\u0e04\u0e32\u0e04\u0e38\u0e42\u0e19\u0e14\u0e32\u0e40\u0e15\u0e30 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2d\u0e32\u0e04\u0e34\u0e15\u0e30 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e1c\u0e25\u0e34\u0e15\u0e43\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2d\u0e32\u0e04\u0e34\u0e15\u0e30<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/smts_2023_02\/smts_2023_02_12-43.jpg\"><\/div>\n<div class=\"caption_text\">\u0e40\u0e23\u0e32\u0e21\u0e35\u0e2b\u0e49\u0e32\u0e23\u0e2a\u0e0a\u0e32\u0e15\u0e34\u0e17\u0e35\u0e48\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e23\u0e32\u0e02\u0e32\u0e22\u0e41\u0e22\u0e01\u0e15\u0e48\u0e32\u0e07\u0e2b\u0e32\u0e01 \u0e41\u0e15\u0e48\u0e40\u0e23\u0e32\u0e02\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e38\u0e14\u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d\u0e14\u0e49\u0e27\u0e22  <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2d\u0e32\u0e01\u0e34\u0e15\u0e30 \u0e23\u0e35\u0e44\u0e27\u0e17\u0e31\u0e25\u0e44\u0e25\u0e40\u0e0b\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e08\u0e31\u0e14\u0e41\u0e2a\u0e14\u0e07 \u0e44\u0e01\u0e48\u0e2d\u0e32\u0e04\u0e34\u0e15\u0e30\u0e01\u0e23\u0e30 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":44404,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[103],"tags":[64,74,25,31,76],"class_list":["post-44403","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-103","tag-transportation-logistics-packaging","tag-information-telecommunication","tag-services","tag-japan","tag-agriculture-forestry-fishery-and-food","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 57 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2566] \u0e44\u0e01\u0e48\u0e2d\u0e32\u0e04\u0e34\u0e15\u0e30\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e17\u0e2d\u0e07 Hinaiji - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2d\u0e32\u0e01\u0e34\u0e15\u0e30 \u0e23\u0e35\u0e44\u0e27\u0e17\u0e31\u0e25\u0e44\u0e25\u0e40\u0e0b\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 \u2013 \u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/thai\/video\/\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 57 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2566] \u0e44\u0e01\u0e48\u0e2d\u0e32\u0e04\u0e34\u0e15\u0e30\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e17\u0e2d\u0e07 Hinaiji - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2d\u0e32\u0e01\u0e34\u0e15\u0e30 \u0e23\u0e35\u0e44\u0e27\u0e17\u0e31\u0e25\u0e44\u0e25\u0e40\u0e0b\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 \u2013 \u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2d\u0e32\u0e01\u0e34\u0e15\u0e30 \u0e23\u0e35\u0e44\u0e27\u0e17\u0e31\u0e25\u0e44\u0e25\u0e40\u0e0b\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e08\u0e31\u0e14\u0e41\u0e2a\u0e14\u0e07 \u0e44\u0e01\u0e48\u0e2d\u0e32\u0e04\u0e34\u0e15\u0e30\u0e01\u0e23\u0e30 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/thai\/video\/\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e21\u0e48 \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-10T02:25:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/thai\/wp-content\/uploads\/2023\/03\/maxresdefault-42.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/video\\\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\\\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/video\\\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\\\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/#\\\/schema\\\/person\\\/638dd6edf11fc6d2cf9b326263448a72\"},\"headline\":\"[\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 57 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2566] \u0e44\u0e01\u0e48\u0e2d\u0e32\u0e04\u0e34\u0e15\u0e30\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e17\u0e2d\u0e07 Hinaiji - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2d\u0e32\u0e01\u0e34\u0e15\u0e30 \u0e23\u0e35\u0e44\u0e27\u0e17\u0e31\u0e25\u0e44\u0e25\u0e40\u0e0b\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\",\"datePublished\":\"2023-03-10T02:25:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/video\\\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\\\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\\\/\"},\"wordCount\":10,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/video\\\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\\\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/maxresdefault-42.jpg\",\"keywords\":[\"\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \\\/ \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \\\/ \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\",\"\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \\\/ \u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\",\"\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\",\"\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\",\"\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21 \\\/ \u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \\\/ \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e07\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\"],\"articleSection\":[\"\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 57 (SMTS) \u0e1b\u0e35 2566\"],\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/video\\\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\\\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/video\\\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\\\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/video\\\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\\\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\\\/\",\"name\":\"[\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 57 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2566] \u0e44\u0e01\u0e48\u0e2d\u0e32\u0e04\u0e34\u0e15\u0e30\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e17\u0e2d\u0e07 Hinaiji - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2d\u0e32\u0e01\u0e34\u0e15\u0e30 \u0e23\u0e35\u0e44\u0e27\u0e17\u0e31\u0e25\u0e44\u0e25\u0e40\u0e0b\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 \u2013 \u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/video\\\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\\\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/video\\\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\\\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/maxresdefault-42.jpg\",\"datePublished\":\"2023-03-10T02:25:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/#\\\/schema\\\/person\\\/638dd6edf11fc6d2cf9b326263448a72\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/video\\\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\\\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/video\\\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\\\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/video\\\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\\\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/maxresdefault-42.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/maxresdefault-42.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/video\\\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\\\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 57 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2566] \u0e44\u0e01\u0e48\u0e2d\u0e32\u0e04\u0e34\u0e15\u0e30\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e17\u0e2d\u0e07 Hinaiji - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2d\u0e32\u0e01\u0e34\u0e15\u0e30 \u0e23\u0e35\u0e44\u0e27\u0e17\u0e31\u0e25\u0e44\u0e25\u0e40\u0e0b\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/\",\"name\":\"\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e21\u0e48 \u2013 WorldTradeShow.TV\",\"description\":\"\u0e04\u0e49\u0e19\u0e1e\u0e1a\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e21\u0e48\u0e43\u0e19\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/thai\\\/#\\\/schema\\\/person\\\/638dd6edf11fc6d2cf9b326263448a72\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/L4QOhuzsr0s\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"62\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 57 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2566] \u0e44\u0e01\u0e48\u0e2d\u0e32\u0e04\u0e34\u0e15\u0e30\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e17\u0e2d\u0e07 Hinaiji - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2d\u0e32\u0e01\u0e34\u0e15\u0e30 \u0e23\u0e35\u0e44\u0e27\u0e17\u0e31\u0e25\u0e44\u0e25\u0e40\u0e0b\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 \u2013 \u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/thai\/video\/\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\/","og_locale":"th_TH","og_type":"article","og_title":"[\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 57 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2566] \u0e44\u0e01\u0e48\u0e2d\u0e32\u0e04\u0e34\u0e15\u0e30\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e17\u0e2d\u0e07 Hinaiji - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2d\u0e32\u0e01\u0e34\u0e15\u0e30 \u0e23\u0e35\u0e44\u0e27\u0e17\u0e31\u0e25\u0e44\u0e25\u0e40\u0e0b\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 \u2013 \u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 | WorldTradeShow.TV","og_description":"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2d\u0e32\u0e01\u0e34\u0e15\u0e30 \u0e23\u0e35\u0e44\u0e27\u0e17\u0e31\u0e25\u0e44\u0e25\u0e40\u0e0b\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e08\u0e31\u0e14\u0e41\u0e2a\u0e14\u0e07 \u0e44\u0e01\u0e48\u0e2d\u0e32\u0e04\u0e34\u0e15\u0e30\u0e01\u0e23\u0e30 [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/thai\/video\/\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\/","og_site_name":"\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e21\u0e48 \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2023-03-10T02:25:14+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/thai\/wp-content\/uploads\/2023\/03\/maxresdefault-42.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"Written by":"user"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/thai\/video\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/thai\/video\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/thai\/#\/schema\/person\/638dd6edf11fc6d2cf9b326263448a72"},"headline":"[\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 57 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2566] \u0e44\u0e01\u0e48\u0e2d\u0e32\u0e04\u0e34\u0e15\u0e30\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e17\u0e2d\u0e07 Hinaiji - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2d\u0e32\u0e01\u0e34\u0e15\u0e30 \u0e23\u0e35\u0e44\u0e27\u0e17\u0e31\u0e25\u0e44\u0e25\u0e40\u0e0b\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14","datePublished":"2023-03-10T02:25:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/thai\/video\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\/"},"wordCount":10,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/thai\/video\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/thai\/wp-content\/uploads\/2023\/03\/maxresdefault-42.jpg","keywords":["\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07 \/ \u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \/ \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c","\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \/ \u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e42\u0e17\u0e23\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21","\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23","\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19","\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21 \/ \u0e1b\u0e48\u0e32\u0e44\u0e21\u0e49 \/ \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e07\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23"],"articleSection":["\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 57 (SMTS) \u0e1b\u0e35 2566"],"inLanguage":"th","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/thai\/video\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/thai\/video\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\/","url":"https:\/\/www.worldtradeshow.tv\/thai\/video\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\/","name":"[\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 57 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2566] \u0e44\u0e01\u0e48\u0e2d\u0e32\u0e04\u0e34\u0e15\u0e30\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e17\u0e2d\u0e07 Hinaiji - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2d\u0e32\u0e01\u0e34\u0e15\u0e30 \u0e23\u0e35\u0e44\u0e27\u0e17\u0e31\u0e25\u0e44\u0e25\u0e40\u0e0b\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 \u2013 \u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/thai\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/thai\/video\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/thai\/video\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/thai\/wp-content\/uploads\/2023\/03\/maxresdefault-42.jpg","datePublished":"2023-03-10T02:25:14+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/thai\/#\/schema\/person\/638dd6edf11fc6d2cf9b326263448a72"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/thai\/video\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/thai\/video\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.worldtradeshow.tv\/thai\/video\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/thai\/wp-content\/uploads\/2023\/03\/maxresdefault-42.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/thai\/wp-content\/uploads\/2023\/03\/maxresdefault-42.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/thai\/video\/%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87%e0%b8%aa%e0%b8%b4%e0%b8%99%e0%b8%84%e0%b9%89%e0%b8%b2%e0%b8%8b%e0%b8%b8%e0%b8%9b%e0%b9%80%e0%b8%9b%e0%b8%ad%e0%b8%a3%e0%b9%8c%e0%b8%a1\/akita-can-gold-hinaiji-chicken_akita-revitalization-co-ltd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.worldtradeshow.tv\/thai\/"},{"@type":"ListItem","position":2,"name":"[\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e40\u0e01\u0e47\u0e15\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 57 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2566] \u0e44\u0e01\u0e48\u0e2d\u0e32\u0e04\u0e34\u0e15\u0e30\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e17\u0e2d\u0e07 Hinaiji - \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2d\u0e32\u0e01\u0e34\u0e15\u0e30 \u0e23\u0e35\u0e44\u0e27\u0e17\u0e31\u0e25\u0e44\u0e25\u0e40\u0e0b\u0e0a\u0e31\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/thai\/#website","url":"https:\/\/www.worldtradeshow.tv\/thai\/","name":"\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e21\u0e48 \u2013 WorldTradeShow.TV","description":"\u0e04\u0e49\u0e19\u0e1e\u0e1a\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e2b\u0e21\u0e48\u0e43\u0e19\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/thai\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/thai\/#\/schema\/person\/638dd6edf11fc6d2cf9b326263448a72","name":"user","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/L4QOhuzsr0s","og_video_type":"text\/html","og_video_duration":"62","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=L4QOhuzsr0s","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/thai\/wp-json\/wp\/v2\/posts\/44403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/thai\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/thai\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/thai\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/thai\/wp-json\/wp\/v2\/comments?post=44403"}],"version-history":[{"count":0,"href":"https:\/\/www.worldtradeshow.tv\/thai\/wp-json\/wp\/v2\/posts\/44403\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/thai\/wp-json\/wp\/v2\/media\/44404"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/thai\/wp-json\/wp\/v2\/media?parent=44403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/thai\/wp-json\/wp\/v2\/categories?post=44403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/thai\/wp-json\/wp\/v2\/tags?post=44403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}