{"id":58553,"date":"2026-07-08T06:06:44","date_gmt":"2026-07-08T06:06:44","guid":{"rendered":"https:\/\/www.worldtradeshow.tv\/portuguese\/?p=58553"},"modified":"2026-09-01T06:06:57","modified_gmt":"2026-09-01T06:06:57","slug":"performance-fabrics-psd-group-gft-2026","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/portuguese\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/","title":{"rendered":"Tecidos de alto desempenho - PSD Group [GFT 2026]"},"content":{"rendered":"<div class=\"entry-content \">\n<blockquote class=\"wp-block-quote\">\n<p>Na ind\u00fastria de vestu\u00e1rio, materiais sustent\u00e1veis \u200b\u200be tecidos de alto desempenho est\u00e3o se tornando requisitos importantes para marcas, fabricantes de uniformes e fabricantes de roupas OEM. Para aplica\u00e7\u00f5es em uniformes, em particular, os tecidos devem apresentar problemas como forma\u00e7\u00e3o de bolinhas, desbotamento da cor, manuten\u00e7\u00e3o da forma, conforto e durabilidade ap\u00f3s lavagens repetidas, sem comprometer a flexibilidade de design.<br \/>Na GFT 2026, o Grupo PSD apresentou sua capacidade de produ\u00e7\u00e3o verticalmente integrada, abrangendo fios de nylon, tecidos de malha e pe\u00e7as de vestu\u00e1rio acabadas. No estande, a empresa apresentou um tecido para vestu\u00e1rio feito com nylon reciclado derivado de redes de pesca usadas, oferecendo uma op\u00e7\u00e3o de material para marcas que buscam solu\u00e7\u00f5es t\u00eaxteis mais sustent\u00e1veis.<br \/>A empresa tamb\u00e9m apresentou tecidos jacquard que suportam estampas personalizadas. Os clientes podem fornecer o design desejado e o PSD Group pode tecer a estampa no tecido jacquard para camisas, roupas casuais, uniformes ou desenvolvimento de vestu\u00e1rio espec\u00edfico para cada marca.<br \/>Para aplica\u00e7\u00f5es em uniformes, o Grupo PSD lan\u00e7ou seu tecido Kinetic Performance Polo, feito de poli\u00e9ster com elastano. Comparado com tecidos de algod\u00e3o ou misturas de algod\u00e3o que podem formar bolinhas ou desbotar ap\u00f3s lavagens repetidas, o tecido de poli\u00e9ster com elastano oferece elasticidade, conforto e durabilidade. A empresa o descreveu como um tecido que mant\u00e9m sua forma mesmo ap\u00f3s mais de 50 lavagens, tornando-o relevante para fabricantes de uniformes e empresas OEM de vestu\u00e1rio.<\/p>\n<\/blockquote>\n<div class=\"video-summary-grid\">\n<div class=\"summary-card\">\n<h3>Desafios abordados<\/h3>\n<ul>\n<li><a href=\"\/portuguese\/?s=Materiais%20sustent%C3%A1veis%20%E2%80%8B%E2%80%8Bpara%20vestu%C3%A1rio&#038;post_type=post\">Materiais sustent\u00e1veis \u200b\u200bpara vestu\u00e1rio<\/a><\/li>\n<li><a href=\"\/portuguese\/?s=Forma%C3%A7%C3%A3o%20de%20bolinhas%20e%20desbotamento%20da%20cor&#038;post_type=post\">Forma\u00e7\u00e3o de bolinhas e desbotamento da cor<\/a><\/li>\n<li><a href=\"\/portuguese\/?s=Desenvolvimento%20de%20tecido%20personalizado&#038;post_type=post\">Desenvolvimento de tecido personalizado<\/a><\/li>\n<\/ul>\n<\/div>\n<div class=\"summary-card\">\n<h3>Solu\u00e7\u00f5es<\/h3>\n<ul>\n<li><a href=\"\/portuguese\/?s=Tecido%20de%20nylon%20reciclado&#038;post_type=post\">Tecido de nylon reciclado<\/a><\/li>\n<li><a href=\"\/portuguese\/?s=Tecido%20Jacquard&#038;post_type=post\">Tecido Jacquard<\/a><\/li>\n<li><a href=\"\/portuguese\/?s=Tecido%20Kinetic%20Performance%20Polo&#038;post_type=post\">Tecido Kinetic Performance Polo<\/a><\/li>\n<\/ul>\n<\/div>\n<div class=\"summary-card\">\n<h3>Clientes-alvo<\/h3>\n<ul>\n<li><a href=\"\/portuguese\/?s=Fabricantes%20de%20vestu%C3%A1rio&#038;post_type=post\">Fabricantes de vestu\u00e1rio<\/a><\/li>\n<li><a href=\"\/portuguese\/?s=Fabricantes%20de%20uniformes&#038;post_type=post\">Fabricantes de uniformes<\/a><\/li>\n<li><a href=\"\/portuguese\/?s=Comerciantes%20t%C3%AAxteis%20e%20fabricantes%20de%20equipamentos%20originais%20%28OEMs%29%20de%20vestu%C3%A1rio&#038;post_type=post\">Comerciantes t\u00eaxteis e fabricantes de equipamentos originais (OEMs) de vestu\u00e1rio<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div class=\"video-faq\">\n<h3 class=\"faq-heading\">Perguntas frequentes<\/h3>\n<details class=\"faq-item\">\n<summary>O que o Grupo PSD apresentou na GFT 2026?<\/summary>\n<div class=\"faq-answer\">O Grupo PSD apresentou tecido de vestu\u00e1rio em nylon reciclado, feito a partir de redes de pesca usadas, tecidos jacquard personalizados e o tecido Kinetic Performance Polo para aplica\u00e7\u00f5es em uniformes.<\/div>\n<\/details>\n<details class=\"faq-item\">\n<summary>O tecido jacquard pode ser personalizado?<\/summary>\n<div class=\"faq-answer\">Sim. Os clientes podem fornecer o padr\u00e3o desejado e o Grupo PSD pode tec\u00ea-lo em tecido jacquard para produtos de vestu\u00e1rio, como camisas e pe\u00e7as personalizadas.<\/div>\n<\/details>\n<details class=\"faq-item\">\n<summary>Qual a vantagem do tecido uniforme?<\/summary>\n<div class=\"faq-answer\">O tecido da polo Kinetic Performance, feito de poli\u00e9ster e elastano, oferece elasticidade, conforto, resist\u00eancia ao desbotamento e mant\u00e9m a forma mesmo ap\u00f3s mais de 50 lavagens.<\/div>\n<\/details>\n<\/div>\n<details class=\"video-transcript\">\n<summary>Ver transcri\u00e7\u00e3o do v\u00eddeo<\/summary>\n<div class=\"transcript-content\">Ol\u00e1, sejam bem-vindos ao estande do Grupo PSD. Somos uma empresa verticalmente integrada, capaz de produzir desde fios de nylon e tecidos de malha at\u00e9 pe\u00e7as de vestu\u00e1rio prontas.<br \/>Hoje, estamos apresentando uma nova inova\u00e7\u00e3o em nosso estande: nylon reciclado feito a partir de redes de pesca usadas, tecido para confec\u00e7\u00e3o de roupas. Voc\u00ea pode v\u00ea-lo aqui.<br \/>Outra t\u00e9cnica que gostar\u00edamos de apresentar \u00e9 a tecelagem Jacquard. O tecido Jacquard \u00e9 um tecido tran\u00e7ado com diversos padr\u00f5es coloridos.<br \/>Este \u00e9 um exemplo de uma camisa feita com tecido Jacquard. Os clientes podem enviar os padr\u00f5es desejados e n\u00f3s podemos tecer o tecido Jacquard finalizado para eles.<br \/>Aqui temos um tecido adequado para uniformes. A maioria dos uniformes \u00e9 feita de algod\u00e3o ou misturas de algod\u00e3o, como TC, TK e CVC. A desvantagem desses tecidos \u00e9 que formam bolinhas com facilidade e desbotam ap\u00f3s lavagens repetidas.<br \/>Por isso, gostar\u00edamos de apresentar nosso tecido Kinetic Performance Polo, um tecido de poli\u00e9ster com elastano.<br \/>O poli\u00e9ster com elastano \u00e9 altamente el\u00e1stico e suporta muitas lavagens sem desbotar. \u00c9 confort\u00e1vel de usar e mant\u00e9m sua forma mesmo ap\u00f3s mais de 50 lavagens.<\/div>\n<\/details>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Na ind\u00fastria de vestu\u00e1rio, materiais sustent\u00e1veis \u200b\u200be tecidos de alto desempenho est\u00e3o se tornando requisitos importantes para marcas, fabricantes de uniformes e fabricantes de roupas OEM. Para aplica\u00e7\u00f5es em uniformes, em particular, os tecidos devem\u2026<\/p>\n","protected":false},"author":1,"featured_media":58555,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[811],"tags":[581,577,32,517,40,6,9,681,34,529,637,14,68,492,530,493,565,609],"class_list":["post-58553","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-gft-2026-thailand","tag-living-1","tag-medical-care-health-5","tag-medical-care-health","tag-machinery-industrial-technology-6","tag-living","tag-fundamental-industries","tag-information-telecommunication","tag-inovacao-startups","tag-machinery-industrial-technology","tag-machinery-industrial-technology-7","tag-fundamental-industries-3","tag-services","tag-thailand","tag-machinery-industrial-technology-9","tag-machinery-industrial-technology-8","tag-information-telecommunication-1","tag-living-2","tag-services-5","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tecidos de alto desempenho - PSD Group [GFT 2026] \u2013 V\u00eddeo da Feira | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/portuguese\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tecidos de alto desempenho - PSD Group [GFT 2026] \u2013 V\u00eddeo da Feira | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"Na ind\u00fastria de vestu\u00e1rio, materiais sustent\u00e1veis \u200b\u200be tecidos de alto desempenho est\u00e3o se tornando requisitos importantes para marcas, fabricantes de uniformes e fabricantes de roupas OEM. Para aplica\u00e7\u00f5es em uniformes, em particular, os tecidos devem\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/portuguese\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00eddeos de Feiras Internacionais e Novos Produtos \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-08T06:06:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T06:06:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/portuguese\/wp-content\/uploads\/2026\/07\/maxresdefault-39.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/#\\\/schema\\\/person\\\/3ea75b2b0542da77a7d411f29d033ddc\"},\"headline\":\"Tecidos de alto desempenho - PSD Group [GFT 2026]\",\"datePublished\":\"2026-07-08T06:06:44+00:00\",\"dateModified\":\"2026-09-01T06:06:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/\"},\"wordCount\":641,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/maxresdefault-39.jpg\",\"keywords\":[\"Couro (Materiais \\\/ Produtos \\\/ M\u00e1quinas) \\\/ Cal\u00e7ado\",\"Cuidados de Sa\u00fade (Equipamentos \\\/ Produtos e Servi\u00e7os)\",\"Cuidados M\u00e9dicos \\\/ Sa\u00fade\",\"El\u00e9trica e Eletr\u00f4nica (Produtos \\\/ M\u00e1quinas)\",\"Industria Viva\",\"Ind\u00fastrias Fundamentais\",\"Informa\u00e7\u00e3o \\\/ Telecomunica\u00e7\u00e3o\",\"Inova\u00e7\u00e3o \\\/ Startups.\",\"M\u00e1quinas \\\/ Tecnologia Industrial\",\"Outras m\u00e1quinas e equipamentos industriais\",\"Qu\u00edmica \\\/ Borracha \\\/ Pl\u00e1sticos \\\/ Materiais\",\"Servi\u00e7os\",\"Tail\u00e2ndia\",\"Tecnologia Avan\u00e7ada \\\/ Materiais \\\/ Comp\u00f3sitos \\\/ P&amp;D\",\"Tecnologia e Engenharia de Fabrica\u00e7\u00e3o\",\"Telecomunica\u00e7\u00f5es \\\/ Processamento de Dados \\\/ Inform\u00e1tica\",\"T\u00eaxteis e Vestu\u00e1rio (Materiais\\\/Produtos e M\u00e1quinas)\",\"Varejo \\\/ Atacado \\\/ Distribui\u00e7\u00e3o \\\/ Franchising\"],\"articleSection\":[\"GFT 2026\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/\",\"name\":\"Tecidos de alto desempenho - PSD Group [GFT 2026] \u2013 V\u00eddeo da Feira | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/maxresdefault-39.jpg\",\"datePublished\":\"2026-07-08T06:06:44+00:00\",\"dateModified\":\"2026-09-01T06:06:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/#\\\/schema\\\/person\\\/3ea75b2b0542da77a7d411f29d033ddc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/maxresdefault-39.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/maxresdefault-39.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tecidos de alto desempenho - PSD Group [GFT 2026]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/\",\"name\":\"V\u00eddeos de Feiras Internacionais e Novos Produtos \u2013 WorldTradeShow.TV\",\"description\":\"Descubra v\u00eddeos de feiras internacionais e novos produtos em portugu\u00eas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/portuguese\\\/#\\\/schema\\\/person\\\/3ea75b2b0542da77a7d411f29d033ddc\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\\\/\\\/127.0.0.1\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/GVUhoNdk7rk\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"110\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tecidos de alto desempenho - PSD Group [GFT 2026] \u2013 V\u00eddeo da Feira | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/portuguese\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/","og_locale":"pt_PT","og_type":"article","og_title":"Tecidos de alto desempenho - PSD Group [GFT 2026] \u2013 V\u00eddeo da Feira | WorldTradeShow.TV","og_description":"Na ind\u00fastria de vestu\u00e1rio, materiais sustent\u00e1veis \u200b\u200be tecidos de alto desempenho est\u00e3o se tornando requisitos importantes para marcas, fabricantes de uniformes e fabricantes de roupas OEM. Para aplica\u00e7\u00f5es em uniformes, em particular, os tecidos devem\u2026","og_url":"https:\/\/www.worldtradeshow.tv\/portuguese\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/","og_site_name":"V\u00eddeos de Feiras Internacionais e Novos Produtos \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2026-07-08T06:06:44+00:00","article_modified_time":"2026-09-01T06:06:57+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/portuguese\/wp-content\/uploads\/2026\/07\/maxresdefault-39.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"user","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/portuguese\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/portuguese\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/portuguese\/#\/schema\/person\/3ea75b2b0542da77a7d411f29d033ddc"},"headline":"Tecidos de alto desempenho - PSD Group [GFT 2026]","datePublished":"2026-07-08T06:06:44+00:00","dateModified":"2026-09-01T06:06:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/portuguese\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/"},"wordCount":641,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/portuguese\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/portuguese\/wp-content\/uploads\/2026\/07\/maxresdefault-39.jpg","keywords":["Couro (Materiais \/ Produtos \/ M\u00e1quinas) \/ Cal\u00e7ado","Cuidados de Sa\u00fade (Equipamentos \/ Produtos e Servi\u00e7os)","Cuidados M\u00e9dicos \/ Sa\u00fade","El\u00e9trica e Eletr\u00f4nica (Produtos \/ M\u00e1quinas)","Industria Viva","Ind\u00fastrias Fundamentais","Informa\u00e7\u00e3o \/ Telecomunica\u00e7\u00e3o","Inova\u00e7\u00e3o \/ Startups.","M\u00e1quinas \/ Tecnologia Industrial","Outras m\u00e1quinas e equipamentos industriais","Qu\u00edmica \/ Borracha \/ Pl\u00e1sticos \/ Materiais","Servi\u00e7os","Tail\u00e2ndia","Tecnologia Avan\u00e7ada \/ Materiais \/ Comp\u00f3sitos \/ P&amp;D","Tecnologia e Engenharia de Fabrica\u00e7\u00e3o","Telecomunica\u00e7\u00f5es \/ Processamento de Dados \/ Inform\u00e1tica","T\u00eaxteis e Vestu\u00e1rio (Materiais\/Produtos e M\u00e1quinas)","Varejo \/ Atacado \/ Distribui\u00e7\u00e3o \/ Franchising"],"articleSection":["GFT 2026"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/portuguese\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/portuguese\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/","url":"https:\/\/www.worldtradeshow.tv\/portuguese\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/","name":"Tecidos de alto desempenho - PSD Group [GFT 2026] \u2013 V\u00eddeo da Feira | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/portuguese\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/portuguese\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/portuguese\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/portuguese\/wp-content\/uploads\/2026\/07\/maxresdefault-39.jpg","datePublished":"2026-07-08T06:06:44+00:00","dateModified":"2026-09-01T06:06:57+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/portuguese\/#\/schema\/person\/3ea75b2b0542da77a7d411f29d033ddc"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/portuguese\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/portuguese\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.worldtradeshow.tv\/portuguese\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/portuguese\/wp-content\/uploads\/2026\/07\/maxresdefault-39.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/portuguese\/wp-content\/uploads\/2026\/07\/maxresdefault-39.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/portuguese\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.worldtradeshow.tv\/portuguese\/"},{"@type":"ListItem","position":2,"name":"Tecidos de alto desempenho - PSD Group [GFT 2026]"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/portuguese\/#website","url":"https:\/\/www.worldtradeshow.tv\/portuguese\/","name":"V\u00eddeos de Feiras Internacionais e Novos Produtos \u2013 WorldTradeShow.TV","description":"Descubra v\u00eddeos de feiras internacionais e novos produtos em portugu\u00eas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/portuguese\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/portuguese\/#\/schema\/person\/3ea75b2b0542da77a7d411f29d033ddc","name":"user","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:\/\/127.0.0.1"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/GVUhoNdk7rk","og_video_type":"text\/html","og_video_duration":"110","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=GVUhoNdk7rk","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/portuguese\/wp-json\/wp\/v2\/posts\/58553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/portuguese\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/portuguese\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/portuguese\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/portuguese\/wp-json\/wp\/v2\/comments?post=58553"}],"version-history":[{"count":2,"href":"https:\/\/www.worldtradeshow.tv\/portuguese\/wp-json\/wp\/v2\/posts\/58553\/revisions"}],"predecessor-version":[{"id":98628,"href":"https:\/\/www.worldtradeshow.tv\/portuguese\/wp-json\/wp\/v2\/posts\/58553\/revisions\/98628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/portuguese\/wp-json\/wp\/v2\/media\/58555"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/portuguese\/wp-json\/wp\/v2\/media?parent=58553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/portuguese\/wp-json\/wp\/v2\/categories?post=58553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/portuguese\/wp-json\/wp\/v2\/tags?post=58553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}