{"id":510,"count":172,"description":"","link":"https:\/\/www.worldtradeshow.tv\/german\/video\/tag\/building-construction-1\/","name":"Bau &amp; Konstruktion \/ Immobilien","slug":"building-construction-1","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bau &amp; Konstruktion \/ Immobilien Messen | Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV<\/title>\n<meta name=\"description\" content=\"Finden Sie Messen in der Branche Bau &amp; Konstruktion \/ Immobilien. Sehen Sie internationale Messevideos und entdecken Sie B2B-Gesch\u00e4ftsm\u00f6glichkeiten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/german\/video\/tag\/building-construction-1\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bau &amp; Konstruktion \/ Immobilien Messen | Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"Finden Sie Messen in der Branche Bau &amp; Konstruktion \/ Immobilien. Sehen Sie internationale Messevideos und entdecken Sie B2B-Gesch\u00e4ftsm\u00f6glichkeiten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/german\/video\/tag\/building-construction-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/tag\\\/building-construction-1\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/tag\\\/building-construction-1\\\/\",\"name\":\"Bau &amp; Konstruktion \\\/ Immobilien Messen | Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/#website\"},\"description\":\"Finden Sie Messen in der Branche Bau &amp; Konstruktion \\\/ Immobilien. Sehen Sie internationale Messevideos und entdecken Sie B2B-Gesch\u00e4ftsm\u00f6glichkeiten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/tag\\\/building-construction-1\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/tag\\\/building-construction-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bau &amp; Konstruktion \\\/ Immobilien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/\",\"name\":\"Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV\",\"description\":\"Entdecken Sie Videos von internationalen Messen und neue Produkte auf Deutsch\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bau &amp; Konstruktion \/ Immobilien Messen | Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV","description":"Finden Sie Messen in der Branche Bau &amp; Konstruktion \/ Immobilien. Sehen Sie internationale Messevideos und entdecken Sie B2B-Gesch\u00e4ftsm\u00f6glichkeiten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/german\/video\/tag\/building-construction-1\/","og_locale":"de_DE","og_type":"article","og_title":"Bau &amp; Konstruktion \/ Immobilien Messen | Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV","og_description":"Finden Sie Messen in der Branche Bau &amp; Konstruktion \/ Immobilien. Sehen Sie internationale Messevideos und entdecken Sie B2B-Gesch\u00e4ftsm\u00f6glichkeiten.","og_url":"https:\/\/www.worldtradeshow.tv\/german\/video\/tag\/building-construction-1\/","og_site_name":"Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV","twitter_card":"summary_large_image","twitter_site":"@tenjitv","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/tag\/building-construction-1\/","url":"https:\/\/www.worldtradeshow.tv\/german\/video\/tag\/building-construction-1\/","name":"Bau &amp; Konstruktion \/ Immobilien Messen | Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/german\/#website"},"description":"Finden Sie Messen in der Branche Bau &amp; Konstruktion \/ Immobilien. Sehen Sie internationale Messevideos und entdecken Sie B2B-Gesch\u00e4ftsm\u00f6glichkeiten.","breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/tag\/building-construction-1\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/tag\/building-construction-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.worldtradeshow.tv\/german\/"},{"@type":"ListItem","position":2,"name":"Bau &amp; Konstruktion \/ Immobilien"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/german\/#website","url":"https:\/\/www.worldtradeshow.tv\/german\/","name":"Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV","description":"Entdecken Sie Videos von internationalen Messen und neue Produkte auf Deutsch","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/german\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/tags\/510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/posts?tags=510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}