{"id":97948,"date":"2026-07-08T06:01:20","date_gmt":"2026-07-08T06:01:20","guid":{"rendered":"https:\/\/www.worldtradeshow.tv\/german\/?p=97948"},"modified":"2026-09-01T06:07:12","modified_gmt":"2026-09-01T06:07:12","slug":"performance-fabrics-psd-group-gft-2026","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/german\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/","title":{"rendered":"Funktionsstoffe - PSD Group [GFT 2026]"},"content":{"rendered":"<div class=\"entry-content \">\n<blockquote class=\"wp-block-quote\">\n<p>In der Bekleidungsindustrie gewinnen nachhaltige Materialien und Hochleistungsstoffe zunehmend an Bedeutung f\u00fcr Marken, Uniformhersteller und OEM-Bekleidungshersteller. Insbesondere f\u00fcr Uniformen m\u00fcssen Stoffe fusselfrei, farbecht, formbest\u00e4ndig, komfortabel und waschbest\u00e4ndig sein und gleichzeitig Designflexibilit\u00e4t erm\u00f6glichen.<br \/>Auf der GFT 2026 pr\u00e4sentierte die PSD Group ihre vertikal integrierte Produktionskompetenz, die Nylongarn, Strickwaren und Konfektionsware umfasst. Am Messestand stellte das Unternehmen Bekleidungsstoffe aus recyceltem Nylon vor, das aus gebrauchten Fischernetzen gewonnen wird und Marken, die nachhaltigere Textill\u00f6sungen suchen, eine neue Materialoption bietet.<br \/>Das Unternehmen pr\u00e4sentierte au\u00dferdem Jacquardstoffe, die sich f\u00fcr individuelle Muster eignen. Kunden k\u00f6nnen ihr Wunschdesign bereitstellen, und die PSD Group webt dieses Muster in den Jacquardstoff ein \u2013 f\u00fcr Hemden, Freizeitkleidung, Uniformen oder die Entwicklung markenspezifischer Bekleidung.<br \/>F\u00fcr Uniformanwendungen hat die PSD Group ihr Kinetic Performance Polo-Gewebe aus Polyester-Spandex vorgestellt. Im Vergleich zu Baumwolle oder Baumwollmischgeweben, die nach mehrmaligem Waschen fusseln oder ausbleichen k\u00f6nnen, bietet das Polyester-Spandex-Gewebe Dehnbarkeit, Tragekomfort und Waschbest\u00e4ndigkeit. Laut Hersteller beh\u00e4lt das Gewebe auch nach \u00fcber 50 W\u00e4schen seine Form und ist daher ideal f\u00fcr Uniformhersteller und Bekleidungs-OEMs.<\/p>\n<\/blockquote>\n<div class=\"video-summary-grid\">\n<div class=\"summary-card\">\n<h3>Angegangene Herausforderungen<\/h3>\n<ul>\n<li><a href=\"\/german\/?s=Nachhaltige%20Bekleidungsmaterialien&#038;post_type=post\">Nachhaltige Bekleidungsmaterialien<\/a><\/li>\n<li><a href=\"\/german\/?s=Pilling%20und%20Farbverblassen&#038;post_type=post\">Pilling und Farbverblassen<\/a><\/li>\n<li><a href=\"\/german\/?s=Entwicklung%20kundenspezifischer%20Stoffe&#038;post_type=post\">Entwicklung kundenspezifischer Stoffe<\/a><\/li>\n<\/ul>\n<\/div>\n<div class=\"summary-card\">\n<h3>L\u00f6sungen<\/h3>\n<ul>\n<li><a href=\"\/german\/?s=Recyceltes%20Nylongewebe&#038;post_type=post\">Recyceltes Nylongewebe<\/a><\/li>\n<li><a href=\"\/german\/?s=Jacquard-Gewebe&#038;post_type=post\">Jacquard-Gewebe<\/a><\/li>\n<li><a href=\"\/german\/?s=Kinetic%20Performance%20Polo-Gewebe&#038;post_type=post\">Kinetic Performance Polo-Gewebe<\/a><\/li>\n<\/ul>\n<\/div>\n<div class=\"summary-card\">\n<h3>Zielkunden<\/h3>\n<ul>\n<li><a href=\"\/german\/?s=Bekleidungshersteller&#038;post_type=post\">Bekleidungshersteller<\/a><\/li>\n<li><a href=\"\/german\/?s=Uniformhersteller&#038;post_type=post\">Uniformhersteller<\/a><\/li>\n<li><a href=\"\/german\/?s=Textilh%C3%A4ndler%20und%20Bekleidungshersteller&#038;post_type=post\">Textilh\u00e4ndler und Bekleidungshersteller<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div class=\"video-faq\">\n<h3 class=\"faq-heading\">H\u00e4ufig gestellte Fragen<\/h3>\n<details class=\"faq-item\">\n<summary>Was pr\u00e4sentierte die PSD Group auf der GFT 2026?<\/summary>\n<div class=\"faq-answer\">Die PSD Group pr\u00e4sentierte recycelte Nylon-Bekleidungsstoffe aus gebrauchten Fischernetzen, ma\u00dfgeschneiderte Jacquard-Stoffe sowie Kinetic Performance Polo-Gewebe f\u00fcr Uniformanwendungen.<\/div>\n<\/details>\n<details class=\"faq-item\">\n<summary>L\u00e4sst sich der Jacquard-Stoff individuell gestalten?<\/summary>\n<div class=\"faq-answer\">Ja. Kunden k\u00f6nnen ihr gew\u00fcnschtes Muster angeben, und die PSD Group kann es in Jacquard-Gewebe f\u00fcr Bekleidungsprodukte wie Hemden und ma\u00dfgeschneiderte Kleidungsst\u00fccke einweben.<\/div>\n<\/details>\n<details class=\"faq-item\">\n<summary>Was ist der Vorteil des einheitlichen Stoffs?<\/summary>\n<div class=\"faq-answer\">Das Kinetic Performance Polo-Gewebe aus Polyester-Spandex bietet Dehnbarkeit, Komfort, Farbbest\u00e4ndigkeit und Formbest\u00e4ndigkeit auch nach mehr als 50 W\u00e4schen.<\/div>\n<\/details>\n<\/div>\n<details class=\"video-transcript\">\n<summary>Videotranskript ansehen<\/summary>\n<div class=\"transcript-content\">Hallo und herzlich willkommen am Stand der PSD Group. Wir sind ein vertikal integriertes Unternehmen und produzieren alles von Nylongarn und Strickwaren bis hin zu fertigen Kleidungsst\u00fccken. Heute pr\u00e4sentieren wir Ihnen an unserem Stand eine neue Innovation: recyceltes Nylon aus gebrauchten Fischernetzen, das zu Bekleidungsstoff verwebt wird. Sie k\u00f6nnen es hier besichtigen. Eine weitere Technik, die wir Ihnen vorstellen m\u00f6chten, ist das Jacquard-Weben. Jacquard-Stoffe sind gewebte Stoffe mit vielf\u00e4ltigen, farbenfrohen Mustern. Dies ist ein Beispiel f\u00fcr ein Hemd aus Jacquard-Stoff. Kunden k\u00f6nnen uns ihre Wunschmuster zusenden, und wir weben den fertigen Jacquard-Stoff f\u00fcr sie. Hier sehen Sie einen Stoff, der sich f\u00fcr Uniformen eignet. Die meisten Uniformen bestehen aus Baumwolle oder Baumwollmischgeweben wie TC, TK und CVC. Der Nachteil dieser Stoffe ist, dass sie leicht fusseln und nach mehrmaligem Waschen ausbleichen. Deshalb m\u00f6chten wir Ihnen unseren Kinetic Performance Polo-Stoff vorstellen, ein Poly-Spandex-Gewebe. Poly-Spandex ist hochelastisch und farbecht, auch nach vielen W\u00e4schen. Es ist angenehm zu tragen und beh\u00e4lt seine Form selbst nach \u00fcber 50 W\u00e4schen.<\/div>\n<\/details>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>In der Bekleidungsindustrie gewinnen nachhaltige Materialien und Hochleistungsstoffe zunehmend an Bedeutung f\u00fcr Marken, Uniformhersteller und OEM-Bekleidungshersteller. Insbesondere f\u00fcr Uniformen m\u00fcssen Stoffe fusselfrei, farbecht, formbest\u00e4ndig, kom\u2026<\/p>\n","protected":false},"author":1,"featured_media":97950,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[791],"tags":[534,633,5,605,522,535,580,41,45,85,15,584,42,39,497,498,568,69],"class_list":["post-97948","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-gft-2026-thailand","tag-machinery-industrial-technology-7","tag-fundamental-industries-3","tag-services","tag-services-5","tag-machinery-industrial-technology-6","tag-machinery-industrial-technology-8","tag-medical-care-health-5","tag-fundamental-industries","tag-information-telecommunication","tag-innovation-startups","tag-living","tag-living-1","tag-machinery-industrial-technology","tag-medical-care-health","tag-machinery-industrial-technology-9","tag-information-telecommunication-1","tag-living-2","tag-thailand","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Funktionsstoffe - PSD Group [GFT 2026] \u2013 Aussteller Video | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/german\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Funktionsstoffe - PSD Group [GFT 2026] \u2013 Aussteller Video | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"In der Bekleidungsindustrie gewinnen nachhaltige Materialien und Hochleistungsstoffe zunehmend an Bedeutung f\u00fcr Marken, Uniformhersteller und OEM-Bekleidungshersteller. Insbesondere f\u00fcr Uniformen m\u00fcssen Stoffe fusselfrei, farbecht, formbest\u00e4ndig, kom\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/german\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-08T06:01:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T06:07:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/german\/wp-content\/uploads\/2026\/07\/maxresdefault-39.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/#\\\/schema\\\/person\\\/dfcf88025bf6b941072148407e2bde58\"},\"headline\":\"Funktionsstoffe - PSD Group [GFT 2026]\",\"datePublished\":\"2026-07-08T06:01:20+00:00\",\"dateModified\":\"2026-09-01T06:07:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/\"},\"wordCount\":488,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/maxresdefault-39.jpg\",\"keywords\":[\"Andere Industriemaschinen und -ger\u00e4te\",\"Chemie \\\/ Gummi \\\/ Kunststoffe \\\/ Materialien\",\"Dienstleistungen\",\"Einzelhandel \\\/ Gro\u00dfhandel \\\/ Vertrieb \\\/ Franchising\",\"Elektrik und Elektronik (Produkte \\\/ Maschinen)\",\"Fertigungstechnik und Ingenieurwesen\",\"Gesundheitswesen (Ausr\u00fcstung \\\/ Produkte &amp; Dienstleistungen)\",\"Grundlegende Industrie\",\"Information \\\/ Telekommunikation\",\"Innovation \\\/ Startups\",\"Leben\",\"Leder (Materialien \\\/ Produkte \\\/ Maschinen) \\\/ Schuhe\",\"Maschinen \\\/ Industrietechnik\",\"Medizinische Versorgung \\\/ Gesundheit\",\"Spitzentechnologie \\\/ Materialien \\\/ Verbundwerkstoffe \\\/ Forschung und Entwicklung\",\"Telekommunikation \\\/ Datenverarbeitung \\\/ Computer\",\"Textilien und Bekleidung (Materialien \\\/ Produkte und Maschinen)\",\"Thailand\"],\"articleSection\":[\"GFT 2026\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/\",\"name\":\"Funktionsstoffe - PSD Group [GFT 2026] \u2013 Aussteller Video | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/maxresdefault-39.jpg\",\"datePublished\":\"2026-07-08T06:01:20+00:00\",\"dateModified\":\"2026-09-01T06:07:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/#\\\/schema\\\/person\\\/dfcf88025bf6b941072148407e2bde58\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/maxresdefault-39.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/maxresdefault-39.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/gft-2026-thailand\\\/performance-fabrics-psd-group-gft-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Funktionsstoffe - PSD Group [GFT 2026]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/\",\"name\":\"Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV\",\"description\":\"Entdecken Sie Videos von internationalen Messen und neue Produkte auf Deutsch\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/#\\\/schema\\\/person\\\/dfcf88025bf6b941072148407e2bde58\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/GVUhoNdk7rk\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"110\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Funktionsstoffe - PSD Group [GFT 2026] \u2013 Aussteller Video | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/german\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/","og_locale":"de_DE","og_type":"article","og_title":"Funktionsstoffe - PSD Group [GFT 2026] \u2013 Aussteller Video | WorldTradeShow.TV","og_description":"In der Bekleidungsindustrie gewinnen nachhaltige Materialien und Hochleistungsstoffe zunehmend an Bedeutung f\u00fcr Marken, Uniformhersteller und OEM-Bekleidungshersteller. Insbesondere f\u00fcr Uniformen m\u00fcssen Stoffe fusselfrei, farbecht, formbest\u00e4ndig, kom\u2026","og_url":"https:\/\/www.worldtradeshow.tv\/german\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/","og_site_name":"Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2026-07-08T06:01:20+00:00","article_modified_time":"2026-09-01T06:07:12+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/german\/wp-content\/uploads\/2026\/07\/maxresdefault-39.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"Verfasst von":"user","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/german\/#\/schema\/person\/dfcf88025bf6b941072148407e2bde58"},"headline":"Funktionsstoffe - PSD Group [GFT 2026]","datePublished":"2026-07-08T06:01:20+00:00","dateModified":"2026-09-01T06:07:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/"},"wordCount":488,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/german\/wp-content\/uploads\/2026\/07\/maxresdefault-39.jpg","keywords":["Andere Industriemaschinen und -ger\u00e4te","Chemie \/ Gummi \/ Kunststoffe \/ Materialien","Dienstleistungen","Einzelhandel \/ Gro\u00dfhandel \/ Vertrieb \/ Franchising","Elektrik und Elektronik (Produkte \/ Maschinen)","Fertigungstechnik und Ingenieurwesen","Gesundheitswesen (Ausr\u00fcstung \/ Produkte &amp; Dienstleistungen)","Grundlegende Industrie","Information \/ Telekommunikation","Innovation \/ Startups","Leben","Leder (Materialien \/ Produkte \/ Maschinen) \/ Schuhe","Maschinen \/ Industrietechnik","Medizinische Versorgung \/ Gesundheit","Spitzentechnologie \/ Materialien \/ Verbundwerkstoffe \/ Forschung und Entwicklung","Telekommunikation \/ Datenverarbeitung \/ Computer","Textilien und Bekleidung (Materialien \/ Produkte und Maschinen)","Thailand"],"articleSection":["GFT 2026"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/german\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/","url":"https:\/\/www.worldtradeshow.tv\/german\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/","name":"Funktionsstoffe - PSD Group [GFT 2026] \u2013 Aussteller Video | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/german\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/german\/wp-content\/uploads\/2026\/07\/maxresdefault-39.jpg","datePublished":"2026-07-08T06:01:20+00:00","dateModified":"2026-09-01T06:07:12+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/german\/#\/schema\/person\/dfcf88025bf6b941072148407e2bde58"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/german\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/german\/wp-content\/uploads\/2026\/07\/maxresdefault-39.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/german\/wp-content\/uploads\/2026\/07\/maxresdefault-39.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/gft-2026-thailand\/performance-fabrics-psd-group-gft-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.worldtradeshow.tv\/german\/"},{"@type":"ListItem","position":2,"name":"Funktionsstoffe - PSD Group [GFT 2026]"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/german\/#website","url":"https:\/\/www.worldtradeshow.tv\/german\/","name":"Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV","description":"Entdecken Sie Videos von internationalen Messen und neue Produkte auf Deutsch","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/german\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/german\/#\/schema\/person\/dfcf88025bf6b941072148407e2bde58","name":"user","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/GVUhoNdk7rk","og_video_type":"text\/html","og_video_duration":"110","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=GVUhoNdk7rk","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/posts\/97948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/comments?post=97948"}],"version-history":[{"count":2,"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/posts\/97948\/revisions"}],"predecessor-version":[{"id":98653,"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/posts\/97948\/revisions\/98653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/media\/97950"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/media?parent=97948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/categories?post=97948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/tags?post=97948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}