{"id":55897,"date":"2025-07-29T02:57:27","date_gmt":"2025-07-29T02:57:27","guid":{"rendered":"https:\/\/www.worldtradeshow.tv\/german\/?p=55897"},"modified":"2025-07-29T02:57:27","modified_gmt":"2025-07-29T02:57:27","slug":"cash-register-system-oneqr_elestyle-inc","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/german\/video\/caferes_2025_07\/cash-register-system-oneqr_elestyle-inc\/","title":{"rendered":"[13. Tokyo Cafe Show 2025] Kassensystem \u201eOneQR\u201c - ELESTYLE, Inc."},"content":{"rendered":"<blockquote class=\"wp-block-quote\"><p>ELESTYLE Inc. pr\u00e4sentierte auf der Tokyo Cafe Show ein umfassendes Kassensystem namens &#8220;OneQR&#8221;. Es bietet L\u00f6sungen f\u00fcr Restaurants und Einzelhandel, darunter Bestellsysteme via QR-Code und mobile Terminals f\u00fcr Mitarbeiter. OneQR unterst\u00fctzt diverse bargeldlose Zahlungsmethoden wie PayPay und Kreditkarten und integriert sich mit Kassenschubladen und Wechselgeldautomaten. Das System zielt darauf ab, die Implementierung und Bedienung zu vereinfachen, wobei die monatlichen Kosten zwischen 1.000 und 10.000 Yen liegen.<br \/><cite>Generated by <a href=\"https:\/\/gemini.google.com\/\">Gemini<\/a><\/cite><\/p><\/blockquote>\n<p><\/p>\n<p>Webseite:<a href=\"https:\/\/elestyle.jp\/\" target=\"_blank\" rel=\"noopener\">https:\/\/elestyle.jp\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ELESTYLE Inc. pr\u00e4sentierte auf der Tokyo Cafe Show ein umfassendes Kassensystem namens &#8220;OneQR&#8221;. Es bietet L\u00f6sungen f\u00fcr Restaurants und Einzelhandel, darunter Bestellsysteme via QR-Code und mobile Terminals f\u00fcr Mitarbeiter. OneQR unterst\u00fctzt diverse bargeldlose Zahlungsmethoden wie PayPay und Kreditkarten und integriert sich mit Kassenschubladen und Wechselgeldautomaten. Das System zielt darauf ab, die Implementierung und Bedienung zu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":55898,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[714],"tags":[13,555,5,605,554,37,46,15,528,512,511],"class_list":["post-55897","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-caferes_2025_07","tag-building-construction","tag-services-7","tag-services","tag-services-5","tag-services-1","tag-japan","tag-agriculture-forestry-fishery-and-food","tag-living","tag-agriculture-forestry-fishery-and-food-2","tag-living-4","tag-building-construction-2","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[13. Tokyo Cafe Show 2025] Kassensystem \u201eOneQR\u201c - ELESTYLE, Inc. \u2013 Aussteller Video | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/german\/video\/caferes_2025_07\/cash-register-system-oneqr_elestyle-inc\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[13. Tokyo Cafe Show 2025] Kassensystem \u201eOneQR\u201c - ELESTYLE, Inc. \u2013 Aussteller Video | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"ELESTYLE Inc. pr\u00e4sentierte auf der Tokyo Cafe Show ein umfassendes Kassensystem namens &#8220;OneQR&#8221;. Es bietet L\u00f6sungen f\u00fcr Restaurants und Einzelhandel, darunter Bestellsysteme via QR-Code und mobile Terminals f\u00fcr Mitarbeiter. OneQR unterst\u00fctzt diverse bargeldlose Zahlungsmethoden wie PayPay und Kreditkarten und integriert sich mit Kassenschubladen und Wechselgeldautomaten. Das System zielt darauf ab, die Implementierung und Bedienung zu [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/german\/video\/caferes_2025_07\/cash-register-system-oneqr_elestyle-inc\/\" \/>\n<meta property=\"og:site_name\" content=\"Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-29T02:57:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/german\/wp-content\/uploads\/2025\/07\/maxresdefault-27.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/caferes_2025_07\\\/cash-register-system-oneqr_elestyle-inc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/caferes_2025_07\\\/cash-register-system-oneqr_elestyle-inc\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/#\\\/schema\\\/person\\\/dfcf88025bf6b941072148407e2bde58\"},\"headline\":\"[13. Tokyo Cafe Show 2025] Kassensystem \u201eOneQR\u201c - ELESTYLE, Inc.\",\"datePublished\":\"2025-07-29T02:57:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/caferes_2025_07\\\/cash-register-system-oneqr_elestyle-inc\\\/\"},\"wordCount\":84,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/caferes_2025_07\\\/cash-register-system-oneqr_elestyle-inc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/maxresdefault-27.jpg\",\"keywords\":[\"Bauen &amp; Konstruktion\",\"Design (inkl. Industriedesign)\",\"Dienstleistungen\",\"Einzelhandel \\\/ Gro\u00dfhandel \\\/ Vertrieb \\\/ Franchising\",\"Hotel-\\\/Restaurant- und Catering-Unternehmen\",\"Japan\",\"Landwirtschaft \\\/ Forstwirtschaft \\\/ Fischerei und Lebensmittel\",\"Leben\",\"Lebensmittel und Getr\u00e4nke \\\/ Lebensmittelverarbeitung\",\"M\u00f6bel und Einrichtungsgegenst\u00e4nde \\\/ Teile\",\"Sanit\u00e4r \\\/ Klimaanlage \\\/ Sanit\u00e4r \\\/ Beleuchtung\"],\"articleSection\":[\"CAFERE JAPAN 2025\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/caferes_2025_07\\\/cash-register-system-oneqr_elestyle-inc\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/caferes_2025_07\\\/cash-register-system-oneqr_elestyle-inc\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/caferes_2025_07\\\/cash-register-system-oneqr_elestyle-inc\\\/\",\"name\":\"[13. Tokyo Cafe Show 2025] Kassensystem \u201eOneQR\u201c - ELESTYLE, Inc. \u2013 Aussteller Video | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/caferes_2025_07\\\/cash-register-system-oneqr_elestyle-inc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/caferes_2025_07\\\/cash-register-system-oneqr_elestyle-inc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/maxresdefault-27.jpg\",\"datePublished\":\"2025-07-29T02:57:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/#\\\/schema\\\/person\\\/dfcf88025bf6b941072148407e2bde58\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/caferes_2025_07\\\/cash-register-system-oneqr_elestyle-inc\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/caferes_2025_07\\\/cash-register-system-oneqr_elestyle-inc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/caferes_2025_07\\\/cash-register-system-oneqr_elestyle-inc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/maxresdefault-27.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/maxresdefault-27.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/caferes_2025_07\\\/cash-register-system-oneqr_elestyle-inc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[13. Tokyo Cafe Show 2025] Kassensystem \u201eOneQR\u201c - ELESTYLE, Inc.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/\",\"name\":\"Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV\",\"description\":\"Entdecken Sie Videos von internationalen Messen und neue Produkte auf Deutsch\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/#\\\/schema\\\/person\\\/dfcf88025bf6b941072148407e2bde58\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/-qTsdFow8cA\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"144\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[13. Tokyo Cafe Show 2025] Kassensystem \u201eOneQR\u201c - ELESTYLE, Inc. \u2013 Aussteller Video | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/german\/video\/caferes_2025_07\/cash-register-system-oneqr_elestyle-inc\/","og_locale":"de_DE","og_type":"article","og_title":"[13. Tokyo Cafe Show 2025] Kassensystem \u201eOneQR\u201c - ELESTYLE, Inc. \u2013 Aussteller Video | WorldTradeShow.TV","og_description":"ELESTYLE Inc. pr\u00e4sentierte auf der Tokyo Cafe Show ein umfassendes Kassensystem namens &#8220;OneQR&#8221;. Es bietet L\u00f6sungen f\u00fcr Restaurants und Einzelhandel, darunter Bestellsysteme via QR-Code und mobile Terminals f\u00fcr Mitarbeiter. OneQR unterst\u00fctzt diverse bargeldlose Zahlungsmethoden wie PayPay und Kreditkarten und integriert sich mit Kassenschubladen und Wechselgeldautomaten. Das System zielt darauf ab, die Implementierung und Bedienung zu [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/german\/video\/caferes_2025_07\/cash-register-system-oneqr_elestyle-inc\/","og_site_name":"Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2025-07-29T02:57:27+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/german\/wp-content\/uploads\/2025\/07\/maxresdefault-27.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"Verfasst von":"user"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/caferes_2025_07\/cash-register-system-oneqr_elestyle-inc\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/caferes_2025_07\/cash-register-system-oneqr_elestyle-inc\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/german\/#\/schema\/person\/dfcf88025bf6b941072148407e2bde58"},"headline":"[13. Tokyo Cafe Show 2025] Kassensystem \u201eOneQR\u201c - ELESTYLE, Inc.","datePublished":"2025-07-29T02:57:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/caferes_2025_07\/cash-register-system-oneqr_elestyle-inc\/"},"wordCount":84,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/caferes_2025_07\/cash-register-system-oneqr_elestyle-inc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/german\/wp-content\/uploads\/2025\/07\/maxresdefault-27.jpg","keywords":["Bauen &amp; Konstruktion","Design (inkl. Industriedesign)","Dienstleistungen","Einzelhandel \/ Gro\u00dfhandel \/ Vertrieb \/ Franchising","Hotel-\/Restaurant- und Catering-Unternehmen","Japan","Landwirtschaft \/ Forstwirtschaft \/ Fischerei und Lebensmittel","Leben","Lebensmittel und Getr\u00e4nke \/ Lebensmittelverarbeitung","M\u00f6bel und Einrichtungsgegenst\u00e4nde \/ Teile","Sanit\u00e4r \/ Klimaanlage \/ Sanit\u00e4r \/ Beleuchtung"],"articleSection":["CAFERE JAPAN 2025"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/german\/video\/caferes_2025_07\/cash-register-system-oneqr_elestyle-inc\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/caferes_2025_07\/cash-register-system-oneqr_elestyle-inc\/","url":"https:\/\/www.worldtradeshow.tv\/german\/video\/caferes_2025_07\/cash-register-system-oneqr_elestyle-inc\/","name":"[13. Tokyo Cafe Show 2025] Kassensystem \u201eOneQR\u201c - ELESTYLE, Inc. \u2013 Aussteller Video | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/german\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/caferes_2025_07\/cash-register-system-oneqr_elestyle-inc\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/caferes_2025_07\/cash-register-system-oneqr_elestyle-inc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/german\/wp-content\/uploads\/2025\/07\/maxresdefault-27.jpg","datePublished":"2025-07-29T02:57:27+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/german\/#\/schema\/person\/dfcf88025bf6b941072148407e2bde58"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/caferes_2025_07\/cash-register-system-oneqr_elestyle-inc\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/german\/video\/caferes_2025_07\/cash-register-system-oneqr_elestyle-inc\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/caferes_2025_07\/cash-register-system-oneqr_elestyle-inc\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/german\/wp-content\/uploads\/2025\/07\/maxresdefault-27.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/german\/wp-content\/uploads\/2025\/07\/maxresdefault-27.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/caferes_2025_07\/cash-register-system-oneqr_elestyle-inc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.worldtradeshow.tv\/german\/"},{"@type":"ListItem","position":2,"name":"[13. Tokyo Cafe Show 2025] Kassensystem \u201eOneQR\u201c - ELESTYLE, Inc."}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/german\/#website","url":"https:\/\/www.worldtradeshow.tv\/german\/","name":"Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV","description":"Entdecken Sie Videos von internationalen Messen und neue Produkte auf Deutsch","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/german\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/german\/#\/schema\/person\/dfcf88025bf6b941072148407e2bde58","name":"user","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/-qTsdFow8cA","og_video_type":"text\/html","og_video_duration":"144","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=-qTsdFow8cA","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/posts\/55897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/comments?post=55897"}],"version-history":[{"count":1,"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/posts\/55897\/revisions"}],"predecessor-version":[{"id":55919,"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/posts\/55897\/revisions\/55919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/media\/55898"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/media?parent=55897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/categories?post=55897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/tags?post=55897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}