{"id":714,"count":10,"description":"","link":"https:\/\/www.worldtradeshow.tv\/german\/video\/category\/caferes_2025_07\/","name":"CAFERE JAPAN 2025","slug":"caferes_2025_07","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CAFERE JAPAN 2025 Messevideos | Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV<\/title>\n<meta name=\"description\" content=\"Entdecken Sie Messen zum Thema CAFERE JAPAN 2025. Finden Sie internationale Messen, neue Produkte und Gesch\u00e4ftsm\u00f6glichkeiten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/german\/video\/category\/caferes_2025_07\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CAFERE JAPAN 2025 Messevideos | Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie Messen zum Thema CAFERE JAPAN 2025. Finden Sie internationale Messen, neue Produkte und Gesch\u00e4ftsm\u00f6glichkeiten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/german\/video\/category\/caferes_2025_07\/\" \/>\n<meta property=\"og:site_name\" content=\"Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/category\\\/caferes_2025_07\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/category\\\/caferes_2025_07\\\/\",\"name\":\"CAFERE JAPAN 2025 Messevideos | Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/#website\"},\"description\":\"Entdecken Sie Messen zum Thema CAFERE JAPAN 2025. Finden Sie internationale Messen, neue Produkte und Gesch\u00e4ftsm\u00f6glichkeiten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/category\\\/caferes_2025_07\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/video\\\/category\\\/caferes_2025_07\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CAFERE JAPAN 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/\",\"name\":\"Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV\",\"description\":\"Entdecken Sie Videos von internationalen Messen und neue Produkte auf Deutsch\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/german\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CAFERE JAPAN 2025 Messevideos | Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV","description":"Entdecken Sie Messen zum Thema CAFERE JAPAN 2025. Finden Sie internationale Messen, neue Produkte und Gesch\u00e4ftsm\u00f6glichkeiten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/german\/video\/category\/caferes_2025_07\/","og_locale":"de_DE","og_type":"article","og_title":"CAFERE JAPAN 2025 Messevideos | Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV","og_description":"Entdecken Sie Messen zum Thema CAFERE JAPAN 2025. Finden Sie internationale Messen, neue Produkte und Gesch\u00e4ftsm\u00f6glichkeiten.","og_url":"https:\/\/www.worldtradeshow.tv\/german\/video\/category\/caferes_2025_07\/","og_site_name":"Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV","twitter_card":"summary_large_image","twitter_site":"@tenjitv","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/category\/caferes_2025_07\/","url":"https:\/\/www.worldtradeshow.tv\/german\/video\/category\/caferes_2025_07\/","name":"CAFERE JAPAN 2025 Messevideos | Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/german\/#website"},"description":"Entdecken Sie Messen zum Thema CAFERE JAPAN 2025. Finden Sie internationale Messen, neue Produkte und Gesch\u00e4ftsm\u00f6glichkeiten.","breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/category\/caferes_2025_07\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/german\/video\/category\/caferes_2025_07\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.worldtradeshow.tv\/german\/"},{"@type":"ListItem","position":2,"name":"CAFERE JAPAN 2025"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/german\/#website","url":"https:\/\/www.worldtradeshow.tv\/german\/","name":"Videos von Internationalen Messen und Neuen Produkten \u2013 WorldTradeShow.TV","description":"Entdecken Sie Videos von internationalen Messen und neue Produkte auf Deutsch","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/german\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/categories\/714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.worldtradeshow.tv\/german\/wp-json\/wp\/v2\/posts?categories=714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}