{"id":98378,"date":"2026-08-14T04:10:16","date_gmt":"2026-08-14T04:10:16","guid":{"rendered":"https:\/\/www.worldtradeshow.tv\/french\/?p=98378"},"modified":"2026-09-01T01:24:34","modified_gmt":"2026-09-01T01:24:34","slug":"coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes-japan-2026-japan\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\/","title":{"rendered":"Machine \u00e0 caf\u00e9 Black&#038;White4 CTS - DCS CO., LTD. [CAFERES JAPAN 2026]"},"content":{"rendered":"<div class=\"entry-content \">\n<blockquote class=\"wp-block-quote\">\n<p>Avec l&#8217;expansion du march\u00e9 du caf\u00e9 de sp\u00e9cialit\u00e9, les caf\u00e9s ont besoin d&#8217;\u00e9quipements haut de gamme capables de reproduire de mani\u00e8re constante des techniques d&#8217;infusion avanc\u00e9es, ainsi que d&#8217;un support technique fiable pour assurer leur bon fonctionnement.<br \/>Lors de l&#8217;exposition, DCS Co., Ltd. a pr\u00e9sent\u00e9 des \u00e9quipements de caf\u00e9 haut de gamme s\u00e9lectionn\u00e9s par des professionnels du monde entier, mettant en avant son activit\u00e9 d&#8217;import-export de machines \u00e0 expresso professionnelles et la fabrication de divers \u00e9quipements de caf\u00e9 sp\u00e9cialis\u00e9s. Depuis sa cr\u00e9ation en 1999, l&#8217;entreprise importe des \u00e9quipements de caf\u00e9 d&#8217;excellente qualit\u00e9 et d\u00e9veloppe ses propres produits.<br \/>Sur leur stand, ils ont mis l&#8217;accent sur leur syst\u00e8me complet qui assure la maintenance apr\u00e8s installation en compl\u00e9ment de la vente d&#8217;\u00e9quipements, d\u00e9montrant ainsi leur capacit\u00e9 \u00e0 accompagner techniquement les g\u00e9rants de caf\u00e9s et \u00e0 optimiser leur efficacit\u00e9 op\u00e9rationnelle. Cette solution est con\u00e7ue pour les baristas souhaitant ouvrir leur propre \u00e9tablissement et les cha\u00eenes de caf\u00e9s en pleine expansion.<\/p>\n<\/blockquote>\n<div class=\"video-summary-grid\">\n<div class=\"summary-card\">\n<h3>D\u00e9fis r\u00e9solus<\/h3>\n<ul>\n<li><a href=\"\/french\/?s=Extraction%20de%20caf%C3%A9%20de%20haute%20qualit%C3%A9%20et%20constante&#038;post_type=post\">Extraction de caf\u00e9 de haute qualit\u00e9 et constante<\/a><\/li>\n<li><a href=\"\/french\/?s=Entretien%20et%20r%C3%A9paration%20du%20mat%C3%A9riel%20de%20caf%C3%A9%20import%C3%A9&#038;post_type=post\">Entretien et r\u00e9paration du mat\u00e9riel de caf\u00e9 import\u00e9<\/a><\/li>\n<li><a href=\"\/french\/?s=S%C3%A9lection%20d%27%C3%A9quipements%20adapt%C3%A9s%20aux%20ouvertures%20de%20caf%C3%A9s&#038;post_type=post\">S\u00e9lection d&#8217;\u00e9quipements adapt\u00e9s aux ouvertures de caf\u00e9s<\/a><\/li>\n<\/ul>\n<\/div>\n<div class=\"summary-card\">\n<h3>Solutions<\/h3>\n<ul>\n<li><a href=\"\/french\/?s=Machines%20%C3%A0%20expresso%20commerciales&#038;post_type=post\">Machines \u00e0 expresso commerciales<\/a><\/li>\n<li><a href=\"\/french\/?s=%C3%89quipement%20pour%20caf%C3%A9%20sp%C3%A9cialis%C3%A9&#038;post_type=post\">\u00c9quipement pour caf\u00e9 sp\u00e9cialis\u00e9<\/a><\/li>\n<li><a href=\"\/french\/?s=Importation%20et%20entretien%20de%20mat%C3%A9riel%20de%20caf%C3%A9&#038;post_type=post\">Importation et entretien de mat\u00e9riel de caf\u00e9<\/a><\/li>\n<\/ul>\n<\/div>\n<div class=\"summary-card\">\n<h3>Clients cibles<\/h3>\n<ul>\n<li><a href=\"\/french\/?s=exploitants%20de%20caf%C3%A9s%20et%20de%20torr%C3%A9facteurs&#038;post_type=post\">exploitants de caf\u00e9s et de torr\u00e9facteurs<\/a><\/li>\n<li><a href=\"\/french\/?s=cha%C3%AEnes%20d%27h%C3%B4tels%20et%20de%20restaurants&#038;post_type=post\">cha\u00eenes d&#8217;h\u00f4tels et de restaurants<\/a><\/li>\n<li><a href=\"\/french\/?s=Propri%C3%A9taires%20potentiels%20de%20caf%C3%A9s%20sp%C3%A9cialis%C3%A9s&#038;post_type=post\">Propri\u00e9taires potentiels de caf\u00e9s sp\u00e9cialis\u00e9s<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div class=\"video-faq\">\n<h3 class=\"faq-heading\">FAQ<\/h3>\n<details class=\"faq-item\">\n<summary>Quels types de produits commercialise la soci\u00e9t\u00e9 DCS Co., Ltd.\u00a0?<\/summary>\n<div class=\"faq-answer\">Ils proposent une large gamme de machines \u00e0 expresso commerciales tr\u00e8s performantes import\u00e9es de l&#8217;\u00e9tranger, ainsi que des \u00e9quipements de caf\u00e9 sp\u00e9cialis\u00e9s qu&#8217;ils con\u00e7oivent et fabriquent en interne.<\/div>\n<\/details>\n<details class=\"faq-item\">\n<summary>Offrent-ils un service apr\u00e8s-vente en cas de panne de la machine\u00a0?<\/summary>\n<div class=\"faq-answer\">Oui, ils disposent d&#8217;un syst\u00e8me d&#8217;assistance tout-en-un couvrant tout, des ventes \u00e0 l&#8217;importation \u00e0 la maintenance, offrant une assistance technique et un accompagnement complets pour la gestion des caf\u00e9s.<\/div>\n<\/details>\n<details class=\"faq-item\">\n<summary>\u00c0 quel type d&#8217;entreprises cette solution s&#8217;adresse-t-elle\u00a0?<\/summary>\n<div class=\"faq-answer\">Il est id\u00e9al pour les caf\u00e9s, les restaurants et les torr\u00e9facteurs qui souhaitent servir un caf\u00e9 de sp\u00e9cialit\u00e9 authentique, ainsi que pour les entreprises qui pr\u00e9voient d&#8217;agrandir leurs magasins ou d&#8217;en ouvrir de nouveaux.<\/div>\n<\/details>\n<\/div>\n<details class=\"video-transcript\">\n<summary>Voir la transcription vid\u00e9o<\/summary>\n<div class=\"transcript-content\">Ici DCS CO., LTD.<br \/>Nous distribuons principalement des machines \u00e0 caf\u00e9 de fabricants \u00e9trangers.<br \/>Nous souhaitons aujourd&#8217;hui vous pr\u00e9senter la Thermoplan Black&#038;White4 CTS.<br \/>Il s&#8217;agit d&#8217;une machine enti\u00e8rement automatique dot\u00e9e d&#8217;une fonction vapeur automatique tr\u00e8s performante.<br \/>Nous esp\u00e9rons que vous prendrez le temps de la d\u00e9couvrir.<br \/>Merci.<\/div>\n<\/details>\n<h2>Renseignez-vous via le lien ci-dessous<\/h2>\n<div class=\"company-profile-section\">\n<div class=\"company-shot\">\n<div class=\"browser-shot\"><a href=\"https:\/\/dcservice.co.jp\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/s.wordpress.com\/mshots\/v1\/https%3A%2F%2Fdcservice.co.jp%2F?w=1200\" alt=\"Capture d'\u00e9cran du site officiel de DCS Co., Ltd.\" loading=\"lazy\"><\/a><\/div>\n<\/div>\n<div class=\"company-info\">\n<h3 class=\"company-name\">DCS Co., Ltd.<\/h3>\n<ul class=\"company-meta\">\n<li><span class=\"label\">Quartier g\u00e9n\u00e9ral<\/span> <span class=\"value\">5-10 Motomachi, Nishinomiya-shi, Hyogo, Japon<\/span><\/li>\n<li><span class=\"label\">\u00c9tabli<\/span> <span class=\"value\">1999<\/span><\/li>\n<li><span class=\"label\">Employ\u00e9s<\/span> <span class=\"value\">75<\/span><\/li>\n<li><span class=\"label\">Site officiel<\/span> <span class=\"value\"><a href=\"https:\/\/dcservice.co.jp\/\" target=\"_blank\" rel=\"noopener\">https:\/\/dcservice.co.jp\/<\/a><\/span><\/li>\n<li><span class=\"label\">Domaine d&#8217;activit\u00e9<\/span> <span class=\"value\">Importation, vente et maintenance de machines \u00e0 expresso professionnelles et d&#8217;\u00e9quipements de caf\u00e9 ; fabrication d&#8217;\u00e9quipements de caf\u00e9 sp\u00e9cialis\u00e9s<\/span><\/li>\n<li><span class=\"label\">Principaux produits\/services<\/span> <span class=\"value\">Machines \u00e0 expresso professionnelles, \u00e9quipements de caf\u00e9, planification et d\u00e9veloppement d&#8217;\u00e9quipements pour le caf\u00e9 de sp\u00e9cialit\u00e9<\/span><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Avec l&#8217;expansion du march\u00e9 du caf\u00e9 de sp\u00e9cialit\u00e9, les caf\u00e9s ont besoin d&#8217;\u00e9quipements haut de gamme capables de reproduire de mani\u00e8re constante des techniques d&#8217;infusion avanc\u00e9es, ainsi que d&#8217;un support technique fiable pour assurer leur bon fonctionn\u2026<\/p>\n","protected":false},"author":1,"featured_media":98499,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[800],"tags":[43,536,522,542,568,562,31,38,33,36,552,588,34,543,506,37],"class_list":["post-98378","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-caferes-japan-2026-japan","tag-agriculture-forestry-fishery-and-food","tag-agriculture-forestry-fishery-and-food-2","tag-services-2","tag-machinery-industrial-technology-7","tag-transportation-logistics-packaging-9","tag-services-1","tag-information-telecommunication","tag-japan","tag-machinery-industrial-technology","tag-services","tag-services-3","tag-medical-care-health-5","tag-medical-care-health","tag-machinery-industrial-technology-8","tag-information-telecommunication-1","tag-transportation-logistics-packaging","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Machine \u00e0 caf\u00e9 Black&amp;White4 CTS - DCS CO., LTD. [CAFERES JAPAN 2026] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes-japan-2026-japan\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Machine \u00e0 caf\u00e9 Black&amp;White4 CTS - DCS CO., LTD. [CAFERES JAPAN 2026] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"Avec l&#039;expansion du march\u00e9 du caf\u00e9 de sp\u00e9cialit\u00e9, les caf\u00e9s ont besoin d&#039;\u00e9quipements haut de gamme capables de reproduire de mani\u00e8re constante des techniques d&#039;infusion avanc\u00e9es, ainsi que d&#039;un support technique fiable pour assurer leur bon fonctionn\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes-japan-2026-japan\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-14T04:10:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T01:24:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/08\/maxresdefault-42.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes-japan-2026-japan\\\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes-japan-2026-japan\\\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"Machine \u00e0 caf\u00e9 Black&#038;White4 CTS - DCS CO., LTD. [CAFERES JAPAN 2026]\",\"datePublished\":\"2026-08-14T04:10:16+00:00\",\"dateModified\":\"2026-09-01T01:24:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes-japan-2026-japan\\\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\\\/\"},\"wordCount\":544,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes-japan-2026-japan\\\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/maxresdefault-42.jpg\",\"keywords\":[\"Agriculture \\\/ For\u00eats \\\/ P\u00eache et nourriture\",\"Aliments et boissons \\\/ Transformation des aliments\",\"Am\u00e9nagement et \u00e9quipement de magasin \\\/ Pr\u00e9sentoir\",\"Autres machines et \u00e9quipements industriels\",\"Emballage (Mat\u00e9riaux \\\/ Machines et \u00e9quipements)\",\"H\u00f4tellerie\\\/Restaurant &amp; Restauration\",\"Information \\\/ T\u00e9l\u00e9communication\",\"Japon\",\"Machines \\\/ Technologie industrielle\",\"Prestations de service\",\"Publicit\u00e9\\\/Marketing\\\/Administration des affaires\",\"Soins de sant\u00e9 (\u00e9quipements\\\/produits et services)\",\"Soins m\u00e9dicaux \\\/ Sant\u00e9\",\"Technologie et ing\u00e9nierie de fabrication\",\"T\u00e9l\u00e9communication \\\/ Informatique \\\/ Informatique\",\"Transport \\\/ Logistique \\\/ Emballage\"],\"articleSection\":[\"CAFERES JAPAN 2026\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes-japan-2026-japan\\\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes-japan-2026-japan\\\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes-japan-2026-japan\\\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\\\/\",\"name\":\"Machine \u00e0 caf\u00e9 Black&White4 CTS - DCS CO., LTD. [CAFERES JAPAN 2026] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes-japan-2026-japan\\\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes-japan-2026-japan\\\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/maxresdefault-42.jpg\",\"datePublished\":\"2026-08-14T04:10:16+00:00\",\"dateModified\":\"2026-09-01T01:24:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes-japan-2026-japan\\\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes-japan-2026-japan\\\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes-japan-2026-japan\\\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/maxresdefault-42.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/maxresdefault-42.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes-japan-2026-japan\\\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Machine \u00e0 caf\u00e9 Black&#038;White4 CTS - DCS CO., LTD. [CAFERES JAPAN 2026]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/XWsQkYWMz0E\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"30\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Machine \u00e0 caf\u00e9 Black&White4 CTS - DCS CO., LTD. [CAFERES JAPAN 2026] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes-japan-2026-japan\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\/","og_locale":"fr_FR","og_type":"article","og_title":"Machine \u00e0 caf\u00e9 Black&White4 CTS - DCS CO., LTD. [CAFERES JAPAN 2026] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"Avec l'expansion du march\u00e9 du caf\u00e9 de sp\u00e9cialit\u00e9, les caf\u00e9s ont besoin d'\u00e9quipements haut de gamme capables de reproduire de mani\u00e8re constante des techniques d'infusion avanc\u00e9es, ainsi que d'un support technique fiable pour assurer leur bon fonctionn\u2026","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes-japan-2026-japan\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2026-08-14T04:10:16+00:00","article_modified_time":"2026-09-01T01:24:34+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/08\/maxresdefault-42.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes-japan-2026-japan\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes-japan-2026-japan\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"Machine \u00e0 caf\u00e9 Black&#038;White4 CTS - DCS CO., LTD. [CAFERES JAPAN 2026]","datePublished":"2026-08-14T04:10:16+00:00","dateModified":"2026-09-01T01:24:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes-japan-2026-japan\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\/"},"wordCount":544,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes-japan-2026-japan\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/08\/maxresdefault-42.jpg","keywords":["Agriculture \/ For\u00eats \/ P\u00eache et nourriture","Aliments et boissons \/ Transformation des aliments","Am\u00e9nagement et \u00e9quipement de magasin \/ Pr\u00e9sentoir","Autres machines et \u00e9quipements industriels","Emballage (Mat\u00e9riaux \/ Machines et \u00e9quipements)","H\u00f4tellerie\/Restaurant &amp; Restauration","Information \/ T\u00e9l\u00e9communication","Japon","Machines \/ Technologie industrielle","Prestations de service","Publicit\u00e9\/Marketing\/Administration des affaires","Soins de sant\u00e9 (\u00e9quipements\/produits et services)","Soins m\u00e9dicaux \/ Sant\u00e9","Technologie et ing\u00e9nierie de fabrication","T\u00e9l\u00e9communication \/ Informatique \/ Informatique","Transport \/ Logistique \/ Emballage"],"articleSection":["CAFERES JAPAN 2026"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/caferes-japan-2026-japan\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes-japan-2026-japan\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes-japan-2026-japan\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\/","name":"Machine \u00e0 caf\u00e9 Black&White4 CTS - DCS CO., LTD. [CAFERES JAPAN 2026] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes-japan-2026-japan\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes-japan-2026-japan\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/08\/maxresdefault-42.jpg","datePublished":"2026-08-14T04:10:16+00:00","dateModified":"2026-09-01T01:24:34+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes-japan-2026-japan\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/caferes-japan-2026-japan\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes-japan-2026-japan\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/08\/maxresdefault-42.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/08\/maxresdefault-42.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes-japan-2026-japan\/coffee-machine-blackwhite4-cts-dcs-co-ltd-caferes-japan-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"Machine \u00e0 caf\u00e9 Black&#038;White4 CTS - DCS CO., LTD. [CAFERES JAPAN 2026]"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/XWsQkYWMz0E","og_video_type":"text\/html","og_video_duration":"30","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=XWsQkYWMz0E","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/98378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=98378"}],"version-history":[{"count":2,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/98378\/revisions"}],"predecessor-version":[{"id":98498,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/98378\/revisions\/98498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/98499"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=98378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=98378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=98378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}