{"id":58533,"date":"2026-07-07T01:16:21","date_gmt":"2026-07-07T01:16:21","guid":{"rendered":"https:\/\/www.worldtradeshow.tv\/french\/?p=58533"},"modified":"2026-07-15T04:42:00","modified_gmt":"2026-07-15T04:42:00","slug":"pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/lifestyle-week-tokyo-summer-2026-japan\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\/","title":{"rendered":"Pattofold, le parapluie \u00e0 m\u00e9moire de forme avec panneau de guidage - KIZAWA [29th LIFESTYLE Week TOKYO [Summer] 2026]"},"content":{"rendered":"<div class=\"entry-content \">\n<blockquote class=\"wp-block-quote\">\n<p>Sur le march\u00e9 des articles de pluie et des parasols, la facilit\u00e9 de pliage, la portabilit\u00e9 et la praticit\u00e9 au quotidien deviennent des caract\u00e9ristiques importantes pour les consommateurs qui transportent des parapluies tous les jours.<br \/>Lors de la Lifestyle Week Tokyo Summer, KIZAWA Co., Ltd. a pr\u00e9sent\u00e9 des parapluies et des articles de pluie, en mettant particuli\u00e8rement l&#8217;accent sur son parasol Pattofold.<br \/>Ce produit rem\u00e9die au probl\u00e8me courant des parapluies pliants, difficiles \u00e0 ranger correctement, en proposant une conception ergonomique qui facilite leur pliage apr\u00e8s utilisation.<br \/>L&#8217;entreprise d\u00e9veloppe et vend des articles de pluie et des parapluies pour un usage quotidien, proposant des produits alliant fonctionnalit\u00e9 pratique et design lifestyle aux d\u00e9taillants et aux acheteurs des secteurs de la mode, des activit\u00e9s de plein air et des biens de consommation courante.<\/p>\n<\/blockquote>\n<div class=\"video-summary-grid\">\n<div class=\"summary-card\">\n<h3>D\u00e9fis abord\u00e9s<\/h3>\n<ul>\n<li><a href=\"\/french\/?s=Am%C3%A9liorer%20la%20facilit%C3%A9%20de%20pliage%20des%20parapluies&#038;post_type=post\">Am\u00e9liorer la facilit\u00e9 de pliage des parapluies<\/a><\/li>\n<li><a href=\"\/french\/?s=Produits%20de%20pluie%20pratiques%20pour%20une%20utilisation%20quotidienne&#038;post_type=post\">V\u00eatements de pluie pratiques pour un usage quotidien<\/a><\/li>\n<li><a href=\"\/french\/?s=D%C3%A9veloppement%20de%20produits%20de%20protection%20solaire%20fonctionnels&#038;post_type=post\">D\u00e9veloppement de produits de protection solaire fonctionnels<\/a><\/li>\n<\/ul>\n<\/div>\n<div class=\"summary-card\">\n<h3>Solutions<\/h3>\n<ul>\n<li><a href=\"\/french\/?s=Parasol%20%C3%A0%20pliage&#038;post_type=post\">Parasol pliable<\/a><\/li>\n<li><a href=\"\/french\/?s=Parapluies%20faciles%20%C3%A0%20plier&#038;post_type=post\">Parapluies faciles \u00e0 plier<\/a><\/li>\n<li><a href=\"\/french\/?s=Produits%20fonctionnels%20pour%20la%20pluie&#038;post_type=post\">Produits de pluie fonctionnels<\/a><\/li>\n<\/ul>\n<\/div>\n<div class=\"summary-card\">\n<h3>Clients cibles<\/h3>\n<ul>\n<li><a href=\"\/french\/?s=d%C3%A9taillants%20de%20biens%20de%20consommation&#038;post_type=post\">d\u00e9taillants de produits de style de vie<\/a><\/li>\n<li><a href=\"\/french\/?s=Magasins%20de%20mode%20et%20de%20marchandises%20g%C3%A9n%C3%A9rales&#038;post_type=post\">Magasins de mode et de marchandises g\u00e9n\u00e9rales<\/a><\/li>\n<li><a href=\"\/french\/?s=Acheteurs%20recherchant%20des%20parapluies%20fonctionnels&#038;post_type=post\">Acheteurs \u00e0 la recherche de parapluies fonctionnels<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div class=\"video-faq\">\n<h3 class=\"faq-heading\">FAQ<\/h3>\n<details class=\"faq-item\">\n<summary>Quel produit KIZAWA a-t-il mis en avant lors de l&#8217;exposition ?<\/summary>\n<div class=\"faq-answer\">L&#8217;entreprise a principalement commercialis\u00e9 des parapluies, en mettant l&#8217;accent sur le parasol Pattofold, un produit con\u00e7u pour faciliter le pliage et le rangement.<\/div>\n<\/details>\n<details class=\"faq-item\">\n<summary>Quel probl\u00e8me Pattofold r\u00e9sout-il ?<\/summary>\n<div class=\"faq-answer\">Pattofold r\u00e9sout le probl\u00e8me courant du pliage propre des parapluies apr\u00e8s utilisation. Il est con\u00e7u pour \u00eatre plus facile \u00e0 plier et plus pratique \u00e0 transporter au quotidien.<\/div>\n<\/details>\n<details class=\"faq-item\">\n<summary>Quels types d&#8217;acheteurs sont adapt\u00e9s \u00e0 ces produits\u00a0?<\/summary>\n<div class=\"faq-answer\">Ces produits conviennent aux d\u00e9taillants d&#8217;articles de mode et de loisirs, aux boutiques de mode, aux magasins de biens de consommation courante et aux acheteurs \u00e0 la recherche de parapluies et d&#8217;articles de pluie fonctionnels.<\/div>\n<\/details>\n<\/div>\n<details class=\"video-transcript\">\n<summary>Voir la transcription vid\u00e9o<\/summary>\n<div class=\"transcript-content\">[[TRANSCRIPTION]]<\/div>\n<\/details>\n<h2>Contactez l&#8217;entreprise<\/h2>\n<div class=\"company-profile-section\">\n<div class=\"company-shot\">\n<div class=\"browser-shot alignnone\"><a href=\"https:\/\/kizawa-corp.com\/\" target=\"_blank\"><img fetchpriority=\"high\" decoding=\"async\"src=\"https:\/\/s0.wp.com\/mshots\/v1\/https%3A%2F%2Fkizawa-corp.com%2F?w=600&#038;h=450\"alt=\"Site officiel de KIZAWA Co., Ltd.\"width=\"600\"height=\"450\"class=\"alignnone\"><\/a><\/div>\n<\/div>\n<div class=\"company-info\">\n<h3 class=\"company-name\">KIZAWA Co., Ltd.<\/h3>\n<ul class=\"company-meta\">\n<li><span class=\"label\">Quartier g\u00e9n\u00e9ral<\/span> <span class=\"value\">2F B\u00e2timent Kuwano, 6-23-4 Jingumae, Shibuya-ku, Tokyo, Japon<\/span><\/li>\n<li><span class=\"label\">\u00c9tabli<\/span> <span class=\"value\">&#8211;<\/span><\/li>\n<li><span class=\"label\">Employ\u00e9s<\/span> <span class=\"value\">&#8211;<\/span><\/li>\n<li><span class=\"label\">Site officiel<\/span> <span class=\"value\"><a href=\"https:\/\/kizawa-corp.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/kizawa-corp.com\/<\/a><\/span><\/li>\n<li><span class=\"label\">Secteurs d&#8217;activit\u00e9<\/span> <span class=\"value\">V\u00eatements de pluie, parapluies, parasols, produits fonctionnels du quotidien et accessoires d&#8217;usage courant<\/span><\/li>\n<li><span class=\"label\">Principaux produits et services<\/span> <span class=\"value\">Pattofold, Selfold, U.Light, Coolia, UVest, Silky Lux, parapluies pliants, parasols, articles de pluie et parapluies fonctionnels<\/span><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sur le march\u00e9 des articles de pluie et des parasols, la facilit\u00e9 de pliage, la portabilit\u00e9 et la praticit\u00e9 au quotidien deviennent des caract\u00e9ristiques importantes pour les consommateurs qui transportent des parapluies tous les jours.Lors de la Lifes\u2026<\/p>\n","protected":false},"author":1,"featured_media":58535,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[791],"tags":[43,536,650,651,659,577,579,563,657,568,551,30,31,38,654,520,569,36,588,34,576,37,615,42],"class_list":["post-58533","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-lifestyle-week-tokyo-summer-2026-japan","tag-agriculture-forestry-fishery-and-food","tag-agriculture-forestry-fishery-and-food-2","tag-living-5","tag-living-10","tag-hobby-education-8","tag-living-6","tag-living-9","tag-services-7","tag-hobby-education-6","tag-transportation-logistics-packaging-9","tag-information-telecommunication-3","tag-hobby-education","tag-information-telecommunication","tag-japan","tag-hobby-education-2","tag-living-4","tag-living-3","tag-services","tag-medical-care-health-5","tag-medical-care-health","tag-living-2","tag-transportation-logistics-packaging","tag-services-5","tag-living","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pattofold, le parapluie \u00e0 m\u00e9moire de forme avec panneau de guidage - KIZAWA [29th LIFESTYLE Week TOKYO [Summer] 2026] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/lifestyle-week-tokyo-summer-2026-japan\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pattofold, le parapluie \u00e0 m\u00e9moire de forme avec panneau de guidage - KIZAWA [29th LIFESTYLE Week TOKYO [Summer] 2026] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"Sur le march\u00e9 des articles de pluie et des parasols, la facilit\u00e9 de pliage, la portabilit\u00e9 et la praticit\u00e9 au quotidien deviennent des caract\u00e9ristiques importantes pour les consommateurs qui transportent des parapluies tous les jours.Lors de la Lifes\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/lifestyle-week-tokyo-summer-2026-japan\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-07T01:16:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T04:42:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/07\/maxresdefault-24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/lifestyle-week-tokyo-summer-2026-japan\\\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/lifestyle-week-tokyo-summer-2026-japan\\\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"Pattofold, le parapluie \u00e0 m\u00e9moire de forme avec panneau de guidage - KIZAWA [29th LIFESTYLE Week TOKYO [Summer] 2026]\",\"datePublished\":\"2026-07-07T01:16:21+00:00\",\"dateModified\":\"2026-07-15T04:42:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/lifestyle-week-tokyo-summer-2026-japan\\\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\\\/\"},\"wordCount\":418,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/lifestyle-week-tokyo-summer-2026-japan\\\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/maxresdefault-24.jpg\",\"keywords\":[\"Agriculture \\\/ For\u00eats \\\/ P\u00eache et nourriture\",\"Aliments et boissons \\\/ Transformation des aliments\",\"Articles m\u00e9nagers \\\/ Vaisselle \\\/ Porcelaine \\\/ Verrerie\",\"Articles pour enfants et b\u00e9b\u00e9s\",\"Arts et artisanat\\\/Antiquit\u00e9s\",\"Cadeaux \\\/ Artisanat \\\/ Primes et incitations\",\"Cosm\u00e9tiques\\\/Produits de soins de beaut\u00e9\\\/Parfumerie\",\"Design (y compris design industriel)\",\"\u00c9ducation et formation\",\"Emballage (Mat\u00e9riaux \\\/ Machines et \u00e9quipements)\",\"Fournitures et \u00e9quipement de bureau \\\/ Bureautique\",\"Hobby \\\/ Education\",\"Information \\\/ T\u00e9l\u00e9communication\",\"Japon\",\"Jouets et jeux\",\"Meubles et accessoires \\\/ Pi\u00e8ces\",\"Papier et produits en papier\\\/Impression et \u00e9dition\",\"Prestations de service\",\"Soins de sant\u00e9 (\u00e9quipements\\\/produits et services)\",\"Soins m\u00e9dicaux \\\/ Sant\u00e9\",\"Textiles et v\u00eatements (Mat\u00e9riaux \\\/ Produits et machines)\",\"Transport \\\/ Logistique \\\/ Emballage\",\"Vente au d\u00e9tail\\\/commerce de gros\\\/distribution\\\/franchise\",\"Vivant\"],\"articleSection\":[\"29th LIFESTYLE Week TOKYO [Summer] 2026\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/lifestyle-week-tokyo-summer-2026-japan\\\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/lifestyle-week-tokyo-summer-2026-japan\\\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/lifestyle-week-tokyo-summer-2026-japan\\\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\\\/\",\"name\":\"Pattofold, le parapluie \u00e0 m\u00e9moire de forme avec panneau de guidage - KIZAWA [29th LIFESTYLE Week TOKYO [Summer] 2026] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/lifestyle-week-tokyo-summer-2026-japan\\\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/lifestyle-week-tokyo-summer-2026-japan\\\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/maxresdefault-24.jpg\",\"datePublished\":\"2026-07-07T01:16:21+00:00\",\"dateModified\":\"2026-07-15T04:42:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/lifestyle-week-tokyo-summer-2026-japan\\\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/lifestyle-week-tokyo-summer-2026-japan\\\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/lifestyle-week-tokyo-summer-2026-japan\\\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/maxresdefault-24.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/maxresdefault-24.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/lifestyle-week-tokyo-summer-2026-japan\\\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pattofold, le parapluie \u00e0 m\u00e9moire de forme avec panneau de guidage - KIZAWA [29th LIFESTYLE Week TOKYO [Summer] 2026]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/dZQal6HST5o\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"38\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pattofold, le parapluie \u00e0 m\u00e9moire de forme avec panneau de guidage - KIZAWA [29th LIFESTYLE Week TOKYO [Summer] 2026] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/lifestyle-week-tokyo-summer-2026-japan\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\/","og_locale":"fr_FR","og_type":"article","og_title":"Pattofold, le parapluie \u00e0 m\u00e9moire de forme avec panneau de guidage - KIZAWA [29th LIFESTYLE Week TOKYO [Summer] 2026] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"Sur le march\u00e9 des articles de pluie et des parasols, la facilit\u00e9 de pliage, la portabilit\u00e9 et la praticit\u00e9 au quotidien deviennent des caract\u00e9ristiques importantes pour les consommateurs qui transportent des parapluies tous les jours.Lors de la Lifes\u2026","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/lifestyle-week-tokyo-summer-2026-japan\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2026-07-07T01:16:21+00:00","article_modified_time":"2026-07-15T04:42:00+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/07\/maxresdefault-24.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/lifestyle-week-tokyo-summer-2026-japan\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/lifestyle-week-tokyo-summer-2026-japan\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"Pattofold, le parapluie \u00e0 m\u00e9moire de forme avec panneau de guidage - KIZAWA [29th LIFESTYLE Week TOKYO [Summer] 2026]","datePublished":"2026-07-07T01:16:21+00:00","dateModified":"2026-07-15T04:42:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/lifestyle-week-tokyo-summer-2026-japan\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\/"},"wordCount":418,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/lifestyle-week-tokyo-summer-2026-japan\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/07\/maxresdefault-24.jpg","keywords":["Agriculture \/ For\u00eats \/ P\u00eache et nourriture","Aliments et boissons \/ Transformation des aliments","Articles m\u00e9nagers \/ Vaisselle \/ Porcelaine \/ Verrerie","Articles pour enfants et b\u00e9b\u00e9s","Arts et artisanat\/Antiquit\u00e9s","Cadeaux \/ Artisanat \/ Primes et incitations","Cosm\u00e9tiques\/Produits de soins de beaut\u00e9\/Parfumerie","Design (y compris design industriel)","\u00c9ducation et formation","Emballage (Mat\u00e9riaux \/ Machines et \u00e9quipements)","Fournitures et \u00e9quipement de bureau \/ Bureautique","Hobby \/ Education","Information \/ T\u00e9l\u00e9communication","Japon","Jouets et jeux","Meubles et accessoires \/ Pi\u00e8ces","Papier et produits en papier\/Impression et \u00e9dition","Prestations de service","Soins de sant\u00e9 (\u00e9quipements\/produits et services)","Soins m\u00e9dicaux \/ Sant\u00e9","Textiles et v\u00eatements (Mat\u00e9riaux \/ Produits et machines)","Transport \/ Logistique \/ Emballage","Vente au d\u00e9tail\/commerce de gros\/distribution\/franchise","Vivant"],"articleSection":["29th LIFESTYLE Week TOKYO [Summer] 2026"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/lifestyle-week-tokyo-summer-2026-japan\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/lifestyle-week-tokyo-summer-2026-japan\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/lifestyle-week-tokyo-summer-2026-japan\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\/","name":"Pattofold, le parapluie \u00e0 m\u00e9moire de forme avec panneau de guidage - KIZAWA [29th LIFESTYLE Week TOKYO [Summer] 2026] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/lifestyle-week-tokyo-summer-2026-japan\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/lifestyle-week-tokyo-summer-2026-japan\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/07\/maxresdefault-24.jpg","datePublished":"2026-07-07T01:16:21+00:00","dateModified":"2026-07-15T04:42:00+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/lifestyle-week-tokyo-summer-2026-japan\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/lifestyle-week-tokyo-summer-2026-japan\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/lifestyle-week-tokyo-summer-2026-japan\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/07\/maxresdefault-24.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/07\/maxresdefault-24.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/lifestyle-week-tokyo-summer-2026-japan\/pattofold-the-shape-memory-umbrella-with-a-guide-panel-kizawa-29th-lifestyle-week-tokyo-summer-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"Pattofold, le parapluie \u00e0 m\u00e9moire de forme avec panneau de guidage - KIZAWA [29th LIFESTYLE Week TOKYO [Summer] 2026]"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/dZQal6HST5o","og_video_type":"text\/html","og_video_duration":"38","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=dZQal6HST5o","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/58533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=58533"}],"version-history":[{"count":1,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/58533\/revisions"}],"predecessor-version":[{"id":58534,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/58533\/revisions\/58534"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/58535"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=58533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=58533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=58533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}