{"id":58394,"date":"2026-06-29T04:18:12","date_gmt":"2026-06-29T04:18:12","guid":{"rendered":"https:\/\/www.worldtradeshow.tv\/french\/?p=58394"},"modified":"2026-06-30T05:36:46","modified_gmt":"2026-06-30T05:36:46","slug":"site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo-2026-japan\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\/","title":{"rendered":"Site Now, une plateforme IoT pour la gestion de la construction - TOPCON CORPORATION [8th International Construction &#038; Survey Productivity Improvement EXPO(CSPI2026)]"},"content":{"rendered":"<div class=\"entry-content \">\n<blockquote class=\"wp-block-quote\">\n<p>Sur les chantiers de construction, la gestion des donn\u00e9es de terrain dans le nuage devient de plus en plus importante pour am\u00e9liorer le suivi des progr\u00e8s, la gestion des plans de r\u00e9colement et le partage d&#8217;informations avec les propri\u00e9taires de projets.<br \/>Lors du salon CSPI-EXPO, TOPCON CORPORATION a pr\u00e9sent\u00e9 \u00ab\u00a0Site Now\u00a0\u00bb, une plateforme de gestion de la construction bas\u00e9e sur le cloud. Ce syst\u00e8me permet de visualiser l\u2019avancement des travaux et les informations de terrain en temps r\u00e9el, et offre une gestion centralis\u00e9e via le cloud.<br \/>Site Now calcule automatiquement les plannings \u00e0 partir des donn\u00e9es du cloud et les exporte dans les formats requis par le minist\u00e8re japonais du Territoire, des Infrastructures, des Transports et du Tourisme pour la gestion des ouvrages r\u00e9alis\u00e9s. Gr\u00e2ce \u00e0 l&#8217;utilisation des donn\u00e9es de construction issues des TIC, il contribue \u00e0 all\u00e9ger la charge de travail li\u00e9e \u00e0 la pr\u00e9paration des documents de gestion et au suivi de l&#8217;avancement des projets.<br \/>En tant que fabricant d&#8217;\u00e9quipements de pr\u00e9cision fournissant des instruments de topographie et des solutions de construction TIC, TOPCON soutient la transformation num\u00e9rique, le partage d&#8217;informations et la gestion avanc\u00e9e des chantiers.<\/p>\n<\/blockquote>\n<div class=\"video-summary-grid\">\n<div class=\"summary-card\">\n<h3>D\u00e9fis abord\u00e9s<\/h3>\n<ul>\n<li><a href=\"\/french\/?s=construction%2Bavancement%2Bgestion%2Befficacit%C3%A9&#038;post_type=post\">efficacit\u00e9 de la gestion de l&#8217;avancement des travaux<\/a><\/li>\n<li><a href=\"\/french\/?s=partage%20d%27informations%20entre%20les%20chantiers%20et%20les%20ma%C3%AEtres%20d%27ouvrage&#038;post_type=post\">Partage d&#8217;informations entre les chantiers et les ma\u00eetres d&#8217;ouvrage<\/a><\/li>\n<li><a href=\"\/french\/?s=charge%20de%20travail%20des%20documents%20de%20gestion%20de%20la%20construction&#038;post_type=post\">Charge de travail des documents de gestion de l&#8217;\u00e9tat de l&#8217;ouvrage<\/a><\/li>\n<\/ul>\n<\/div>\n<div class=\"summary-card\">\n<h3>Solutions<\/h3>\n<ul>\n<li><a href=\"\/french\/?s=Site%2BMaintenant&#038;post_type=post\">Site maintenant<\/a><\/li>\n<li><a href=\"\/french\/?s=cloud%2Bconstruction%2Bgestion&#038;post_type=post\">Gestion de la construction dans le cloud<\/a><\/li>\n<li><a href=\"\/french\/?s=TIC%2Bconstruction%2Bint%C3%A9gration%20des%20donn%C3%A9es&#038;post_type=post\">int\u00e9gration des donn\u00e9es de construction TIC<\/a><\/li>\n<\/ul>\n<\/div>\n<div class=\"summary-card\">\n<h3>Clients cibles<\/h3>\n<ul>\n<li><a href=\"\/french\/?s=entreprises%20de%20construction&#038;post_type=post\">entreprises de construction<\/a><\/li>\n<li><a href=\"\/french\/?s=construction%20%2B%20gestion%20%2B%20%C3%A9quipes&#038;post_type=post\">\u00e9quipes de gestion de la construction<\/a><\/li>\n<li><a href=\"\/french\/?s=propri%C3%A9taires%20de%20projets%20publics&#038;post_type=post\">Les ma\u00eetres d&#8217;ouvrage et les organismes publics<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div class=\"video-faq\">\n<h3 class=\"faq-heading\">FAQ<\/h3>\n<details class=\"faq-item\">\n<summary>Qu&#8217;est-ce que Site Now ?<\/summary>\n<div class=\"faq-answer\">Site Now est une plateforme de gestion de la construction bas\u00e9e sur le cloud qui permet de visualiser l&#8217;avancement des travaux et les informations de terrain en temps r\u00e9el. Elle facilite la gestion centralis\u00e9e et le partage d&#8217;informations entre les chefs de chantier et les ma\u00eetres d&#8217;ouvrage.<\/div>\n<\/details>\n<details class=\"faq-item\">\n<summary>Le site Site Now peut-il utiliser les donn\u00e9es de construction issues des TIC\u00a0?<\/summary>\n<div class=\"faq-answer\">Oui. Site Now est con\u00e7u pour utiliser les donn\u00e9es de construction issues des TIC afin de faciliter la gestion des progr\u00e8s, le calcul des \u00e9ch\u00e9anciers et la pr\u00e9paration des documents de gestion des ouvrages r\u00e9alis\u00e9s.<\/div>\n<\/details>\n<details class=\"faq-item\">\n<summary>Site Now prend-il en charge les documents de gestion conformes \u00e0 l&#8217;ex\u00e9cution ?<\/summary>\n<div class=\"faq-answer\">Oui. La plateforme peut exporter des donn\u00e9es dans les formats requis par le minist\u00e8re japonais du Territoire, des Infrastructures, des Transports et du Tourisme pour la gestion des ouvrages r\u00e9alis\u00e9s, contribuant ainsi \u00e0 r\u00e9duire la charge de travail li\u00e9e \u00e0 la pr\u00e9paration des documents.<\/div>\n<\/details>\n<\/div>\n<details class=\"video-transcript\">\n<summary>Voir la transcription vid\u00e9o<\/summary>\n<div class=\"transcript-content\">Nous sommes TOPCON CORPORATION.<br \/>Nous souhaitons vous pr\u00e9senter notre nouveau produit \u00ab Site Now \u00bb, sorti en mars dernier.<br \/>Site Now permet de visualiser l&#8217;\u00e9tat actuel du chantier et fournit un syst\u00e8me qui assure une gestion int\u00e9gr\u00e9e entre le site et le cloud.<br \/>Plus pr\u00e9cis\u00e9ment, Site Now permet aux utilisateurs de suivre l&#8217;avancement des travaux et les conditions sur le terrain en temps r\u00e9el. Le syst\u00e8me peut \u00e9galement calculer automatiquement les plannings \u00e0 partir des donn\u00e9es du cloud. De plus, gr\u00e2ce aux formats de donn\u00e9es d\u00e9finis par le minist\u00e8re japonais du Territoire, des Infrastructures, des Transports et du Tourisme pour les \u00e9tats des lieux et le statut de gestion, il est capable de les exporter.<br \/>L&#8217;une des principales caract\u00e9ristiques est que ces t\u00e2ches peuvent \u00eatre effectu\u00e9es automatiquement gr\u00e2ce aux donn\u00e9es de construction issues des TIC.<br \/>Gr\u00e2ce \u00e0 ces informations, les agents de chantier peuvent suivre l&#8217;avancement des travaux, et le partage d&#8217;informations avec les ma\u00eetres d&#8217;ouvrage peut \u00eatre beaucoup plus facile via le cloud.<br \/>N&#8217;h\u00e9sitez pas \u00e0 nous contacter si cela vous int\u00e9resse.<\/div>\n<\/details>\n<h2>Contactez l&#8217;entreprise<\/h2>\n<div class=\"company-profile-section\">\n<div class=\"company-shot\">\n<div class=\"browser-shot alignnone\"><a href=\"https:\/\/www.topcon.co.jp\/\" target=\"_blank\"><img fetchpriority=\"high\" decoding=\"async\"src=\"https:\/\/s0.wp.com\/mshots\/v1\/https%3A%2F%2Fwww.topcon.co.jp%2F?w=600&#038;h=450\"alt=\"Site officiel de TOPCON CORPORATION\"width=\"600\"height=\"450\"class=\"alignnone\"><\/a><\/div>\n<\/div>\n<div class=\"company-info\">\n<h3 class=\"company-name\">TOPCON CORPORATION<\/h3>\n<ul class=\"company-meta\">\n<li><span class=\"label\">Quartier g\u00e9n\u00e9ral<\/span> <span class=\"value\">75-1 Hasunuma-cho, Itabashi-ku, Tokyo, Japon<\/span><\/li>\n<li><span class=\"label\">\u00c9tabli<\/span> <span class=\"value\">Septembre 1932<\/span><\/li>\n<li><span class=\"label\">Employ\u00e9s<\/span> <span class=\"value\">5 571 employ\u00e9s sur une base consolid\u00e9e<\/span><\/li>\n<li><span class=\"label\">Site officiel<\/span> <span class=\"value\"><a href=\"https:\/\/www.topcon.co.jp\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.topcon.co.jp\/<\/a><\/span><\/li>\n<li><span class=\"label\">Secteurs d&#8217;activit\u00e9<\/span> <span class=\"value\">Instruments topographiques, solutions DX pour la construction, solutions TIC pour la construction, assistance \u00e0 la gestion de la construction, d\u00e9veloppement, fabrication et vente d&#8217;\u00e9quipements de pr\u00e9cision<\/span><\/li>\n<li><span class=\"label\">Principaux produits et services<\/span> <span class=\"value\">Site Now propose des instruments de topographie GNSS, des stations totales, des syst\u00e8mes de commande de machines, des solutions de construction TIC et des syst\u00e8mes de topographie 3D.<\/span><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sur les chantiers de construction, la gestion des donn\u00e9es de terrain dans le nuage devient de plus en plus importante pour am\u00e9liorer le suivi des progr\u00e8s, la gestion des plans de r\u00e9colement et le partage d&#8217;informations avec les propri\u00e9taires de proje\u2026<\/p>\n","protected":false},"author":1,"featured_media":58396,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[787],"tags":[595,542,518,26,27,529,604,31,599,77,38,33,567,36,557,552,634,505,506,37],"class_list":["post-58394","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-cspi-expo-2026-japan","tag-transportation-logistics-packaging-1","tag-machinery-industrial-technology-7","tag-building-construction-1","tag-building-construction","tag-environment","tag-building-construction-3","tag-machinery-industrial-technology-5","tag-information-telecommunication","tag-innovation-startups-1","tag-innovation-startups","tag-japan","tag-machinery-industrial-technology","tag-machinery-industrial-technology-4","tag-services","tag-environment-1","tag-services-3","tag-services-9","tag-machinery-industrial-technology-9","tag-information-telecommunication-1","tag-transportation-logistics-packaging","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Site Now, une plateforme IoT pour la gestion de la construction - TOPCON CORPORATION [8th International Construction &amp; Survey Productivity Improvement EXPO(CSPI2026)] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo-2026-japan\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Site Now, une plateforme IoT pour la gestion de la construction - TOPCON CORPORATION [8th International Construction &amp; Survey Productivity Improvement EXPO(CSPI2026)] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"Sur les chantiers de construction, la gestion des donn\u00e9es de terrain dans le nuage devient de plus en plus importante pour am\u00e9liorer le suivi des progr\u00e8s, la gestion des plans de r\u00e9colement et le partage d&#039;informations avec les propri\u00e9taires de proje\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo-2026-japan\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-29T04:18:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-30T05:36:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/06\/maxresdefault-44.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo-2026-japan\\\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo-2026-japan\\\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"Site Now, une plateforme IoT pour la gestion de la construction - TOPCON CORPORATION [8th International Construction &#038; Survey Productivity Improvement EXPO(CSPI2026)]\",\"datePublished\":\"2026-06-29T04:18:12+00:00\",\"dateModified\":\"2026-06-30T05:36:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo-2026-japan\\\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/\"},\"wordCount\":788,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo-2026-japan\\\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/maxresdefault-44.jpg\",\"keywords\":[\"Automobiles (y compris pi\u00e8ces\\\/machines)\",\"Autres machines et \u00e9quipements industriels\",\"B\u00e2timent et construction \\\/ Immobilier\",\"Construction de b\u00e2timents\",\"Environnement\",\"\u00c9quipements pour \u00c9tablissement Public \\\/ Am\u00e9nagement Urbain\",\"Essais\\\/Mesure et analyse\\\/M\u00e9canique de pr\u00e9cision\",\"Information \\\/ T\u00e9l\u00e9communication\",\"Innovation \\\/ Start-up\",\"Innovation \\\/ Startups\",\"Japon\",\"Machines \\\/ Technologie industrielle\",\"Manutention \\\/ Pneumatique\",\"Prestations de service\",\"Protection de l'environnement \\\/ \u00c9limination des d\u00e9chets \\\/ Recyclage\",\"Publicit\u00e9\\\/Marketing\\\/Administration des affaires\",\"S\u00e9curit\u00e9 et sant\u00e9 au travail \\\/ Gestion du travail\",\"Technologie avanc\u00e9e \\\/ Mat\u00e9riaux \\\/ Composites \\\/ R&amp;D\",\"T\u00e9l\u00e9communication \\\/ Informatique \\\/ Informatique\",\"Transport \\\/ Logistique \\\/ Emballage\"],\"articleSection\":[\"8th International Construction &amp; Survey Productivity Improvement EXPO(CSPI2026)\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo-2026-japan\\\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo-2026-japan\\\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo-2026-japan\\\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/\",\"name\":\"Site Now, une plateforme IoT pour la gestion de la construction - TOPCON CORPORATION [8th International Construction & Survey Productivity Improvement EXPO(CSPI2026)] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo-2026-japan\\\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo-2026-japan\\\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/maxresdefault-44.jpg\",\"datePublished\":\"2026-06-29T04:18:12+00:00\",\"dateModified\":\"2026-06-30T05:36:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo-2026-japan\\\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo-2026-japan\\\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo-2026-japan\\\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/maxresdefault-44.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/maxresdefault-44.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo-2026-japan\\\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Site Now, une plateforme IoT pour la gestion de la construction - TOPCON CORPORATION [8th International Construction &#038; Survey Productivity Improvement EXPO(CSPI2026)]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/fGtX76z1jWU\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"89\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Site Now, une plateforme IoT pour la gestion de la construction - TOPCON CORPORATION [8th International Construction & Survey Productivity Improvement EXPO(CSPI2026)] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo-2026-japan\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\/","og_locale":"fr_FR","og_type":"article","og_title":"Site Now, une plateforme IoT pour la gestion de la construction - TOPCON CORPORATION [8th International Construction & Survey Productivity Improvement EXPO(CSPI2026)] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"Sur les chantiers de construction, la gestion des donn\u00e9es de terrain dans le nuage devient de plus en plus importante pour am\u00e9liorer le suivi des progr\u00e8s, la gestion des plans de r\u00e9colement et le partage d'informations avec les propri\u00e9taires de proje\u2026","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo-2026-japan\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2026-06-29T04:18:12+00:00","article_modified_time":"2026-06-30T05:36:46+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/06\/maxresdefault-44.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo-2026-japan\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo-2026-japan\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"Site Now, une plateforme IoT pour la gestion de la construction - TOPCON CORPORATION [8th International Construction &#038; Survey Productivity Improvement EXPO(CSPI2026)]","datePublished":"2026-06-29T04:18:12+00:00","dateModified":"2026-06-30T05:36:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo-2026-japan\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\/"},"wordCount":788,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo-2026-japan\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/06\/maxresdefault-44.jpg","keywords":["Automobiles (y compris pi\u00e8ces\/machines)","Autres machines et \u00e9quipements industriels","B\u00e2timent et construction \/ Immobilier","Construction de b\u00e2timents","Environnement","\u00c9quipements pour \u00c9tablissement Public \/ Am\u00e9nagement Urbain","Essais\/Mesure et analyse\/M\u00e9canique de pr\u00e9cision","Information \/ T\u00e9l\u00e9communication","Innovation \/ Start-up","Innovation \/ Startups","Japon","Machines \/ Technologie industrielle","Manutention \/ Pneumatique","Prestations de service","Protection de l'environnement \/ \u00c9limination des d\u00e9chets \/ Recyclage","Publicit\u00e9\/Marketing\/Administration des affaires","S\u00e9curit\u00e9 et sant\u00e9 au travail \/ Gestion du travail","Technologie avanc\u00e9e \/ Mat\u00e9riaux \/ Composites \/ R&amp;D","T\u00e9l\u00e9communication \/ Informatique \/ Informatique","Transport \/ Logistique \/ Emballage"],"articleSection":["8th International Construction &amp; Survey Productivity Improvement EXPO(CSPI2026)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo-2026-japan\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo-2026-japan\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo-2026-japan\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\/","name":"Site Now, une plateforme IoT pour la gestion de la construction - TOPCON CORPORATION [8th International Construction & Survey Productivity Improvement EXPO(CSPI2026)] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo-2026-japan\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo-2026-japan\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/06\/maxresdefault-44.jpg","datePublished":"2026-06-29T04:18:12+00:00","dateModified":"2026-06-30T05:36:46+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo-2026-japan\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo-2026-japan\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo-2026-japan\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/06\/maxresdefault-44.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/06\/maxresdefault-44.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo-2026-japan\/site-now-an-iot-platform-for-construction-management-topcon-corporation-8th-international-construction-survey-productivity-improvement-expocspi2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"Site Now, une plateforme IoT pour la gestion de la construction - TOPCON CORPORATION [8th International Construction &#038; Survey Productivity Improvement EXPO(CSPI2026)]"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/fGtX76z1jWU","og_video_type":"text\/html","og_video_duration":"89","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=fGtX76z1jWU","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/58394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=58394"}],"version-history":[{"count":1,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/58394\/revisions"}],"predecessor-version":[{"id":58395,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/58394\/revisions\/58395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/58396"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=58394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=58394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=58394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}