{"id":58382,"date":"2026-06-29T04:18:16","date_gmt":"2026-06-29T04:18:16","guid":{"rendered":"https:\/\/www.worldtradeshow.tv\/french\/?p=58382"},"modified":"2026-06-30T05:36:46","modified_gmt":"2026-06-30T05:36:46","slug":"inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo-2026-japan\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\/","title":{"rendered":"Services de drones d'inspection et de lev\u00e9s topographiques - FURUKAWA SANGYO KAISHA, LTD. [8th International Construction &#038; Survey Productivity Improvement EXPO(CSPI2026)]"},"content":{"rendered":"<div class=\"entry-content \">\n<blockquote class=\"wp-block-quote\">\n<p>Pour les travaux d&#8217;arpentage et d&#8217;inspection des rivi\u00e8res, des ports, des barrages et autres plans d&#8217;eau, les op\u00e9rateurs doivent collecter efficacement les donn\u00e9es de profondeur et de terrain tout en r\u00e9duisant la n\u00e9cessit\u00e9 pour les travailleurs de p\u00e9n\u00e9trer dans des zones dangereuses.<br \/>Lors du salon CSPI-EXPO, Furukawa Sangyo Kaisha, Ltd. a pr\u00e9sent\u00e9 deux types de bateaux radiocommand\u00e9s\u00a0: l\u2019un destin\u00e9 \u00e0 la lev\u00e9 topographique et l\u2019autre \u00e0 l\u2019inspection. Le mod\u00e8le de lev\u00e9 permet la mesure de la profondeur et peut \u00eatre \u00e9quip\u00e9 d\u2019un sonar monofaisceau ou d\u2019un sonar multifaisceaux selon l\u2019application.<br \/>Le plus grand bateau de lev\u00e9s hydrographiques peut embarquer un sonar multifaisceaux capable d&#8217;acqu\u00e9rir des donn\u00e9es 3D. Ceci permet des lev\u00e9s hydrographiques automatis\u00e9s et moins gourmands en main-d&#8217;\u0153uvre, contribuant ainsi \u00e0 am\u00e9liorer la s\u00e9curit\u00e9 des travailleurs et l&#8217;efficacit\u00e9 de la collecte de donn\u00e9es.<br \/>En tant que soci\u00e9t\u00e9 commerciale du groupe Furukawa Electric, Furukawa Sangyo propose \u00e9galement des solutions li\u00e9es aux drones et aux robots, ainsi que des technologies sans pilote pour l&#8217;inspection et la surveillance des infrastructures.<\/p>\n<\/blockquote>\n<div class=\"video-summary-grid\">\n<div class=\"summary-card\">\n<h3>D\u00e9fis abord\u00e9s<\/h3>\n<ul>\n<li><a href=\"\/french\/?s=charge%20de%20travail%20li%C3%A9e%20%C3%A0%20l%27arpentage%20des%20zones%20aquatiques&#038;post_type=post\">Charge de travail dans le domaine des lev\u00e9s topographiques des zones aquatiques<\/a><\/li>\n<li><a href=\"\/french\/?s=risques%2Bdans%2Bles%2Bzones%2Bd%27inspection%2Bdangereuses&#038;post_type=post\">Risques dans les zones d&#8217;inspection dangereuses<\/a><\/li>\n<li><a href=\"\/french\/?s=acquisition%20de%20donn%C3%A9es%203D%20efficace&#038;post_type=post\">Acquisition efficace de donn\u00e9es 3D<\/a><\/li>\n<\/ul>\n<\/div>\n<div class=\"summary-card\">\n<h3>Solutions<\/h3>\n<ul>\n<li><a href=\"\/french\/?s=bateau%20de%20lev%C3%A9%20radiocommand%C3%A9&#038;post_type=post\">Bateau de lev\u00e9s hydrographiques radiocommand\u00e9<\/a><\/li>\n<li><a href=\"\/french\/?s=bateau%20d%27inspection%20radiocommand%C3%A9&#038;post_type=post\">Bateau d&#8217;inspection radiocommand\u00e9<\/a><\/li>\n<li><a href=\"\/french\/?s=lev%C3%A9s%20topographiques%20par%20sonar%20multifaisceaux&#038;post_type=post\">lev\u00e9s topographiques par sonar multifaisceaux<\/a><\/li>\n<\/ul>\n<\/div>\n<div class=\"summary-card\">\n<h3>Clients cibles<\/h3>\n<ul>\n<li><a href=\"\/french\/?s=soci%C3%A9t%C3%A9s%20d%27arpentage&#038;post_type=post\">Soci\u00e9t\u00e9s d&#8217;arpentage<\/a><\/li>\n<li><a href=\"\/french\/?s=construction%2Bconsultants&#038;post_type=post\">consultants en construction<\/a><\/li>\n<li><a href=\"\/french\/?s=exploitants%20d%27installations%20fluviales%20et%20portuaires&#038;post_type=post\">exploitants d&#8217;installations fluviales et portuaires<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div class=\"video-faq\">\n<h3 class=\"faq-heading\">FAQ<\/h3>\n<details class=\"faq-item\">\n<summary>\u00c0 quoi sert un bateau de lev\u00e9s topographiques radiocommand\u00e9 ?<\/summary>\n<div class=\"faq-answer\">Il est utilis\u00e9 pour les lev\u00e9s topographiques des zones aquatiques, notamment la mesure de la profondeur des rivi\u00e8res, des ports, des barrages et autres sites similaires. Il permet de r\u00e9duire la n\u00e9cessit\u00e9 pour les travailleurs d&#8217;embarquer \u00e0 bord des navires et facilite les op\u00e9rations de lev\u00e9s n\u00e9cessitant peu de main-d&#8217;\u0153uvre.<\/div>\n<\/details>\n<details class=\"faq-item\">\n<summary>Quelle est la diff\u00e9rence entre un sonar monofaisceau et un sonar multifaisceaux\u00a0?<\/summary>\n<div class=\"faq-answer\">Le sonar monofaisceau sert \u00e0 mesurer la profondeur, tandis que le sonar multifaisceaux permet d&#8217;acqu\u00e9rir des donn\u00e9es 3D sur une zone plus \u00e9tendue. Le choix d\u00e9pend du type de donn\u00e9es requises et des conditions de lev\u00e9.<\/div>\n<\/details>\n<details class=\"faq-item\">\n<summary>Ces bateaux peuvent-ils \u00e9galement \u00eatre utilis\u00e9s pour des travaux d&#8217;inspection\u00a0?<\/summary>\n<div class=\"faq-answer\">Oui. L&#8217;exposition pr\u00e9sentait un mod\u00e8le de lev\u00e9 topographique et un mod\u00e8le d&#8217;inspection, illustrant des cas d&#8217;utilisation pour l&#8217;inspection des zones aquatiques et la maintenance des infrastructures.<\/div>\n<\/details>\n<\/div>\n<details class=\"video-transcript\">\n<summary>Voir la transcription vid\u00e9o<\/summary>\n<div class=\"transcript-content\">Nous sommes Furukawa Sangyo Kaisha, Ltd.<br \/>Notre soci\u00e9t\u00e9 op\u00e8re principalement en tant que division commerciale de Furukawa Electric Co., Ltd., et notre d\u00e9partement g\u00e8re \u00e9galement des activit\u00e9s li\u00e9es aux drones et aux robots.<br \/>\u00c0 cette exposition, nous pr\u00e9sentons deux types de bateaux radiocommand\u00e9s\u00a0: l\u2019un pour les lev\u00e9s topographiques et l\u2019autre pour l\u2019inspection.<br \/>Premi\u00e8rement, le bateau radiocommand\u00e9 utilis\u00e9 pour les lev\u00e9s topographiques sert principalement aux lev\u00e9s bathym\u00e9triques, qui permettent de mesurer la profondeur de l&#8217;eau gr\u00e2ce \u00e0 un sonar.<br \/>Le plus grand bateau jaune radiocommand\u00e9 peut \u00eatre \u00e9quip\u00e9 d&#8217;un sonar multifaisceaux, capable d&#8217;acqu\u00e9rir des donn\u00e9es 3D, et ce bateau peut \u00e9galement \u00eatre \u00e9quip\u00e9 soit d&#8217;un sonar multifaisceaux, soit d&#8217;un sonar unique.<br \/>Nous serions ravis de commencer par une consultation.<\/div>\n<\/details>\n<h2>Contactez l&#8217;entreprise<\/h2>\n<div class=\"company-profile-section\">\n<div class=\"company-shot\">\n<div class=\"browser-shot alignnone\"><a href=\"https:\/\/www.furusan.co.jp\/\" target=\"_blank\"><img fetchpriority=\"high\" decoding=\"async\"src=\"https:\/\/s0.wp.com\/mshots\/v1\/https%3A%2F%2Fwww.furusan.co.jp%2F?w=600&#038;h=450\"alt=\"Site officiel de Furukawa Sangyo Kaisha, Ltd.\"width=\"600\"height=\"450\"class=\"alignnone\"><\/a><\/div>\n<\/div>\n<div class=\"company-info\">\n<h3 class=\"company-name\">Furukawa Sangyo Kaisha, Ltd.<\/h3>\n<ul class=\"company-meta\">\n<li><span class=\"label\">Quartier g\u00e9n\u00e9ral<\/span> <span class=\"value\">B\u00e2timent Shimbashi Tokyu, 4-21-3 Shimbashi, Minato-ku, Tokyo, Japon<\/span><\/li>\n<li><span class=\"label\">\u00c9tabli<\/span> <span class=\"value\">F\u00e9vrier 1947<\/span><\/li>\n<li><span class=\"label\">Employ\u00e9s<\/span> <span class=\"value\">Non divulgu\u00e9 publiquement<\/span><\/li>\n<li><span class=\"label\">Site officiel<\/span> <span class=\"value\"><a href=\"https:\/\/www.furusan.co.jp\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.furusan.co.jp\/<\/a><\/span><\/li>\n<li><span class=\"label\">Secteurs d&#8217;activit\u00e9<\/span> <span class=\"value\">Solutions techniques de trading, de drones et de robots, d&#8217;\u00e9quipements topographiques, d&#8217;assistance \u00e0 l&#8217;inspection des infrastructures et de syst\u00e8mes topographiques sans pilote<\/span><\/li>\n<li><span class=\"label\">Principaux produits et services<\/span> <span class=\"value\">Bateaux de lev\u00e9s radiocommand\u00e9s, bateaux d&#8217;inspection radiocommand\u00e9s, \u00e9quipements li\u00e9s aux drones, solutions robotiques, syst\u00e8mes de lev\u00e9s sonar et \u00e9quipements de lev\u00e9s hydrographiques sans pilote<\/span><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pour les travaux d&#8217;arpentage et d&#8217;inspection des rivi\u00e8res, des ports, des barrages et autres plans d&#8217;eau, les op\u00e9rateurs doivent collecter efficacement les donn\u00e9es de profondeur et de terrain tout en r\u00e9duisant la n\u00e9cessit\u00e9 pour les travailleurs de p\u00e9\u2026<\/p>\n","protected":false},"author":1,"featured_media":58384,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[787],"tags":[595,542,518,26,27,529,604,31,599,77,38,33,567,36,557,552,634,505,506,37],"class_list":["post-58382","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-cspi-expo-2026-japan","tag-transportation-logistics-packaging-1","tag-machinery-industrial-technology-7","tag-building-construction-1","tag-building-construction","tag-environment","tag-building-construction-3","tag-machinery-industrial-technology-5","tag-information-telecommunication","tag-innovation-startups-1","tag-innovation-startups","tag-japan","tag-machinery-industrial-technology","tag-machinery-industrial-technology-4","tag-services","tag-environment-1","tag-services-3","tag-services-9","tag-machinery-industrial-technology-9","tag-information-telecommunication-1","tag-transportation-logistics-packaging","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Services de drones d&#039;inspection et de lev\u00e9s topographiques - FURUKAWA SANGYO KAISHA, LTD. [8th International Construction &amp; Survey Productivity Improvement EXPO(CSPI2026)] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/french.worldtradeshow.tv\/video\/cspi-expo-2026-japan\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Services de drones d&#039;inspection et de lev\u00e9s topographiques - FURUKAWA SANGYO KAISHA, LTD. [8th International Construction &amp; Survey Productivity Improvement EXPO(CSPI2026)] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"Pour les travaux d&#039;arpentage et d&#039;inspection des rivi\u00e8res, des ports, des barrages et autres plans d&#039;eau, les op\u00e9rateurs doivent collecter efficacement les donn\u00e9es de profondeur et de terrain tout en r\u00e9duisant la n\u00e9cessit\u00e9 pour les travailleurs de p\u00e9\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/french.worldtradeshow.tv\/video\/cspi-expo-2026-japan\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-29T04:18:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-30T05:36:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/06\/maxresdefault-40.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/french.worldtradeshow.tv\\\/video\\\/cspi-expo-2026-japan\\\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/french.worldtradeshow.tv\\\/video\\\/cspi-expo-2026-japan\\\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"Services de drones d'inspection et de lev\u00e9s topographiques - FURUKAWA SANGYO KAISHA, LTD. [8th International Construction &#038; Survey Productivity Improvement EXPO(CSPI2026)]\",\"datePublished\":\"2026-06-29T04:18:16+00:00\",\"dateModified\":\"2026-06-30T05:36:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/french.worldtradeshow.tv\\\/video\\\/cspi-expo-2026-japan\\\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/\"},\"wordCount\":694,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/french.worldtradeshow.tv\\\/video\\\/cspi-expo-2026-japan\\\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/maxresdefault-40.jpg\",\"keywords\":[\"Automobiles (y compris pi\u00e8ces\\\/machines)\",\"Autres machines et \u00e9quipements industriels\",\"B\u00e2timent et construction \\\/ Immobilier\",\"Construction de b\u00e2timents\",\"Environnement\",\"\u00c9quipements pour \u00c9tablissement Public \\\/ Am\u00e9nagement Urbain\",\"Essais\\\/Mesure et analyse\\\/M\u00e9canique de pr\u00e9cision\",\"Information \\\/ T\u00e9l\u00e9communication\",\"Innovation \\\/ Start-up\",\"Innovation \\\/ Startups\",\"Japon\",\"Machines \\\/ Technologie industrielle\",\"Manutention \\\/ Pneumatique\",\"Prestations de service\",\"Protection de l'environnement \\\/ \u00c9limination des d\u00e9chets \\\/ Recyclage\",\"Publicit\u00e9\\\/Marketing\\\/Administration des affaires\",\"S\u00e9curit\u00e9 et sant\u00e9 au travail \\\/ Gestion du travail\",\"Technologie avanc\u00e9e \\\/ Mat\u00e9riaux \\\/ Composites \\\/ R&amp;D\",\"T\u00e9l\u00e9communication \\\/ Informatique \\\/ Informatique\",\"Transport \\\/ Logistique \\\/ Emballage\"],\"articleSection\":[\"8th International Construction &amp; Survey Productivity Improvement EXPO(CSPI2026)\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/french.worldtradeshow.tv\\\/video\\\/cspi-expo-2026-japan\\\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/french.worldtradeshow.tv\\\/video\\\/cspi-expo-2026-japan\\\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/\",\"url\":\"https:\\\/\\\/french.worldtradeshow.tv\\\/video\\\/cspi-expo-2026-japan\\\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/\",\"name\":\"Services de drones d'inspection et de lev\u00e9s topographiques - FURUKAWA SANGYO KAISHA, LTD. [8th International Construction & Survey Productivity Improvement EXPO(CSPI2026)] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/french.worldtradeshow.tv\\\/video\\\/cspi-expo-2026-japan\\\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/french.worldtradeshow.tv\\\/video\\\/cspi-expo-2026-japan\\\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/maxresdefault-40.jpg\",\"datePublished\":\"2026-06-29T04:18:16+00:00\",\"dateModified\":\"2026-06-30T05:36:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/french.worldtradeshow.tv\\\/video\\\/cspi-expo-2026-japan\\\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/french.worldtradeshow.tv\\\/video\\\/cspi-expo-2026-japan\\\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/french.worldtradeshow.tv\\\/video\\\/cspi-expo-2026-japan\\\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/maxresdefault-40.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/maxresdefault-40.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/french.worldtradeshow.tv\\\/video\\\/cspi-expo-2026-japan\\\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services de drones d'inspection et de lev\u00e9s topographiques - FURUKAWA SANGYO KAISHA, LTD. [8th International Construction &#038; Survey Productivity Improvement EXPO(CSPI2026)]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/9r9aNYnlAtc\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"58\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Services de drones d'inspection et de lev\u00e9s topographiques - FURUKAWA SANGYO KAISHA, LTD. [8th International Construction & Survey Productivity Improvement EXPO(CSPI2026)] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/french.worldtradeshow.tv\/video\/cspi-expo-2026-japan\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\/","og_locale":"fr_FR","og_type":"article","og_title":"Services de drones d'inspection et de lev\u00e9s topographiques - FURUKAWA SANGYO KAISHA, LTD. [8th International Construction & Survey Productivity Improvement EXPO(CSPI2026)] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"Pour les travaux d'arpentage et d'inspection des rivi\u00e8res, des ports, des barrages et autres plans d'eau, les op\u00e9rateurs doivent collecter efficacement les donn\u00e9es de profondeur et de terrain tout en r\u00e9duisant la n\u00e9cessit\u00e9 pour les travailleurs de p\u00e9\u2026","og_url":"https:\/\/french.worldtradeshow.tv\/video\/cspi-expo-2026-japan\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2026-06-29T04:18:16+00:00","article_modified_time":"2026-06-30T05:36:46+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/06\/maxresdefault-40.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/french.worldtradeshow.tv\/video\/cspi-expo-2026-japan\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\/#article","isPartOf":{"@id":"https:\/\/french.worldtradeshow.tv\/video\/cspi-expo-2026-japan\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"Services de drones d'inspection et de lev\u00e9s topographiques - FURUKAWA SANGYO KAISHA, LTD. [8th International Construction &#038; Survey Productivity Improvement EXPO(CSPI2026)]","datePublished":"2026-06-29T04:18:16+00:00","dateModified":"2026-06-30T05:36:46+00:00","mainEntityOfPage":{"@id":"https:\/\/french.worldtradeshow.tv\/video\/cspi-expo-2026-japan\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\/"},"wordCount":694,"commentCount":0,"image":{"@id":"https:\/\/french.worldtradeshow.tv\/video\/cspi-expo-2026-japan\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/06\/maxresdefault-40.jpg","keywords":["Automobiles (y compris pi\u00e8ces\/machines)","Autres machines et \u00e9quipements industriels","B\u00e2timent et construction \/ Immobilier","Construction de b\u00e2timents","Environnement","\u00c9quipements pour \u00c9tablissement Public \/ Am\u00e9nagement Urbain","Essais\/Mesure et analyse\/M\u00e9canique de pr\u00e9cision","Information \/ T\u00e9l\u00e9communication","Innovation \/ Start-up","Innovation \/ Startups","Japon","Machines \/ Technologie industrielle","Manutention \/ Pneumatique","Prestations de service","Protection de l'environnement \/ \u00c9limination des d\u00e9chets \/ Recyclage","Publicit\u00e9\/Marketing\/Administration des affaires","S\u00e9curit\u00e9 et sant\u00e9 au travail \/ Gestion du travail","Technologie avanc\u00e9e \/ Mat\u00e9riaux \/ Composites \/ R&amp;D","T\u00e9l\u00e9communication \/ Informatique \/ Informatique","Transport \/ Logistique \/ Emballage"],"articleSection":["8th International Construction &amp; Survey Productivity Improvement EXPO(CSPI2026)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/french.worldtradeshow.tv\/video\/cspi-expo-2026-japan\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/french.worldtradeshow.tv\/video\/cspi-expo-2026-japan\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\/","url":"https:\/\/french.worldtradeshow.tv\/video\/cspi-expo-2026-japan\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\/","name":"Services de drones d'inspection et de lev\u00e9s topographiques - FURUKAWA SANGYO KAISHA, LTD. [8th International Construction & Survey Productivity Improvement EXPO(CSPI2026)] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/french.worldtradeshow.tv\/video\/cspi-expo-2026-japan\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\/#primaryimage"},"image":{"@id":"https:\/\/french.worldtradeshow.tv\/video\/cspi-expo-2026-japan\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/06\/maxresdefault-40.jpg","datePublished":"2026-06-29T04:18:16+00:00","dateModified":"2026-06-30T05:36:46+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/french.worldtradeshow.tv\/video\/cspi-expo-2026-japan\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/french.worldtradeshow.tv\/video\/cspi-expo-2026-japan\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/french.worldtradeshow.tv\/video\/cspi-expo-2026-japan\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/06\/maxresdefault-40.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2026\/06\/maxresdefault-40.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/french.worldtradeshow.tv\/video\/cspi-expo-2026-japan\/inspection-and-surveying-drone-services-furukawa-sangyo-kaisha-ltd-8th-international-construction-survey-productivity-improvement-expocspi2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"Services de drones d'inspection et de lev\u00e9s topographiques - FURUKAWA SANGYO KAISHA, LTD. [8th International Construction &#038; Survey Productivity Improvement EXPO(CSPI2026)]"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/9r9aNYnlAtc","og_video_type":"text\/html","og_video_duration":"58","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=9r9aNYnlAtc","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/58382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=58382"}],"version-history":[{"count":1,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/58382\/revisions"}],"predecessor-version":[{"id":58383,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/58382\/revisions\/58383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/58384"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=58382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=58382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=58382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}