{"id":56540,"date":"2025-11-21T04:44:15","date_gmt":"2025-11-21T04:44:15","guid":{"rendered":"https:\/\/www.worldtradeshow.tv\/french\/?p=56540"},"modified":"2025-11-21T04:44:15","modified_gmt":"2025-11-21T04:44:15","slug":"katz-eye_air-mount-technic","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/asiandefense_2025_11\/katz-eye_air-mount-technic\/","title":{"rendered":"\u0152il de Katz - Air Mount Technic [D&#038;S - Defense &#038; Security 2025]"},"content":{"rendered":"<blockquote class=\"wp-block-quote\"><p>Lors du salon Defense &#038; Security 2025, la soci\u00e9t\u00e9 tha\u00eflandaise AMT Air Mount Technic Co., Ltd a fait forte impression en pr\u00e9sentant sa cam\u00e9ra thermique de pointe. Ce dispositif sophistiqu\u00e9, v\u00e9ritable &#8220;\u0153il de Katz&#8221; technologique, est con\u00e7u pour d\u00e9tecter les rayonnements et identifier la pr\u00e9sence d&#8217;\u00e9l\u00e9ments ext\u00e9rieurs dans un rayon de 5 \u00e0 10 kilom\u00e8tres. Son champ d&#8217;application potentiel est vaste, allant de la d\u00e9tection de troupes ennemies dissimul\u00e9es \u00e0 la localisation de personnes cach\u00e9es dans des environnements complexes, \u00e9voquant la capacit\u00e9 d&#8217;un &#8220;troisi\u00e8me \u0153il&#8221; pour les forces de s\u00e9curit\u00e9.<br \/>Outre cette innovation, AMT Air Mount Technic a \u00e9galement mis en avant son expertise dans la fabrication de pi\u00e8ces a\u00e9ronautiques essentielles. Des freins aux ailes, en passant par les empennages, l&#8217;entreprise se positionne comme un fournisseur polyvalent pour l&#8217;industrie a\u00e9rospatiale.<br \/>La pr\u00e9sence de AMT Air Mount Technic \u00e0 Defense &#038; Security 2025 illustre la mont\u00e9e en puissance des entreprises tha\u00eflandaises dans le secteur de la d\u00e9fense et de la s\u00e9curit\u00e9. L&#8217;entreprise invite les professionnels \u00e0 la contacter pour d\u00e9couvrir l&#8217;\u00e9tendue de son offre et promet un soutien technique de premier ordre. Cette initiative s&#8217;inscrit dans une tendance globale \u00e0 l&#8217;innovation technologique au service de la s\u00e9curit\u00e9, un enjeu majeur \u00e0 l&#8217;\u00e9chelle internationale.<br \/><cite>Generated by <a href=\"https:\/\/gemini.google.com\/\">Gemini<\/a><\/cite><\/p><\/blockquote>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lors du salon Defense &#038; Security 2025, la soci\u00e9t\u00e9 tha\u00eflandaise AMT Air Mount Technic Co., Ltd a fait forte impression en pr\u00e9sentant sa cam\u00e9ra thermique de pointe. Ce dispositif sophistiqu\u00e9, v\u00e9ritable &#8220;\u0153il de Katz&#8221; technologique, est con\u00e7u pour d\u00e9tecter les rayonnements et identifier la pr\u00e9sence d&#8217;\u00e9l\u00e9ments ext\u00e9rieurs dans un rayon de 5 \u00e0 10 kilom\u00e8tres. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":56541,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[736],"tags":[647,595,626,31,645,548,34,506,65,37,42],"class_list":["post-56540","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-asiandefense_2025_11","tag-transportation-logistics-packaging-6","tag-transportation-logistics-packaging-1","tag-medical-care-health-1","tag-information-telecommunication","tag-transportation-logistics-packaging-4","tag-living-12","tag-medical-care-health","tag-information-telecommunication-1","tag-thailand","tag-transportation-logistics-packaging","tag-living","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0152il de Katz - Air Mount Technic [D&amp;S - Defense &amp; Security 2025] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/asiandefense_2025_11\/katz-eye_air-mount-technic\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0152il de Katz - Air Mount Technic [D&amp;S - Defense &amp; Security 2025] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"Lors du salon Defense &#038; Security 2025, la soci\u00e9t\u00e9 tha\u00eflandaise AMT Air Mount Technic Co., Ltd a fait forte impression en pr\u00e9sentant sa cam\u00e9ra thermique de pointe. Ce dispositif sophistiqu\u00e9, v\u00e9ritable &#8220;\u0153il de Katz&#8221; technologique, est con\u00e7u pour d\u00e9tecter les rayonnements et identifier la pr\u00e9sence d&#8217;\u00e9l\u00e9ments ext\u00e9rieurs dans un rayon de 5 \u00e0 10 kilom\u00e8tres. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/asiandefense_2025_11\/katz-eye_air-mount-technic\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-21T04:44:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/11\/maxresdefault-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/asiandefense_2025_11\\\/katz-eye_air-mount-technic\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/asiandefense_2025_11\\\/katz-eye_air-mount-technic\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"\u0152il de Katz - Air Mount Technic [D&#038;S - Defense &#038; Security 2025]\",\"datePublished\":\"2025-11-21T04:44:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/asiandefense_2025_11\\\/katz-eye_air-mount-technic\\\/\"},\"wordCount\":241,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/asiandefense_2025_11\\\/katz-eye_air-mount-technic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/maxresdefault-1.jpg\",\"keywords\":[\"A\u00e9rospatiale et aviation \\\/ \u00c9quipement a\u00e9roportuaire\",\"Automobiles (y compris pi\u00e8ces\\\/machines)\",\"\u00c9quipements\\\/fournitures m\u00e9dicales et hospitali\u00e8res\",\"Information \\\/ T\u00e9l\u00e9communication\",\"Marine \\\/ Construction navale \\\/ Navigation \\\/ \u00c9quipement portuaire\",\"S\u00e9curit\u00e9 \\\/ S\u00fbret\u00e9 \\\/ Protection Incendie \\\/ Police \\\/ D\u00e9fense\",\"Soins m\u00e9dicaux \\\/ Sant\u00e9\",\"T\u00e9l\u00e9communication \\\/ Informatique \\\/ Informatique\",\"Tha\u00eflande\",\"Transport \\\/ Logistique \\\/ Emballage\",\"Vivant\"],\"articleSection\":[\"D&amp;S - Defense &amp; Security 2025\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/asiandefense_2025_11\\\/katz-eye_air-mount-technic\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/asiandefense_2025_11\\\/katz-eye_air-mount-technic\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/asiandefense_2025_11\\\/katz-eye_air-mount-technic\\\/\",\"name\":\"\u0152il de Katz - Air Mount Technic [D&S - Defense & Security 2025] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/asiandefense_2025_11\\\/katz-eye_air-mount-technic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/asiandefense_2025_11\\\/katz-eye_air-mount-technic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/maxresdefault-1.jpg\",\"datePublished\":\"2025-11-21T04:44:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/asiandefense_2025_11\\\/katz-eye_air-mount-technic\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/asiandefense_2025_11\\\/katz-eye_air-mount-technic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/asiandefense_2025_11\\\/katz-eye_air-mount-technic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/maxresdefault-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/maxresdefault-1.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/asiandefense_2025_11\\\/katz-eye_air-mount-technic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0152il de Katz - Air Mount Technic [D&#038;S - Defense &#038; Security 2025]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/LtfjaViFzkU\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"90\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0152il de Katz - Air Mount Technic [D&S - Defense & Security 2025] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/asiandefense_2025_11\/katz-eye_air-mount-technic\/","og_locale":"fr_FR","og_type":"article","og_title":"\u0152il de Katz - Air Mount Technic [D&S - Defense & Security 2025] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"Lors du salon Defense &#038; Security 2025, la soci\u00e9t\u00e9 tha\u00eflandaise AMT Air Mount Technic Co., Ltd a fait forte impression en pr\u00e9sentant sa cam\u00e9ra thermique de pointe. Ce dispositif sophistiqu\u00e9, v\u00e9ritable &#8220;\u0153il de Katz&#8221; technologique, est con\u00e7u pour d\u00e9tecter les rayonnements et identifier la pr\u00e9sence d&#8217;\u00e9l\u00e9ments ext\u00e9rieurs dans un rayon de 5 \u00e0 10 kilom\u00e8tres. [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/asiandefense_2025_11\/katz-eye_air-mount-technic\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2025-11-21T04:44:15+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/11\/maxresdefault-1.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/asiandefense_2025_11\/katz-eye_air-mount-technic\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/asiandefense_2025_11\/katz-eye_air-mount-technic\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"\u0152il de Katz - Air Mount Technic [D&#038;S - Defense &#038; Security 2025]","datePublished":"2025-11-21T04:44:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/asiandefense_2025_11\/katz-eye_air-mount-technic\/"},"wordCount":241,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/asiandefense_2025_11\/katz-eye_air-mount-technic\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/11\/maxresdefault-1.jpg","keywords":["A\u00e9rospatiale et aviation \/ \u00c9quipement a\u00e9roportuaire","Automobiles (y compris pi\u00e8ces\/machines)","\u00c9quipements\/fournitures m\u00e9dicales et hospitali\u00e8res","Information \/ T\u00e9l\u00e9communication","Marine \/ Construction navale \/ Navigation \/ \u00c9quipement portuaire","S\u00e9curit\u00e9 \/ S\u00fbret\u00e9 \/ Protection Incendie \/ Police \/ D\u00e9fense","Soins m\u00e9dicaux \/ Sant\u00e9","T\u00e9l\u00e9communication \/ Informatique \/ Informatique","Tha\u00eflande","Transport \/ Logistique \/ Emballage","Vivant"],"articleSection":["D&amp;S - Defense &amp; Security 2025"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/asiandefense_2025_11\/katz-eye_air-mount-technic\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/asiandefense_2025_11\/katz-eye_air-mount-technic\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/asiandefense_2025_11\/katz-eye_air-mount-technic\/","name":"\u0152il de Katz - Air Mount Technic [D&S - Defense & Security 2025] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/asiandefense_2025_11\/katz-eye_air-mount-technic\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/asiandefense_2025_11\/katz-eye_air-mount-technic\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/11\/maxresdefault-1.jpg","datePublished":"2025-11-21T04:44:15+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/asiandefense_2025_11\/katz-eye_air-mount-technic\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/asiandefense_2025_11\/katz-eye_air-mount-technic\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/asiandefense_2025_11\/katz-eye_air-mount-technic\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/11\/maxresdefault-1.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/11\/maxresdefault-1.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/asiandefense_2025_11\/katz-eye_air-mount-technic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"\u0152il de Katz - Air Mount Technic [D&#038;S - Defense &#038; Security 2025]"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/LtfjaViFzkU","og_video_type":"text\/html","og_video_duration":"90","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=LtfjaViFzkU","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/56540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=56540"}],"version-history":[{"count":1,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/56540\/revisions"}],"predecessor-version":[{"id":56568,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/56540\/revisions\/56568"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/56541"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=56540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=56540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=56540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}