{"id":56222,"date":"2025-10-03T06:17:58","date_gmt":"2025-10-03T06:17:58","guid":{"rendered":"https:\/\/www.worldtradeshow.tv\/french\/?p=56222"},"modified":"2025-10-03T06:17:58","modified_gmt":"2025-10-03T06:17:58","slug":"cssd-equipment_moveox-technologies","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall_2025_09\/cssd-equipment_moveox-technologies\/","title":{"rendered":"\u00c9quipement CSSD - MOVEOX TECHNOLOGIES [Medicall 2025 - Salon des \u00e9quipements m\u00e9dicaux (New Delhi)]"},"content":{"rendered":"<blockquote class=\"wp-block-quote\"><p>MOVEOX Technologies mise sur l&#8217;innovation pour r\u00e9volutionner la st\u00e9rilisation en milieu hospitalier. Pr\u00e9sente au salon Medicall 2025 \u00e0 New Delhi, l&#8217;entreprise a d\u00e9voil\u00e9 son autoclave nouvelle g\u00e9n\u00e9ration, un \u00e9quipement CSSD (Central Sterile Supply Department) con\u00e7u pour garantir une s\u00e9curit\u00e9 et une efficacit\u00e9 optimales.<br \/>Selon Pratak Mahel, propri\u00e9taire de MOVEOX Technologies, l&#8217;autoclave se distingue par sa construction robuste en acier 316 triple paroi, gage de durabilit\u00e9 et de conformit\u00e9 aux standards de qualit\u00e9 les plus exigeants.  La machine est enti\u00e8rement automatis\u00e9e gr\u00e2ce \u00e0 un automate programmable (PLC). Faisant \u00e9cho \u00e0 la pens\u00e9e de Blaise Pascal, l&#8217;automate se veut ici un palliatif \u00e0 la faillibilit\u00e9 humaine. La v\u00e9ritable prouesse r\u00e9side cependant dans un syst\u00e8me de s\u00e9curit\u00e9 in\u00e9dit. En cas de d\u00e9faillance de l&#8217;automate, un syst\u00e8me manuel prend automatiquement le relais, \u00e9liminant ainsi tout risque d&#8217;interruption du processus de st\u00e9rilisation. L&#8217;int\u00e9gration d&#8217;un syst\u00e8me d&#8217;\u00e9jection renforce encore la fiabilit\u00e9 de l&#8217;appareil.<br \/>Avec des dimensions de 2x2x4 pieds, l&#8217;autoclave se positionne comme une solution id\u00e9ale pour les \u00e9tablissements de sant\u00e9 soucieux d&#8217;optimiser leur gestion du mat\u00e9riel st\u00e9rilis\u00e9, tout en minimisant les risques li\u00e9s \u00e0 la contamination. L&#8217;entreprise esp\u00e8re ainsi s&#8217;imposer comme un acteur cl\u00e9 dans le domaine de la st\u00e9rilisation m\u00e9dicale.<br \/><cite>Generated by <a href=\"https:\/\/gemini.google.com\/\">Gemini<\/a><\/cite><\/p><\/blockquote>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MOVEOX Technologies mise sur l&#8217;innovation pour r\u00e9volutionner la st\u00e9rilisation en milieu hospitalier. Pr\u00e9sente au salon Medicall 2025 \u00e0 New Delhi, l&#8217;entreprise a d\u00e9voil\u00e9 son autoclave nouvelle g\u00e9n\u00e9ration, un \u00e9quipement CSSD (Central Sterile Supply Department) con\u00e7u pour garantir une s\u00e9curit\u00e9 et une efficacit\u00e9 optimales.Selon Pratak Mahel, propri\u00e9taire de MOVEOX Technologies, l&#8217;autoclave se distingue par sa construction [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":56223,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[729],"tags":[626,154,588,34],"class_list":["post-56222","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-medicall_2025_09","tag-medical-care-health-1","tag-india","tag-medical-care-health-5","tag-medical-care-health","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9quipement CSSD - MOVEOX TECHNOLOGIES [Medicall 2025 - Salon des \u00e9quipements m\u00e9dicaux (New Delhi)] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall_2025_09\/cssd-equipment_moveox-technologies\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9quipement CSSD - MOVEOX TECHNOLOGIES [Medicall 2025 - Salon des \u00e9quipements m\u00e9dicaux (New Delhi)] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"MOVEOX Technologies mise sur l&#8217;innovation pour r\u00e9volutionner la st\u00e9rilisation en milieu hospitalier. Pr\u00e9sente au salon Medicall 2025 \u00e0 New Delhi, l&#8217;entreprise a d\u00e9voil\u00e9 son autoclave nouvelle g\u00e9n\u00e9ration, un \u00e9quipement CSSD (Central Sterile Supply Department) con\u00e7u pour garantir une s\u00e9curit\u00e9 et une efficacit\u00e9 optimales.Selon Pratak Mahel, propri\u00e9taire de MOVEOX Technologies, l&#8217;autoclave se distingue par sa construction [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall_2025_09\/cssd-equipment_moveox-technologies\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-03T06:17:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/10\/maxresdefault-12.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall_2025_09\\\/cssd-equipment_moveox-technologies\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall_2025_09\\\/cssd-equipment_moveox-technologies\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"\u00c9quipement CSSD - MOVEOX TECHNOLOGIES [Medicall 2025 - Salon des \u00e9quipements m\u00e9dicaux (New Delhi)]\",\"datePublished\":\"2025-10-03T06:17:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall_2025_09\\\/cssd-equipment_moveox-technologies\\\/\"},\"wordCount\":251,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall_2025_09\\\/cssd-equipment_moveox-technologies\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/maxresdefault-12.jpg\",\"keywords\":[\"\u00c9quipements\\\/fournitures m\u00e9dicales et hospitali\u00e8res\",\"Inde\",\"Soins de sant\u00e9 (\u00e9quipements\\\/produits et services)\",\"Soins m\u00e9dicaux \\\/ Sant\u00e9\"],\"articleSection\":[\"Medicall 2025 - Salon des \u00e9quipements m\u00e9dicaux (New Delhi)\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall_2025_09\\\/cssd-equipment_moveox-technologies\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall_2025_09\\\/cssd-equipment_moveox-technologies\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall_2025_09\\\/cssd-equipment_moveox-technologies\\\/\",\"name\":\"\u00c9quipement CSSD - MOVEOX TECHNOLOGIES [Medicall 2025 - Salon des \u00e9quipements m\u00e9dicaux (New Delhi)] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall_2025_09\\\/cssd-equipment_moveox-technologies\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall_2025_09\\\/cssd-equipment_moveox-technologies\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/maxresdefault-12.jpg\",\"datePublished\":\"2025-10-03T06:17:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall_2025_09\\\/cssd-equipment_moveox-technologies\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall_2025_09\\\/cssd-equipment_moveox-technologies\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall_2025_09\\\/cssd-equipment_moveox-technologies\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/maxresdefault-12.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/maxresdefault-12.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall_2025_09\\\/cssd-equipment_moveox-technologies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9quipement CSSD - MOVEOX TECHNOLOGIES [Medicall 2025 - Salon des \u00e9quipements m\u00e9dicaux (New Delhi)]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/j3AZUvhh3Bs\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"59\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9quipement CSSD - MOVEOX TECHNOLOGIES [Medicall 2025 - Salon des \u00e9quipements m\u00e9dicaux (New Delhi)] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall_2025_09\/cssd-equipment_moveox-technologies\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9quipement CSSD - MOVEOX TECHNOLOGIES [Medicall 2025 - Salon des \u00e9quipements m\u00e9dicaux (New Delhi)] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"MOVEOX Technologies mise sur l&#8217;innovation pour r\u00e9volutionner la st\u00e9rilisation en milieu hospitalier. Pr\u00e9sente au salon Medicall 2025 \u00e0 New Delhi, l&#8217;entreprise a d\u00e9voil\u00e9 son autoclave nouvelle g\u00e9n\u00e9ration, un \u00e9quipement CSSD (Central Sterile Supply Department) con\u00e7u pour garantir une s\u00e9curit\u00e9 et une efficacit\u00e9 optimales.Selon Pratak Mahel, propri\u00e9taire de MOVEOX Technologies, l&#8217;autoclave se distingue par sa construction [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall_2025_09\/cssd-equipment_moveox-technologies\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2025-10-03T06:17:58+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/10\/maxresdefault-12.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall_2025_09\/cssd-equipment_moveox-technologies\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall_2025_09\/cssd-equipment_moveox-technologies\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"\u00c9quipement CSSD - MOVEOX TECHNOLOGIES [Medicall 2025 - Salon des \u00e9quipements m\u00e9dicaux (New Delhi)]","datePublished":"2025-10-03T06:17:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall_2025_09\/cssd-equipment_moveox-technologies\/"},"wordCount":251,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall_2025_09\/cssd-equipment_moveox-technologies\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/10\/maxresdefault-12.jpg","keywords":["\u00c9quipements\/fournitures m\u00e9dicales et hospitali\u00e8res","Inde","Soins de sant\u00e9 (\u00e9quipements\/produits et services)","Soins m\u00e9dicaux \/ Sant\u00e9"],"articleSection":["Medicall 2025 - Salon des \u00e9quipements m\u00e9dicaux (New Delhi)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/medicall_2025_09\/cssd-equipment_moveox-technologies\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall_2025_09\/cssd-equipment_moveox-technologies\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall_2025_09\/cssd-equipment_moveox-technologies\/","name":"\u00c9quipement CSSD - MOVEOX TECHNOLOGIES [Medicall 2025 - Salon des \u00e9quipements m\u00e9dicaux (New Delhi)] \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall_2025_09\/cssd-equipment_moveox-technologies\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall_2025_09\/cssd-equipment_moveox-technologies\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/10\/maxresdefault-12.jpg","datePublished":"2025-10-03T06:17:58+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall_2025_09\/cssd-equipment_moveox-technologies\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/medicall_2025_09\/cssd-equipment_moveox-technologies\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall_2025_09\/cssd-equipment_moveox-technologies\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/10\/maxresdefault-12.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/10\/maxresdefault-12.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall_2025_09\/cssd-equipment_moveox-technologies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"\u00c9quipement CSSD - MOVEOX TECHNOLOGIES [Medicall 2025 - Salon des \u00e9quipements m\u00e9dicaux (New Delhi)]"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/j3AZUvhh3Bs","og_video_type":"text\/html","og_video_duration":"59","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=j3AZUvhh3Bs","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/56222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=56222"}],"version-history":[{"count":1,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/56222\/revisions"}],"predecessor-version":[{"id":56246,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/56222\/revisions\/56246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/56223"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=56222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=56222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=56222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}