{"id":55790,"date":"2025-07-29T02:57:15","date_gmt":"2025-07-29T02:57:15","guid":{"rendered":"https:\/\/www.worldtradeshow.tv\/french\/?p=55790"},"modified":"2025-07-29T02:57:15","modified_gmt":"2025-07-29T02:57:15","slug":"eclipse-ice-cream_eclipse-foods-japan","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes_2025_07\/eclipse-ice-cream_eclipse-foods-japan\/","title":{"rendered":"[13e Salon des Caf\u00e9s de Tokyo 2025] Cr\u00e8me glac\u00e9e Eclipse - Eclipse Foods Japon."},"content":{"rendered":"<blockquote class=\"wp-block-quote\"><p>**Eclipse Foods s\u00e9duit le Tokyo Cafe Show avec ses glaces alternatives**<br \/>Eclipse Foods Japan, filiale d&#8217;une startup californienne, a pr\u00e9sent\u00e9 au Tokyo Cafe Show ses glaces alternatives. Sans produits laitiers, les saveurs cookie butter, mangue passion et fraise attirent l&#8217;attention. L&#8217;entreprise met en avant l&#8217;absence de cholest\u00e9rol et de graisses trans, ainsi qu&#8217;un impact environnemental r\u00e9duit. Une alternative gourmande pour tous, y compris les intol\u00e9rants au lactose.<br \/><cite>Generated by <a href=\"https:\/\/gemini.google.com\/\">Gemini<\/a><\/cite><\/p><\/blockquote>\n<p><\/p>\n<p>site Internet:<a href=\"https:\/\/eclipsefoods.co.jp\/\" target=\"_blank\" rel=\"noopener\">https:\/\/eclipsefoods.co.jp\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>**Eclipse Foods s\u00e9duit le Tokyo Cafe Show avec ses glaces alternatives**Eclipse Foods Japan, filiale d&#8217;une startup californienne, a pr\u00e9sent\u00e9 au Tokyo Cafe Show ses glaces alternatives. Sans produits laitiers, les saveurs cookie butter, mangue passion et fraise attirent l&#8217;attention. L&#8217;entreprise met en avant l&#8217;absence de cholest\u00e9rol et de graisses trans, ainsi qu&#8217;un impact environnemental r\u00e9duit. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":55791,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[718],"tags":[43,536,519,26,563,562,38,520,36,615,42],"class_list":["post-55790","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-caferes_2025_07","tag-agriculture-forestry-fishery-and-food","tag-agriculture-forestry-fishery-and-food-2","tag-building-construction-2","tag-building-construction","tag-services-7","tag-services-1","tag-japan","tag-living-4","tag-services","tag-services-5","tag-living","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[13e Salon des Caf\u00e9s de Tokyo 2025] Cr\u00e8me glac\u00e9e Eclipse - Eclipse Foods Japon. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes_2025_07\/eclipse-ice-cream_eclipse-foods-japan\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[13e Salon des Caf\u00e9s de Tokyo 2025] Cr\u00e8me glac\u00e9e Eclipse - Eclipse Foods Japon. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"**Eclipse Foods s\u00e9duit le Tokyo Cafe Show avec ses glaces alternatives**Eclipse Foods Japan, filiale d&#8217;une startup californienne, a pr\u00e9sent\u00e9 au Tokyo Cafe Show ses glaces alternatives. Sans produits laitiers, les saveurs cookie butter, mangue passion et fraise attirent l&#8217;attention. L&#8217;entreprise met en avant l&#8217;absence de cholest\u00e9rol et de graisses trans, ainsi qu&#8217;un impact environnemental r\u00e9duit. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes_2025_07\/eclipse-ice-cream_eclipse-foods-japan\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-29T02:57:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/07\/maxresdefault-30.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes_2025_07\\\/eclipse-ice-cream_eclipse-foods-japan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes_2025_07\\\/eclipse-ice-cream_eclipse-foods-japan\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"[13e Salon des Caf\u00e9s de Tokyo 2025] Cr\u00e8me glac\u00e9e Eclipse - Eclipse Foods Japon.\",\"datePublished\":\"2025-07-29T02:57:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes_2025_07\\\/eclipse-ice-cream_eclipse-foods-japan\\\/\"},\"wordCount\":102,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes_2025_07\\\/eclipse-ice-cream_eclipse-foods-japan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/maxresdefault-30.jpg\",\"keywords\":[\"Agriculture \\\/ For\u00eats \\\/ P\u00eache et nourriture\",\"Aliments et boissons \\\/ Transformation des aliments\",\"Assainissement \\\/ Climatisation \\\/ Plomberie \\\/ \u00c9clairage\",\"Construction de b\u00e2timents\",\"Design (y compris design industriel)\",\"H\u00f4tellerie\\\/Restaurant &amp; Restauration\",\"Japon\",\"Meubles et accessoires \\\/ Pi\u00e8ces\",\"Prestations de service\",\"Vente au d\u00e9tail\\\/commerce de gros\\\/distribution\\\/franchise\",\"Vivant\"],\"articleSection\":[\"CAFERES JAPAN 2025\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes_2025_07\\\/eclipse-ice-cream_eclipse-foods-japan\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes_2025_07\\\/eclipse-ice-cream_eclipse-foods-japan\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes_2025_07\\\/eclipse-ice-cream_eclipse-foods-japan\\\/\",\"name\":\"[13e Salon des Caf\u00e9s de Tokyo 2025] Cr\u00e8me glac\u00e9e Eclipse - Eclipse Foods Japon. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes_2025_07\\\/eclipse-ice-cream_eclipse-foods-japan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes_2025_07\\\/eclipse-ice-cream_eclipse-foods-japan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/maxresdefault-30.jpg\",\"datePublished\":\"2025-07-29T02:57:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes_2025_07\\\/eclipse-ice-cream_eclipse-foods-japan\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes_2025_07\\\/eclipse-ice-cream_eclipse-foods-japan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes_2025_07\\\/eclipse-ice-cream_eclipse-foods-japan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/maxresdefault-30.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/maxresdefault-30.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/caferes_2025_07\\\/eclipse-ice-cream_eclipse-foods-japan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[13e Salon des Caf\u00e9s de Tokyo 2025] Cr\u00e8me glac\u00e9e Eclipse - Eclipse Foods Japon.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/hzz7FK-USUc\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"81\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[13e Salon des Caf\u00e9s de Tokyo 2025] Cr\u00e8me glac\u00e9e Eclipse - Eclipse Foods Japon. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes_2025_07\/eclipse-ice-cream_eclipse-foods-japan\/","og_locale":"fr_FR","og_type":"article","og_title":"[13e Salon des Caf\u00e9s de Tokyo 2025] Cr\u00e8me glac\u00e9e Eclipse - Eclipse Foods Japon. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"**Eclipse Foods s\u00e9duit le Tokyo Cafe Show avec ses glaces alternatives**Eclipse Foods Japan, filiale d&#8217;une startup californienne, a pr\u00e9sent\u00e9 au Tokyo Cafe Show ses glaces alternatives. Sans produits laitiers, les saveurs cookie butter, mangue passion et fraise attirent l&#8217;attention. L&#8217;entreprise met en avant l&#8217;absence de cholest\u00e9rol et de graisses trans, ainsi qu&#8217;un impact environnemental r\u00e9duit. [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes_2025_07\/eclipse-ice-cream_eclipse-foods-japan\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2025-07-29T02:57:15+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/07\/maxresdefault-30.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes_2025_07\/eclipse-ice-cream_eclipse-foods-japan\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes_2025_07\/eclipse-ice-cream_eclipse-foods-japan\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"[13e Salon des Caf\u00e9s de Tokyo 2025] Cr\u00e8me glac\u00e9e Eclipse - Eclipse Foods Japon.","datePublished":"2025-07-29T02:57:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes_2025_07\/eclipse-ice-cream_eclipse-foods-japan\/"},"wordCount":102,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes_2025_07\/eclipse-ice-cream_eclipse-foods-japan\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/07\/maxresdefault-30.jpg","keywords":["Agriculture \/ For\u00eats \/ P\u00eache et nourriture","Aliments et boissons \/ Transformation des aliments","Assainissement \/ Climatisation \/ Plomberie \/ \u00c9clairage","Construction de b\u00e2timents","Design (y compris design industriel)","H\u00f4tellerie\/Restaurant &amp; Restauration","Japon","Meubles et accessoires \/ Pi\u00e8ces","Prestations de service","Vente au d\u00e9tail\/commerce de gros\/distribution\/franchise","Vivant"],"articleSection":["CAFERES JAPAN 2025"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/caferes_2025_07\/eclipse-ice-cream_eclipse-foods-japan\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes_2025_07\/eclipse-ice-cream_eclipse-foods-japan\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes_2025_07\/eclipse-ice-cream_eclipse-foods-japan\/","name":"[13e Salon des Caf\u00e9s de Tokyo 2025] Cr\u00e8me glac\u00e9e Eclipse - Eclipse Foods Japon. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes_2025_07\/eclipse-ice-cream_eclipse-foods-japan\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes_2025_07\/eclipse-ice-cream_eclipse-foods-japan\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/07\/maxresdefault-30.jpg","datePublished":"2025-07-29T02:57:15+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes_2025_07\/eclipse-ice-cream_eclipse-foods-japan\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/caferes_2025_07\/eclipse-ice-cream_eclipse-foods-japan\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes_2025_07\/eclipse-ice-cream_eclipse-foods-japan\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/07\/maxresdefault-30.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/07\/maxresdefault-30.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/caferes_2025_07\/eclipse-ice-cream_eclipse-foods-japan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"[13e Salon des Caf\u00e9s de Tokyo 2025] Cr\u00e8me glac\u00e9e Eclipse - Eclipse Foods Japon."}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/hzz7FK-USUc","og_video_type":"text\/html","og_video_duration":"81","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=hzz7FK-USUc","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/55790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=55790"}],"version-history":[{"count":1,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/55790\/revisions"}],"predecessor-version":[{"id":55802,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/55790\/revisions\/55802"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/55791"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=55790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=55790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=55790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}