{"id":55615,"date":"2025-06-23T05:21:44","date_gmt":"2025-06-23T05:21:44","guid":{"rendered":"https:\/\/www.worldtradeshow.tv\/french\/?p=55615"},"modified":"2025-06-23T05:21:44","modified_gmt":"2025-06-23T05:21:44","slug":"self-propelled-screen-595-separator_imagiire-co-ltd","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo_2025_06\/self-propelled-screen-595-separator_imagiire-co-ltd\/","title":{"rendered":"[CSPI-EXPO 2025 - Salon international de l'am\u00e9lioration de la productivit\u00e9 dans la construction et les \u00e9tudes] S\u00e9parateur \u00ab\u00a0Cribleur automoteur 595\u00a0\u00bb - Imagiire Co., Ltd."},"content":{"rendered":"<blockquote class=\"wp-block-quote\"><p>**Imagiire Co. mise sur la s\u00e9paration des sols avec son &#8220;Self-Propelled Screen 595&#8243;**<br \/>Imagiire Co. propose le FINLAY595, un s\u00e9parateur de sols automoteur de 20 tonnes. Cet engin, pr\u00e9sent\u00e9 lors d&#8217;une exposition, permet de trier efficacement les mat\u00e9riaux de construction, r\u00e9duisant les co\u00fbts de d\u00e9chetterie. En s\u00e9parant pierres et sable, il optimise aussi la r\u00e9utilisation des ressources sur les chantiers.<br \/><cite>Generated by <a href=\"https:\/\/gemini.google.com\/\">Gemini<\/a><\/cite><\/p><\/blockquote>\n<p><\/p>\n<p>site Internet:<a href=\"https:\/\/www.imagiire.co.jp\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.imagiire.co.jp\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>**Imagiire Co. mise sur la s\u00e9paration des sols avec son &#8220;Self-Propelled Screen 595&#8243;**Imagiire Co. propose le FINLAY595, un s\u00e9parateur de sols automoteur de 20 tonnes. Cet engin, pr\u00e9sent\u00e9 lors d&#8217;une exposition, permet de trier efficacement les mat\u00e9riaux de construction, r\u00e9duisant les co\u00fbts de d\u00e9chetterie. En s\u00e9parant pierres et sable, il optimise aussi la r\u00e9utilisation des [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":55616,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[713],"tags":[519,518,26,556,27,38,33,557,505],"class_list":["post-55615","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-cspi-expo_2025_06","tag-building-construction-2","tag-building-construction-1","tag-building-construction","tag-building-construction-4","tag-environment","tag-japan","tag-machinery-industrial-technology","tag-environment-1","tag-machinery-industrial-technology-9","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[CSPI-EXPO 2025 - Salon international de l&#039;am\u00e9lioration de la productivit\u00e9 dans la construction et les \u00e9tudes] S\u00e9parateur \u00ab\u00a0Cribleur automoteur 595\u00a0\u00bb - Imagiire Co., Ltd. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo_2025_06\/self-propelled-screen-595-separator_imagiire-co-ltd\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[CSPI-EXPO 2025 - Salon international de l&#039;am\u00e9lioration de la productivit\u00e9 dans la construction et les \u00e9tudes] S\u00e9parateur \u00ab\u00a0Cribleur automoteur 595\u00a0\u00bb - Imagiire Co., Ltd. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"**Imagiire Co. mise sur la s\u00e9paration des sols avec son &#8220;Self-Propelled Screen 595&#8243;**Imagiire Co. propose le FINLAY595, un s\u00e9parateur de sols automoteur de 20 tonnes. Cet engin, pr\u00e9sent\u00e9 lors d&#8217;une exposition, permet de trier efficacement les mat\u00e9riaux de construction, r\u00e9duisant les co\u00fbts de d\u00e9chetterie. En s\u00e9parant pierres et sable, il optimise aussi la r\u00e9utilisation des [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo_2025_06\/self-propelled-screen-595-separator_imagiire-co-ltd\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-23T05:21:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/06\/maxresdefault-62.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo_2025_06\\\/self-propelled-screen-595-separator_imagiire-co-ltd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo_2025_06\\\/self-propelled-screen-595-separator_imagiire-co-ltd\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"[CSPI-EXPO 2025 - Salon international de l'am\u00e9lioration de la productivit\u00e9 dans la construction et les \u00e9tudes] S\u00e9parateur \u00ab\u00a0Cribleur automoteur 595\u00a0\u00bb - Imagiire Co., Ltd.\",\"datePublished\":\"2025-06-23T05:21:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo_2025_06\\\/self-propelled-screen-595-separator_imagiire-co-ltd\\\/\"},\"wordCount\":103,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo_2025_06\\\/self-propelled-screen-595-separator_imagiire-co-ltd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/maxresdefault-62.jpg\",\"keywords\":[\"Assainissement \\\/ Climatisation \\\/ Plomberie \\\/ \u00c9clairage\",\"B\u00e2timent et construction \\\/ Immobilier\",\"Construction de b\u00e2timents\",\"Entretien \\\/ R\u00e9paration \\\/ Nettoyage du b\u00e2timent\",\"Environnement\",\"Japon\",\"Machines \\\/ Technologie industrielle\",\"Protection de l'environnement \\\/ \u00c9limination des d\u00e9chets \\\/ Recyclage\",\"Technologie avanc\u00e9e \\\/ Mat\u00e9riaux \\\/ Composites \\\/ R&amp;D\"],\"articleSection\":[\"CSPI-EXPO 2025 - Salon international de l'am\u00e9lioration de la productivit\u00e9 dans la construction et les \u00e9tudes\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo_2025_06\\\/self-propelled-screen-595-separator_imagiire-co-ltd\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo_2025_06\\\/self-propelled-screen-595-separator_imagiire-co-ltd\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo_2025_06\\\/self-propelled-screen-595-separator_imagiire-co-ltd\\\/\",\"name\":\"[CSPI-EXPO 2025 - Salon international de l'am\u00e9lioration de la productivit\u00e9 dans la construction et les \u00e9tudes] S\u00e9parateur \u00ab\u00a0Cribleur automoteur 595\u00a0\u00bb - Imagiire Co., Ltd. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo_2025_06\\\/self-propelled-screen-595-separator_imagiire-co-ltd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo_2025_06\\\/self-propelled-screen-595-separator_imagiire-co-ltd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/maxresdefault-62.jpg\",\"datePublished\":\"2025-06-23T05:21:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo_2025_06\\\/self-propelled-screen-595-separator_imagiire-co-ltd\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo_2025_06\\\/self-propelled-screen-595-separator_imagiire-co-ltd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo_2025_06\\\/self-propelled-screen-595-separator_imagiire-co-ltd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/maxresdefault-62.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/maxresdefault-62.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cspi-expo_2025_06\\\/self-propelled-screen-595-separator_imagiire-co-ltd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[CSPI-EXPO 2025 - Salon international de l'am\u00e9lioration de la productivit\u00e9 dans la construction et les \u00e9tudes] S\u00e9parateur \u00ab\u00a0Cribleur automoteur 595\u00a0\u00bb - Imagiire Co., Ltd.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/qSTO5bIOl-Q\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"99\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[CSPI-EXPO 2025 - Salon international de l'am\u00e9lioration de la productivit\u00e9 dans la construction et les \u00e9tudes] S\u00e9parateur \u00ab\u00a0Cribleur automoteur 595\u00a0\u00bb - Imagiire Co., Ltd. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo_2025_06\/self-propelled-screen-595-separator_imagiire-co-ltd\/","og_locale":"fr_FR","og_type":"article","og_title":"[CSPI-EXPO 2025 - Salon international de l'am\u00e9lioration de la productivit\u00e9 dans la construction et les \u00e9tudes] S\u00e9parateur \u00ab\u00a0Cribleur automoteur 595\u00a0\u00bb - Imagiire Co., Ltd. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"**Imagiire Co. mise sur la s\u00e9paration des sols avec son &#8220;Self-Propelled Screen 595&#8243;**Imagiire Co. propose le FINLAY595, un s\u00e9parateur de sols automoteur de 20 tonnes. Cet engin, pr\u00e9sent\u00e9 lors d&#8217;une exposition, permet de trier efficacement les mat\u00e9riaux de construction, r\u00e9duisant les co\u00fbts de d\u00e9chetterie. En s\u00e9parant pierres et sable, il optimise aussi la r\u00e9utilisation des [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo_2025_06\/self-propelled-screen-595-separator_imagiire-co-ltd\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2025-06-23T05:21:44+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/06\/maxresdefault-62.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo_2025_06\/self-propelled-screen-595-separator_imagiire-co-ltd\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo_2025_06\/self-propelled-screen-595-separator_imagiire-co-ltd\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"[CSPI-EXPO 2025 - Salon international de l'am\u00e9lioration de la productivit\u00e9 dans la construction et les \u00e9tudes] S\u00e9parateur \u00ab\u00a0Cribleur automoteur 595\u00a0\u00bb - Imagiire Co., Ltd.","datePublished":"2025-06-23T05:21:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo_2025_06\/self-propelled-screen-595-separator_imagiire-co-ltd\/"},"wordCount":103,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo_2025_06\/self-propelled-screen-595-separator_imagiire-co-ltd\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/06\/maxresdefault-62.jpg","keywords":["Assainissement \/ Climatisation \/ Plomberie \/ \u00c9clairage","B\u00e2timent et construction \/ Immobilier","Construction de b\u00e2timents","Entretien \/ R\u00e9paration \/ Nettoyage du b\u00e2timent","Environnement","Japon","Machines \/ Technologie industrielle","Protection de l'environnement \/ \u00c9limination des d\u00e9chets \/ Recyclage","Technologie avanc\u00e9e \/ Mat\u00e9riaux \/ Composites \/ R&amp;D"],"articleSection":["CSPI-EXPO 2025 - Salon international de l'am\u00e9lioration de la productivit\u00e9 dans la construction et les \u00e9tudes"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo_2025_06\/self-propelled-screen-595-separator_imagiire-co-ltd\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo_2025_06\/self-propelled-screen-595-separator_imagiire-co-ltd\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo_2025_06\/self-propelled-screen-595-separator_imagiire-co-ltd\/","name":"[CSPI-EXPO 2025 - Salon international de l'am\u00e9lioration de la productivit\u00e9 dans la construction et les \u00e9tudes] S\u00e9parateur \u00ab\u00a0Cribleur automoteur 595\u00a0\u00bb - Imagiire Co., Ltd. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo_2025_06\/self-propelled-screen-595-separator_imagiire-co-ltd\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo_2025_06\/self-propelled-screen-595-separator_imagiire-co-ltd\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/06\/maxresdefault-62.jpg","datePublished":"2025-06-23T05:21:44+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo_2025_06\/self-propelled-screen-595-separator_imagiire-co-ltd\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo_2025_06\/self-propelled-screen-595-separator_imagiire-co-ltd\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo_2025_06\/self-propelled-screen-595-separator_imagiire-co-ltd\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/06\/maxresdefault-62.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/06\/maxresdefault-62.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cspi-expo_2025_06\/self-propelled-screen-595-separator_imagiire-co-ltd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"[CSPI-EXPO 2025 - Salon international de l'am\u00e9lioration de la productivit\u00e9 dans la construction et les \u00e9tudes] S\u00e9parateur \u00ab\u00a0Cribleur automoteur 595\u00a0\u00bb - Imagiire Co., Ltd."}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/qSTO5bIOl-Q","og_video_type":"text\/html","og_video_duration":"99","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=qSTO5bIOl-Q","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/55615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=55615"}],"version-history":[{"count":1,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/55615\/revisions"}],"predecessor-version":[{"id":55619,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/55615\/revisions\/55619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/55616"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=55615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=55615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=55615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}