{"id":53939,"date":"2025-01-17T03:01:20","date_gmt":"2025-01-17T03:01:20","guid":{"rendered":"https:\/\/www.worldtradeshow.tv\/french\/?p=53939"},"modified":"2025-01-17T03:01:20","modified_gmt":"2025-01-17T03:01:20","slug":"specialty-chemicals_ultima","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/cphi_2024_11\/specialty-chemicals_ultima\/","title":{"rendered":"[CPHI et PMEC Inde 2024] Produits chimiques sp\u00e9cialis\u00e9s - ULTIMA"},"content":{"rendered":"<blockquote class=\"wp-block-quote\"><p>**ULTIMA Specialty Chemicals : Distributeur de produits chimiques sp\u00e9cialis\u00e9s**<br \/>ULTIMA Specialty Chemicals, soci\u00e9t\u00e9 de distribution de produits chimiques cr\u00e9\u00e9e il y a pr\u00e8s de 30 ans, a pr\u00e9sent\u00e9 des mati\u00e8res premi\u00e8res utilis\u00e9es par diverses industries. L&#8217;entreprise importe des produits de 14 pays et les distribue dans toute l&#8217;Inde. Elle propose \u00e9galement des services de fabrication \u00e0 fa\u00e7on dans le secteur des produits chimiques sp\u00e9cialis\u00e9s.<br \/>**Contactez ULTIMA Specialty Chemicals :**<br \/>https:\/\/www.ultimachem.com\/<cite>Generated by <a href=\"https:\/\/gemini.google.com\/\">Gemini<\/a><\/cite><\/p><\/blockquote>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>**ULTIMA Specialty Chemicals : Distributeur de produits chimiques sp\u00e9cialis\u00e9s**ULTIMA Specialty Chemicals, soci\u00e9t\u00e9 de distribution de produits chimiques cr\u00e9\u00e9e il y a pr\u00e8s de 30 ans, a pr\u00e9sent\u00e9 des mati\u00e8res premi\u00e8res utilis\u00e9es par diverses industries. L&#8217;entreprise importe des produits de 14 pays et les distribue dans toute l&#8217;Inde. Elle propose \u00e9galement des services de fabrication \u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":53940,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[591],"tags":[568,154,587,588,34,37],"class_list":["post-53939","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-cphi_2024_11","tag-transportation-logistics-packaging-9","tag-india","tag-medical-care-health-4","tag-medical-care-health-5","tag-medical-care-health","tag-transportation-logistics-packaging","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[CPHI et PMEC Inde 2024] Produits chimiques sp\u00e9cialis\u00e9s - ULTIMA \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/cphi_2024_11\/specialty-chemicals_ultima\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[CPHI et PMEC Inde 2024] Produits chimiques sp\u00e9cialis\u00e9s - ULTIMA \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"**ULTIMA Specialty Chemicals : Distributeur de produits chimiques sp\u00e9cialis\u00e9s**ULTIMA Specialty Chemicals, soci\u00e9t\u00e9 de distribution de produits chimiques cr\u00e9\u00e9e il y a pr\u00e8s de 30 ans, a pr\u00e9sent\u00e9 des mati\u00e8res premi\u00e8res utilis\u00e9es par diverses industries. L&#8217;entreprise importe des produits de 14 pays et les distribue dans toute l&#8217;Inde. Elle propose \u00e9galement des services de fabrication \u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/cphi_2024_11\/specialty-chemicals_ultima\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-17T03:01:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/01\/maxresdefault-26.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cphi_2024_11\\\/specialty-chemicals_ultima\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cphi_2024_11\\\/specialty-chemicals_ultima\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"[CPHI et PMEC Inde 2024] Produits chimiques sp\u00e9cialis\u00e9s - ULTIMA\",\"datePublished\":\"2025-01-17T03:01:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cphi_2024_11\\\/specialty-chemicals_ultima\\\/\"},\"wordCount\":96,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cphi_2024_11\\\/specialty-chemicals_ultima\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/maxresdefault-26.jpg\",\"keywords\":[\"Emballage (Mat\u00e9riaux \\\/ Machines et \u00e9quipements)\",\"Inde\",\"Produits pharmaceutiques \\\/ Pharmacie\",\"Soins de sant\u00e9 (\u00e9quipements\\\/produits et services)\",\"Soins m\u00e9dicaux \\\/ Sant\u00e9\",\"Transport \\\/ Logistique \\\/ Emballage\"],\"articleSection\":[\"CPHI et PMEC Inde 2024\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cphi_2024_11\\\/specialty-chemicals_ultima\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cphi_2024_11\\\/specialty-chemicals_ultima\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cphi_2024_11\\\/specialty-chemicals_ultima\\\/\",\"name\":\"[CPHI et PMEC Inde 2024] Produits chimiques sp\u00e9cialis\u00e9s - ULTIMA \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cphi_2024_11\\\/specialty-chemicals_ultima\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cphi_2024_11\\\/specialty-chemicals_ultima\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/maxresdefault-26.jpg\",\"datePublished\":\"2025-01-17T03:01:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cphi_2024_11\\\/specialty-chemicals_ultima\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cphi_2024_11\\\/specialty-chemicals_ultima\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cphi_2024_11\\\/specialty-chemicals_ultima\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/maxresdefault-26.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/maxresdefault-26.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/cphi_2024_11\\\/specialty-chemicals_ultima\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[CPHI et PMEC Inde 2024] Produits chimiques sp\u00e9cialis\u00e9s - ULTIMA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/bKVIrxSPGJg\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"59\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[CPHI et PMEC Inde 2024] Produits chimiques sp\u00e9cialis\u00e9s - ULTIMA \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/cphi_2024_11\/specialty-chemicals_ultima\/","og_locale":"fr_FR","og_type":"article","og_title":"[CPHI et PMEC Inde 2024] Produits chimiques sp\u00e9cialis\u00e9s - ULTIMA \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"**ULTIMA Specialty Chemicals : Distributeur de produits chimiques sp\u00e9cialis\u00e9s**ULTIMA Specialty Chemicals, soci\u00e9t\u00e9 de distribution de produits chimiques cr\u00e9\u00e9e il y a pr\u00e8s de 30 ans, a pr\u00e9sent\u00e9 des mati\u00e8res premi\u00e8res utilis\u00e9es par diverses industries. L&#8217;entreprise importe des produits de 14 pays et les distribue dans toute l&#8217;Inde. Elle propose \u00e9galement des services de fabrication \u00e0 [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/cphi_2024_11\/specialty-chemicals_ultima\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2025-01-17T03:01:20+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/01\/maxresdefault-26.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cphi_2024_11\/specialty-chemicals_ultima\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cphi_2024_11\/specialty-chemicals_ultima\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"[CPHI et PMEC Inde 2024] Produits chimiques sp\u00e9cialis\u00e9s - ULTIMA","datePublished":"2025-01-17T03:01:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cphi_2024_11\/specialty-chemicals_ultima\/"},"wordCount":96,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cphi_2024_11\/specialty-chemicals_ultima\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/01\/maxresdefault-26.jpg","keywords":["Emballage (Mat\u00e9riaux \/ Machines et \u00e9quipements)","Inde","Produits pharmaceutiques \/ Pharmacie","Soins de sant\u00e9 (\u00e9quipements\/produits et services)","Soins m\u00e9dicaux \/ Sant\u00e9","Transport \/ Logistique \/ Emballage"],"articleSection":["CPHI et PMEC Inde 2024"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/cphi_2024_11\/specialty-chemicals_ultima\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cphi_2024_11\/specialty-chemicals_ultima\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/cphi_2024_11\/specialty-chemicals_ultima\/","name":"[CPHI et PMEC Inde 2024] Produits chimiques sp\u00e9cialis\u00e9s - ULTIMA \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cphi_2024_11\/specialty-chemicals_ultima\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cphi_2024_11\/specialty-chemicals_ultima\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/01\/maxresdefault-26.jpg","datePublished":"2025-01-17T03:01:20+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cphi_2024_11\/specialty-chemicals_ultima\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/cphi_2024_11\/specialty-chemicals_ultima\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cphi_2024_11\/specialty-chemicals_ultima\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/01\/maxresdefault-26.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2025\/01\/maxresdefault-26.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/cphi_2024_11\/specialty-chemicals_ultima\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"[CPHI et PMEC Inde 2024] Produits chimiques sp\u00e9cialis\u00e9s - ULTIMA"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/bKVIrxSPGJg","og_video_type":"text\/html","og_video_duration":"59","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=bKVIrxSPGJg","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/53939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=53939"}],"version-history":[{"count":1,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/53939\/revisions"}],"predecessor-version":[{"id":53957,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/53939\/revisions\/53957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/53940"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=53939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=53939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=53939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}