{"id":52932,"date":"2024-10-22T01:02:25","date_gmt":"2024-10-22T01:02:25","guid":{"rendered":"https:\/\/www.worldtradeshow.tv\/french\/?p=52932"},"modified":"2024-10-22T01:02:25","modified_gmt":"2024-10-22T01:02:25","slug":"movbot-office_access-engineering-co","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/hcr_2024_10\/movbot-office_access-engineering-co\/","title":{"rendered":"[H.C.R.2024 &#038; Forum - Le 51\u00e8me Salon International des Soins \u00e0 Domicile et de la R\u00e9adaptation] Bureau de movBot - Acc\u00e8s Engineering Co."},"content":{"rendered":"<blockquote class=\"wp-block-quote\"><p>**MovBot Office\u00a0: offrir aux utilisateurs de fauteuils roulants accessibilit\u00e9 et efficacit\u00e9**<br \/>Lors du r\u00e9cent salon professionnel H.C.R.2024 &#038; Forum, Access Engineering Co. a d\u00e9voil\u00e9 son innovant MovBot Office, un robot en fauteuil roulant con\u00e7u pour am\u00e9liorer la mobilit\u00e9 et l&#8217;ind\u00e9pendance des utilisateurs. Avec ses roues m\u00e9caniques avanc\u00e9es, sa hauteur r\u00e9glable et ses capacit\u00e9s de pivotement, le MovBot Office permet aux individus de naviguer dans des espaces restreints, de s&#8217;\u00e9lever jusqu&#8217;\u00e0 une position de travail confortable et de participer pleinement \u00e0 divers environnements de travail.<br \/>Soutenu par une subvention de la pr\u00e9fecture de Kanagawa, le bureau MovBot vise \u00e0 cr\u00e9er un espace de travail inclusif o\u00f9 les utilisateurs de fauteuils roulants peuvent accomplir leurs t\u00e2ches de mani\u00e8re transparente aux c\u00f4t\u00e9s de leurs coll\u00e8gues non handicap\u00e9s. Access Engineering Co. s&#8217;engage \u00e0 fournir des solutions accessibles et efficaces qui permettent aux personnes handicap\u00e9es d&#8217;atteindre leur plein potentiel.<cite>Generated by <a href=\"https:\/\/gemini.google.com\/\">Gemini<\/a><\/cite><\/p><\/blockquote>\n<p><\/p>\n<p>site Internet:<a href=\"https:\/\/www.access-eng.com\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.access-eng.com\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>**MovBot Office\u00a0: offrir aux utilisateurs de fauteuils roulants accessibilit\u00e9 et efficacit\u00e9**Lors du r\u00e9cent salon professionnel H.C.R.2024 &#038; Forum, Access Engineering Co. a d\u00e9voil\u00e9 son innovant MovBot Office, un robot en fauteuil roulant con\u00e7u pour am\u00e9liorer la mobilit\u00e9 et l&#8217;ind\u00e9pendance des utilisateurs. Avec ses roues m\u00e9caniques avanc\u00e9es, sa hauteur r\u00e9glable et ses capacit\u00e9s de pivotement, le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":52933,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[497],"tags":[38,34],"class_list":["post-52932","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-hcr_2024_10","tag-japan","tag-medical-care-health","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[H.C.R.2024 &amp; Forum - Le 51\u00e8me Salon International des Soins \u00e0 Domicile et de la R\u00e9adaptation] Bureau de movBot - Acc\u00e8s Engineering Co. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/hcr_2024_10\/movbot-office_access-engineering-co\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[H.C.R.2024 &amp; Forum - Le 51\u00e8me Salon International des Soins \u00e0 Domicile et de la R\u00e9adaptation] Bureau de movBot - Acc\u00e8s Engineering Co. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"**MovBot Office\u00a0: offrir aux utilisateurs de fauteuils roulants accessibilit\u00e9 et efficacit\u00e9**Lors du r\u00e9cent salon professionnel H.C.R.2024 &#038; Forum, Access Engineering Co. a d\u00e9voil\u00e9 son innovant MovBot Office, un robot en fauteuil roulant con\u00e7u pour am\u00e9liorer la mobilit\u00e9 et l&#8217;ind\u00e9pendance des utilisateurs. Avec ses roues m\u00e9caniques avanc\u00e9es, sa hauteur r\u00e9glable et ses capacit\u00e9s de pivotement, le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/hcr_2024_10\/movbot-office_access-engineering-co\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-22T01:02:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2024\/10\/maxresdefault-38.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/hcr_2024_10\\\/movbot-office_access-engineering-co\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/hcr_2024_10\\\/movbot-office_access-engineering-co\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"[H.C.R.2024 &#038; Forum - Le 51\u00e8me Salon International des Soins \u00e0 Domicile et de la R\u00e9adaptation] Bureau de movBot - Acc\u00e8s Engineering Co.\",\"datePublished\":\"2024-10-22T01:02:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/hcr_2024_10\\\/movbot-office_access-engineering-co\\\/\"},\"wordCount\":198,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/hcr_2024_10\\\/movbot-office_access-engineering-co\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/maxresdefault-38.jpg\",\"keywords\":[\"Japon\",\"Soins m\u00e9dicaux \\\/ Sant\u00e9\"],\"articleSection\":[\"H.C.R.2024 &amp; Forum - Le 51\u00e8me Salon International des Soins \u00e0 Domicile et de la R\u00e9adaptation\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/hcr_2024_10\\\/movbot-office_access-engineering-co\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/hcr_2024_10\\\/movbot-office_access-engineering-co\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/hcr_2024_10\\\/movbot-office_access-engineering-co\\\/\",\"name\":\"[H.C.R.2024 & Forum - Le 51\u00e8me Salon International des Soins \u00e0 Domicile et de la R\u00e9adaptation] Bureau de movBot - Acc\u00e8s Engineering Co. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/hcr_2024_10\\\/movbot-office_access-engineering-co\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/hcr_2024_10\\\/movbot-office_access-engineering-co\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/maxresdefault-38.jpg\",\"datePublished\":\"2024-10-22T01:02:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/hcr_2024_10\\\/movbot-office_access-engineering-co\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/hcr_2024_10\\\/movbot-office_access-engineering-co\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/hcr_2024_10\\\/movbot-office_access-engineering-co\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/maxresdefault-38.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/maxresdefault-38.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/hcr_2024_10\\\/movbot-office_access-engineering-co\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[H.C.R.2024 &#038; Forum - Le 51\u00e8me Salon International des Soins \u00e0 Domicile et de la R\u00e9adaptation] Bureau de movBot - Acc\u00e8s Engineering Co.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/Ii02Bh4diNs\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"52\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[H.C.R.2024 & Forum - Le 51\u00e8me Salon International des Soins \u00e0 Domicile et de la R\u00e9adaptation] Bureau de movBot - Acc\u00e8s Engineering Co. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/hcr_2024_10\/movbot-office_access-engineering-co\/","og_locale":"fr_FR","og_type":"article","og_title":"[H.C.R.2024 & Forum - Le 51\u00e8me Salon International des Soins \u00e0 Domicile et de la R\u00e9adaptation] Bureau de movBot - Acc\u00e8s Engineering Co. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"**MovBot Office\u00a0: offrir aux utilisateurs de fauteuils roulants accessibilit\u00e9 et efficacit\u00e9**Lors du r\u00e9cent salon professionnel H.C.R.2024 &#038; Forum, Access Engineering Co. a d\u00e9voil\u00e9 son innovant MovBot Office, un robot en fauteuil roulant con\u00e7u pour am\u00e9liorer la mobilit\u00e9 et l&#8217;ind\u00e9pendance des utilisateurs. Avec ses roues m\u00e9caniques avanc\u00e9es, sa hauteur r\u00e9glable et ses capacit\u00e9s de pivotement, le [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/hcr_2024_10\/movbot-office_access-engineering-co\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2024-10-22T01:02:25+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2024\/10\/maxresdefault-38.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/hcr_2024_10\/movbot-office_access-engineering-co\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/hcr_2024_10\/movbot-office_access-engineering-co\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"[H.C.R.2024 &#038; Forum - Le 51\u00e8me Salon International des Soins \u00e0 Domicile et de la R\u00e9adaptation] Bureau de movBot - Acc\u00e8s Engineering Co.","datePublished":"2024-10-22T01:02:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/hcr_2024_10\/movbot-office_access-engineering-co\/"},"wordCount":198,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/hcr_2024_10\/movbot-office_access-engineering-co\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2024\/10\/maxresdefault-38.jpg","keywords":["Japon","Soins m\u00e9dicaux \/ Sant\u00e9"],"articleSection":["H.C.R.2024 &amp; Forum - Le 51\u00e8me Salon International des Soins \u00e0 Domicile et de la R\u00e9adaptation"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/hcr_2024_10\/movbot-office_access-engineering-co\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/hcr_2024_10\/movbot-office_access-engineering-co\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/hcr_2024_10\/movbot-office_access-engineering-co\/","name":"[H.C.R.2024 & Forum - Le 51\u00e8me Salon International des Soins \u00e0 Domicile et de la R\u00e9adaptation] Bureau de movBot - Acc\u00e8s Engineering Co. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/hcr_2024_10\/movbot-office_access-engineering-co\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/hcr_2024_10\/movbot-office_access-engineering-co\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2024\/10\/maxresdefault-38.jpg","datePublished":"2024-10-22T01:02:25+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/hcr_2024_10\/movbot-office_access-engineering-co\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/hcr_2024_10\/movbot-office_access-engineering-co\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/hcr_2024_10\/movbot-office_access-engineering-co\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2024\/10\/maxresdefault-38.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2024\/10\/maxresdefault-38.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/hcr_2024_10\/movbot-office_access-engineering-co\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"[H.C.R.2024 &#038; Forum - Le 51\u00e8me Salon International des Soins \u00e0 Domicile et de la R\u00e9adaptation] Bureau de movBot - Acc\u00e8s Engineering Co."}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/Ii02Bh4diNs","og_video_type":"text\/html","og_video_duration":"52","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=Ii02Bh4diNs","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/52932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=52932"}],"version-history":[{"count":1,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/52932\/revisions"}],"predecessor-version":[{"id":52958,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/52932\/revisions\/52958"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/52933"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=52932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=52932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=52932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}