{"id":49746,"date":"2024-03-12T02:40:12","date_gmt":"2024-03-12T02:40:12","guid":{"rendered":"https:\/\/france.worldtradeshow.tv\/?p=49746"},"modified":"2024-03-12T02:40:12","modified_gmt":"2024-03-12T02:40:12","slug":"oils-additives_xenum-racing","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/acma-automechanika-newdelhi_2024_02\/oils-additives_xenum-racing\/","title":{"rendered":"[ACMA Automechanika New Delhi 2024] Huiles et additifs - COURSE X\u00c9NUM"},"content":{"rendered":"<blockquote class=\"wp-block-quote\"><p>**XENUM Racing : Des solutions innovantes pour l&#8217;huile et les additifs**<br \/>Au salon Automechanika de Delhi 2024, XENUM Racing a pr\u00e9sent\u00e9 ses derni\u00e8res avanc\u00e9es dans le domaine des huiles et additifs. La soci\u00e9t\u00e9 propose une large gamme de produits pour pr\u00e9venir et r\u00e9soudre les probl\u00e8mes de lubrification, notamment des additifs pour \u00e9viter la cristallisation des lubrifiants, une innovation brevet\u00e9e.<br \/>**XENUM : 20 ans d&#8217;expertise dans les fluides et \u00e9quipements automobiles**<br \/>Cr\u00e9\u00e9e il y a 20 ans, XENUM s&#8217;est impos\u00e9e comme un leader europ\u00e9en dans la fabrication d&#8217;huiles, d&#8217;additifs et d&#8217;\u00e9quipements automobiles. Pr\u00e9sente dans 42 pays, la soci\u00e9t\u00e9 se distingue par ses produits innovants et performants, con\u00e7us pour optimiser les performances des v\u00e9hicules.<cite>Generated by <a href=\"https:\/\/openai.com\/\">OpenAI<\/a><\/cite><\/p><\/blockquote>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>**XENUM Racing : Des solutions innovantes pour l&#8217;huile et les additifs**Au salon Automechanika de Delhi 2024, XENUM Racing a pr\u00e9sent\u00e9 ses derni\u00e8res avanc\u00e9es dans le domaine des huiles et additifs. La soci\u00e9t\u00e9 propose une large gamme de produits pour pr\u00e9venir et r\u00e9soudre les probl\u00e8mes de lubrification, notamment des additifs pour \u00e9viter la cristallisation des lubrifiants, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":49747,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[422],"tags":[35,154,31,37],"class_list":["post-49746","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-acma-automechanika-newdelhi_2024_02","tag-others","tag-india","tag-information-telecommunication","tag-transportation-logistics-packaging","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[ACMA Automechanika New Delhi 2024] Huiles et additifs - COURSE X\u00c9NUM \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/acma-automechanika-newdelhi_2024_02\/oils-additives_xenum-racing\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[ACMA Automechanika New Delhi 2024] Huiles et additifs - COURSE X\u00c9NUM \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"**XENUM Racing : Des solutions innovantes pour l&#8217;huile et les additifs**Au salon Automechanika de Delhi 2024, XENUM Racing a pr\u00e9sent\u00e9 ses derni\u00e8res avanc\u00e9es dans le domaine des huiles et additifs. La soci\u00e9t\u00e9 propose une large gamme de produits pour pr\u00e9venir et r\u00e9soudre les probl\u00e8mes de lubrification, notamment des additifs pour \u00e9viter la cristallisation des lubrifiants, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/acma-automechanika-newdelhi_2024_02\/oils-additives_xenum-racing\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-12T02:40:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2024\/03\/maxresdefault-70.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/acma-automechanika-newdelhi_2024_02\\\/oils-additives_xenum-racing\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/acma-automechanika-newdelhi_2024_02\\\/oils-additives_xenum-racing\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"[ACMA Automechanika New Delhi 2024] Huiles et additifs - COURSE X\u00c9NUM\",\"datePublished\":\"2024-03-12T02:40:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/acma-automechanika-newdelhi_2024_02\\\/oils-additives_xenum-racing\\\/\"},\"wordCount\":141,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/acma-automechanika-newdelhi_2024_02\\\/oils-additives_xenum-racing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/maxresdefault-70.jpg\",\"keywords\":[\"Autres\",\"Inde\",\"Information \\\/ T\u00e9l\u00e9communication\",\"Transport \\\/ Logistique \\\/ Emballage\"],\"articleSection\":[\"ACMA Automechanika New Delhi 2024\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/acma-automechanika-newdelhi_2024_02\\\/oils-additives_xenum-racing\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/acma-automechanika-newdelhi_2024_02\\\/oils-additives_xenum-racing\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/acma-automechanika-newdelhi_2024_02\\\/oils-additives_xenum-racing\\\/\",\"name\":\"[ACMA Automechanika New Delhi 2024] Huiles et additifs - COURSE X\u00c9NUM \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/acma-automechanika-newdelhi_2024_02\\\/oils-additives_xenum-racing\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/acma-automechanika-newdelhi_2024_02\\\/oils-additives_xenum-racing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/maxresdefault-70.jpg\",\"datePublished\":\"2024-03-12T02:40:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/acma-automechanika-newdelhi_2024_02\\\/oils-additives_xenum-racing\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/acma-automechanika-newdelhi_2024_02\\\/oils-additives_xenum-racing\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/acma-automechanika-newdelhi_2024_02\\\/oils-additives_xenum-racing\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/maxresdefault-70.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/maxresdefault-70.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/acma-automechanika-newdelhi_2024_02\\\/oils-additives_xenum-racing\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[ACMA Automechanika New Delhi 2024] Huiles et additifs - COURSE X\u00c9NUM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/ye39-628R_g\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"73\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[ACMA Automechanika New Delhi 2024] Huiles et additifs - COURSE X\u00c9NUM \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/acma-automechanika-newdelhi_2024_02\/oils-additives_xenum-racing\/","og_locale":"fr_FR","og_type":"article","og_title":"[ACMA Automechanika New Delhi 2024] Huiles et additifs - COURSE X\u00c9NUM \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"**XENUM Racing : Des solutions innovantes pour l&#8217;huile et les additifs**Au salon Automechanika de Delhi 2024, XENUM Racing a pr\u00e9sent\u00e9 ses derni\u00e8res avanc\u00e9es dans le domaine des huiles et additifs. La soci\u00e9t\u00e9 propose une large gamme de produits pour pr\u00e9venir et r\u00e9soudre les probl\u00e8mes de lubrification, notamment des additifs pour \u00e9viter la cristallisation des lubrifiants, [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/acma-automechanika-newdelhi_2024_02\/oils-additives_xenum-racing\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2024-03-12T02:40:12+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2024\/03\/maxresdefault-70.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/acma-automechanika-newdelhi_2024_02\/oils-additives_xenum-racing\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/acma-automechanika-newdelhi_2024_02\/oils-additives_xenum-racing\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"[ACMA Automechanika New Delhi 2024] Huiles et additifs - COURSE X\u00c9NUM","datePublished":"2024-03-12T02:40:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/acma-automechanika-newdelhi_2024_02\/oils-additives_xenum-racing\/"},"wordCount":141,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/acma-automechanika-newdelhi_2024_02\/oils-additives_xenum-racing\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2024\/03\/maxresdefault-70.jpg","keywords":["Autres","Inde","Information \/ T\u00e9l\u00e9communication","Transport \/ Logistique \/ Emballage"],"articleSection":["ACMA Automechanika New Delhi 2024"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/acma-automechanika-newdelhi_2024_02\/oils-additives_xenum-racing\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/acma-automechanika-newdelhi_2024_02\/oils-additives_xenum-racing\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/acma-automechanika-newdelhi_2024_02\/oils-additives_xenum-racing\/","name":"[ACMA Automechanika New Delhi 2024] Huiles et additifs - COURSE X\u00c9NUM \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/acma-automechanika-newdelhi_2024_02\/oils-additives_xenum-racing\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/acma-automechanika-newdelhi_2024_02\/oils-additives_xenum-racing\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2024\/03\/maxresdefault-70.jpg","datePublished":"2024-03-12T02:40:12+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/acma-automechanika-newdelhi_2024_02\/oils-additives_xenum-racing\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/acma-automechanika-newdelhi_2024_02\/oils-additives_xenum-racing\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/acma-automechanika-newdelhi_2024_02\/oils-additives_xenum-racing\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2024\/03\/maxresdefault-70.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2024\/03\/maxresdefault-70.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/acma-automechanika-newdelhi_2024_02\/oils-additives_xenum-racing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"[ACMA Automechanika New Delhi 2024] Huiles et additifs - COURSE X\u00c9NUM"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/ye39-628R_g","og_video_type":"text\/html","og_video_duration":"73","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=ye39-628R_g","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/49746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=49746"}],"version-history":[{"count":0,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/49746\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/49747"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=49746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=49746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=49746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}