{"id":48475,"date":"2023-12-21T02:05:08","date_gmt":"2023-12-21T02:05:08","guid":{"rendered":"https:\/\/france.worldtradeshow.tv\/?p=48475"},"modified":"2023-12-21T02:05:08","modified_gmt":"2023-12-21T02:05:08","slug":"cloud-recording-service-antenna-eye_elecom-co-ltd","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/japan-build_2023_12\/cloud-recording-service-antenna-eye_elecom-co-ltd\/","title":{"rendered":"[8e JAPAN BUILD TOKYO - Semaine internationale du b\u00e2timent et de la maison -] Antenne-oeil du service d'enregistrement cloud - ELECOM Co., Ltd."},"content":{"rendered":"<blockquote class=\"wp-block-quote\"><p>ELECOM Co., Ltd., pr\u00e9sent \u00e0 la 8e JAPAN BUILD TOKYO &#8211; International Building &#038; Home Week, propose son service d&#8217;enregistrement cloud, antenna-eye. Sp\u00e9cialis\u00e9e dans les p\u00e9riph\u00e9riques, la soci\u00e9t\u00e9 met en avant ses solutions de cam\u00e9ras r\u00e9seau pour les professionnels. Gr\u00e2ce \u00e0 des partenariats avec DX Antenna, ELECOM offre une vari\u00e9t\u00e9 de cam\u00e9ras et de solutions bas\u00e9es sur le cloud. Leurs formats d&#8217;enregistrement hybrides r\u00e9pondent \u00e9galement aux besoins sp\u00e9cifiques des clients. En utilisant un serveur fourni par Sakura Internet, leur service est fiable. ELECOM se positionne comme un partenaire de premier choix pour l&#8217;industrie de la construction.<cite>Generated by <a href=\"https:\/\/openai.com\/\">OpenAI<\/a><\/cite><\/p><\/blockquote>\n<p><\/p>\n<p>site Internet:<a href=\"https:\/\/www.elecom.co.jp\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.elecom.co.jp\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ELECOM Co., Ltd., pr\u00e9sent \u00e0 la 8e JAPAN BUILD TOKYO &#8211; International Building &#038; Home Week, propose son service d&#8217;enregistrement cloud, antenna-eye. Sp\u00e9cialis\u00e9e dans les p\u00e9riph\u00e9riques, la soci\u00e9t\u00e9 met en avant ses solutions de cam\u00e9ras r\u00e9seau pour les professionnels. Gr\u00e2ce \u00e0 des partenariats avec DX Antenna, ELECOM offre une vari\u00e9t\u00e9 de cam\u00e9ras et de solutions [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":48476,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[388],"tags":[35,26,38],"class_list":["post-48475","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-japan-build_2023_12","tag-others","tag-building-construction","tag-japan","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[8e JAPAN BUILD TOKYO - Semaine internationale du b\u00e2timent et de la maison -] Antenne-oeil du service d&#039;enregistrement cloud - ELECOM Co., Ltd. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/japan-build_2023_12\/cloud-recording-service-antenna-eye_elecom-co-ltd\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[8e JAPAN BUILD TOKYO - Semaine internationale du b\u00e2timent et de la maison -] Antenne-oeil du service d&#039;enregistrement cloud - ELECOM Co., Ltd. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"ELECOM Co., Ltd., pr\u00e9sent \u00e0 la 8e JAPAN BUILD TOKYO &#8211; International Building &#038; Home Week, propose son service d&#8217;enregistrement cloud, antenna-eye. Sp\u00e9cialis\u00e9e dans les p\u00e9riph\u00e9riques, la soci\u00e9t\u00e9 met en avant ses solutions de cam\u00e9ras r\u00e9seau pour les professionnels. Gr\u00e2ce \u00e0 des partenariats avec DX Antenna, ELECOM offre une vari\u00e9t\u00e9 de cam\u00e9ras et de solutions [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/japan-build_2023_12\/cloud-recording-service-antenna-eye_elecom-co-ltd\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-21T02:05:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/12\/maxresdefault-40.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/japan-build_2023_12\\\/cloud-recording-service-antenna-eye_elecom-co-ltd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/japan-build_2023_12\\\/cloud-recording-service-antenna-eye_elecom-co-ltd\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"[8e JAPAN BUILD TOKYO - Semaine internationale du b\u00e2timent et de la maison -] Antenne-oeil du service d'enregistrement cloud - ELECOM Co., Ltd.\",\"datePublished\":\"2023-12-21T02:05:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/japan-build_2023_12\\\/cloud-recording-service-antenna-eye_elecom-co-ltd\\\/\"},\"wordCount\":145,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/japan-build_2023_12\\\/cloud-recording-service-antenna-eye_elecom-co-ltd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/maxresdefault-40.jpg\",\"keywords\":[\"Autres\",\"Construction de b\u00e2timents\",\"Japon\"],\"articleSection\":[\"8e JAPAN BUILD TOKYO - Semaine internationale du b\u00e2timent et de la maison -\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/japan-build_2023_12\\\/cloud-recording-service-antenna-eye_elecom-co-ltd\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/japan-build_2023_12\\\/cloud-recording-service-antenna-eye_elecom-co-ltd\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/japan-build_2023_12\\\/cloud-recording-service-antenna-eye_elecom-co-ltd\\\/\",\"name\":\"[8e JAPAN BUILD TOKYO - Semaine internationale du b\u00e2timent et de la maison -] Antenne-oeil du service d'enregistrement cloud - ELECOM Co., Ltd. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/japan-build_2023_12\\\/cloud-recording-service-antenna-eye_elecom-co-ltd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/japan-build_2023_12\\\/cloud-recording-service-antenna-eye_elecom-co-ltd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/maxresdefault-40.jpg\",\"datePublished\":\"2023-12-21T02:05:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/japan-build_2023_12\\\/cloud-recording-service-antenna-eye_elecom-co-ltd\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/japan-build_2023_12\\\/cloud-recording-service-antenna-eye_elecom-co-ltd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/japan-build_2023_12\\\/cloud-recording-service-antenna-eye_elecom-co-ltd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/maxresdefault-40.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/maxresdefault-40.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/japan-build_2023_12\\\/cloud-recording-service-antenna-eye_elecom-co-ltd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[8e JAPAN BUILD TOKYO - Semaine internationale du b\u00e2timent et de la maison -] Antenne-oeil du service d'enregistrement cloud - ELECOM Co., Ltd.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/pJ0Yh6OuNrc\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"81\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[8e JAPAN BUILD TOKYO - Semaine internationale du b\u00e2timent et de la maison -] Antenne-oeil du service d'enregistrement cloud - ELECOM Co., Ltd. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/japan-build_2023_12\/cloud-recording-service-antenna-eye_elecom-co-ltd\/","og_locale":"fr_FR","og_type":"article","og_title":"[8e JAPAN BUILD TOKYO - Semaine internationale du b\u00e2timent et de la maison -] Antenne-oeil du service d'enregistrement cloud - ELECOM Co., Ltd. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"ELECOM Co., Ltd., pr\u00e9sent \u00e0 la 8e JAPAN BUILD TOKYO &#8211; International Building &#038; Home Week, propose son service d&#8217;enregistrement cloud, antenna-eye. Sp\u00e9cialis\u00e9e dans les p\u00e9riph\u00e9riques, la soci\u00e9t\u00e9 met en avant ses solutions de cam\u00e9ras r\u00e9seau pour les professionnels. Gr\u00e2ce \u00e0 des partenariats avec DX Antenna, ELECOM offre une vari\u00e9t\u00e9 de cam\u00e9ras et de solutions [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/japan-build_2023_12\/cloud-recording-service-antenna-eye_elecom-co-ltd\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2023-12-21T02:05:08+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/12\/maxresdefault-40.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/japan-build_2023_12\/cloud-recording-service-antenna-eye_elecom-co-ltd\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/japan-build_2023_12\/cloud-recording-service-antenna-eye_elecom-co-ltd\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"[8e JAPAN BUILD TOKYO - Semaine internationale du b\u00e2timent et de la maison -] Antenne-oeil du service d'enregistrement cloud - ELECOM Co., Ltd.","datePublished":"2023-12-21T02:05:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/japan-build_2023_12\/cloud-recording-service-antenna-eye_elecom-co-ltd\/"},"wordCount":145,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/japan-build_2023_12\/cloud-recording-service-antenna-eye_elecom-co-ltd\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/12\/maxresdefault-40.jpg","keywords":["Autres","Construction de b\u00e2timents","Japon"],"articleSection":["8e JAPAN BUILD TOKYO - Semaine internationale du b\u00e2timent et de la maison -"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/japan-build_2023_12\/cloud-recording-service-antenna-eye_elecom-co-ltd\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/japan-build_2023_12\/cloud-recording-service-antenna-eye_elecom-co-ltd\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/japan-build_2023_12\/cloud-recording-service-antenna-eye_elecom-co-ltd\/","name":"[8e JAPAN BUILD TOKYO - Semaine internationale du b\u00e2timent et de la maison -] Antenne-oeil du service d'enregistrement cloud - ELECOM Co., Ltd. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/japan-build_2023_12\/cloud-recording-service-antenna-eye_elecom-co-ltd\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/japan-build_2023_12\/cloud-recording-service-antenna-eye_elecom-co-ltd\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/12\/maxresdefault-40.jpg","datePublished":"2023-12-21T02:05:08+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/japan-build_2023_12\/cloud-recording-service-antenna-eye_elecom-co-ltd\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/japan-build_2023_12\/cloud-recording-service-antenna-eye_elecom-co-ltd\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/japan-build_2023_12\/cloud-recording-service-antenna-eye_elecom-co-ltd\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/12\/maxresdefault-40.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/12\/maxresdefault-40.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/japan-build_2023_12\/cloud-recording-service-antenna-eye_elecom-co-ltd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"[8e JAPAN BUILD TOKYO - Semaine internationale du b\u00e2timent et de la maison -] Antenne-oeil du service d'enregistrement cloud - ELECOM Co., Ltd."}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/pJ0Yh6OuNrc","og_video_type":"text\/html","og_video_duration":"81","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=pJ0Yh6OuNrc","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/48475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=48475"}],"version-history":[{"count":0,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/48475\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/48476"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=48475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=48475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=48475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}