{"id":47694,"date":"2023-10-13T07:13:35","date_gmt":"2023-10-13T07:13:35","guid":{"rendered":"https:\/\/france.worldtradeshow.tv\/?p=47694"},"modified":"2023-10-13T07:13:35","modified_gmt":"2023-10-13T07:13:35","slug":"standing-wheelchair-u0026-hoist-multi-lift_cmed-medical","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicalfair-thailand_2023_09\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\/","title":{"rendered":"[Salon m\u00e9dical Tha\u00eflande 2023] Fauteuil roulant debout u0026 Hoist Multi Lift - Cmed M\u00e9dical"},"content":{"rendered":"<blockquote class=\"wp-block-quote\"><p>Cmed Medical pr\u00e9sente lors du salon Medical Fair Thailand 2023 sa nouvelle innovation : un fauteuil roulant debout et un l\u00e8ve-personne multi-niveaux. Ces outils m\u00e9dicaux sont con\u00e7us et produits en interne par l&#8217;entreprise tha\u00eflandaise. Le fauteuil roulant permet aux patients de se mettre debout et facilite leur transfert vers une voiture, \u00e9vitant ainsi l&#8217;utilisation d&#8217;une ambulance ou d&#8217;un v\u00e9hicule adapt\u00e9. Cette invention est utilis\u00e9e \u00e0 la fois dans les maisons et les h\u00f4pitaux du pays. Pour plus d&#8217;informations, rendez-vous sur le site web de Cmed Medical.<cite>Generated by <a href=\"https:\/\/openai.com\/\">OpenAI<\/a><\/cite><\/p><\/blockquote>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cmed Medical pr\u00e9sente lors du salon Medical Fair Thailand 2023 sa nouvelle innovation : un fauteuil roulant debout et un l\u00e8ve-personne multi-niveaux. Ces outils m\u00e9dicaux sont con\u00e7us et produits en interne par l&#8217;entreprise tha\u00eflandaise. Le fauteuil roulant permet aux patients de se mettre debout et facilite leur transfert vers une voiture, \u00e9vitant ainsi l&#8217;utilisation d&#8217;une [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":47695,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[370],"tags":[34,65],"class_list":["post-47694","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-medicalfair-thailand_2023_09","tag-medical-care-health","tag-thailand","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[Salon m\u00e9dical Tha\u00eflande 2023] Fauteuil roulant debout u0026 Hoist Multi Lift - Cmed M\u00e9dical \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/medicalfair-thailand_2023_09\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Salon m\u00e9dical Tha\u00eflande 2023] Fauteuil roulant debout u0026 Hoist Multi Lift - Cmed M\u00e9dical \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"Cmed Medical pr\u00e9sente lors du salon Medical Fair Thailand 2023 sa nouvelle innovation : un fauteuil roulant debout et un l\u00e8ve-personne multi-niveaux. Ces outils m\u00e9dicaux sont con\u00e7us et produits en interne par l&#8217;entreprise tha\u00eflandaise. Le fauteuil roulant permet aux patients de se mettre debout et facilite leur transfert vers une voiture, \u00e9vitant ainsi l&#8217;utilisation d&#8217;une [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/medicalfair-thailand_2023_09\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-13T07:13:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/10\/maxresdefault-50.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicalfair-thailand_2023_09\\\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicalfair-thailand_2023_09\\\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"[Salon m\u00e9dical Tha\u00eflande 2023] Fauteuil roulant debout u0026 Hoist Multi Lift - Cmed M\u00e9dical\",\"datePublished\":\"2023-10-13T07:13:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicalfair-thailand_2023_09\\\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\\\/\"},\"wordCount\":115,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicalfair-thailand_2023_09\\\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/maxresdefault-50.jpg\",\"keywords\":[\"Soins m\u00e9dicaux \\\/ Sant\u00e9\",\"Tha\u00eflande\"],\"articleSection\":[\"Salon m\u00e9dical Tha\u00eflande 2023\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicalfair-thailand_2023_09\\\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicalfair-thailand_2023_09\\\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicalfair-thailand_2023_09\\\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\\\/\",\"name\":\"[Salon m\u00e9dical Tha\u00eflande 2023] Fauteuil roulant debout u0026 Hoist Multi Lift - Cmed M\u00e9dical \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicalfair-thailand_2023_09\\\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicalfair-thailand_2023_09\\\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/maxresdefault-50.jpg\",\"datePublished\":\"2023-10-13T07:13:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicalfair-thailand_2023_09\\\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicalfair-thailand_2023_09\\\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicalfair-thailand_2023_09\\\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/maxresdefault-50.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/maxresdefault-50.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicalfair-thailand_2023_09\\\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Salon m\u00e9dical Tha\u00eflande 2023] Fauteuil roulant debout u0026 Hoist Multi Lift - Cmed M\u00e9dical\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/pzh6gcTsgso\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"85\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[Salon m\u00e9dical Tha\u00eflande 2023] Fauteuil roulant debout u0026 Hoist Multi Lift - Cmed M\u00e9dical \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicalfair-thailand_2023_09\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\/","og_locale":"fr_FR","og_type":"article","og_title":"[Salon m\u00e9dical Tha\u00eflande 2023] Fauteuil roulant debout u0026 Hoist Multi Lift - Cmed M\u00e9dical \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"Cmed Medical pr\u00e9sente lors du salon Medical Fair Thailand 2023 sa nouvelle innovation : un fauteuil roulant debout et un l\u00e8ve-personne multi-niveaux. Ces outils m\u00e9dicaux sont con\u00e7us et produits en interne par l&#8217;entreprise tha\u00eflandaise. Le fauteuil roulant permet aux patients de se mettre debout et facilite leur transfert vers une voiture, \u00e9vitant ainsi l&#8217;utilisation d&#8217;une [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicalfair-thailand_2023_09\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2023-10-13T07:13:35+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/10\/maxresdefault-50.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicalfair-thailand_2023_09\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicalfair-thailand_2023_09\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"[Salon m\u00e9dical Tha\u00eflande 2023] Fauteuil roulant debout u0026 Hoist Multi Lift - Cmed M\u00e9dical","datePublished":"2023-10-13T07:13:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicalfair-thailand_2023_09\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\/"},"wordCount":115,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicalfair-thailand_2023_09\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/10\/maxresdefault-50.jpg","keywords":["Soins m\u00e9dicaux \/ Sant\u00e9","Tha\u00eflande"],"articleSection":["Salon m\u00e9dical Tha\u00eflande 2023"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/medicalfair-thailand_2023_09\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicalfair-thailand_2023_09\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicalfair-thailand_2023_09\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\/","name":"[Salon m\u00e9dical Tha\u00eflande 2023] Fauteuil roulant debout u0026 Hoist Multi Lift - Cmed M\u00e9dical \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicalfair-thailand_2023_09\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicalfair-thailand_2023_09\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/10\/maxresdefault-50.jpg","datePublished":"2023-10-13T07:13:35+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicalfair-thailand_2023_09\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/medicalfair-thailand_2023_09\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicalfair-thailand_2023_09\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/10\/maxresdefault-50.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/10\/maxresdefault-50.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicalfair-thailand_2023_09\/standing-wheelchair-u0026-hoist-multi-lift_cmed-medical\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"[Salon m\u00e9dical Tha\u00eflande 2023] Fauteuil roulant debout u0026 Hoist Multi Lift - Cmed M\u00e9dical"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/pzh6gcTsgso","og_video_type":"text\/html","og_video_duration":"85","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=pzh6gcTsgso","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/47694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=47694"}],"version-history":[{"count":0,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/47694\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/47695"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=47694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=47694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=47694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}