{"id":47087,"date":"2023-09-01T06:39:56","date_gmt":"2023-09-01T06:39:56","guid":{"rendered":"https:\/\/france.worldtradeshow.tv\/?p=47087"},"modified":"2023-09-01T06:39:56","modified_gmt":"2023-09-01T06:39:56","slug":"fans_super-duty-fans","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/awfsfair_2023_07\/fans_super-duty-fans\/","title":{"rendered":"[AWFS 2023 - Salon des fournisseurs de menuiserie et d'ameublement] VENTILATEURS - VENTILATEURS SUPER DUTY"},"content":{"rendered":"<blockquote class=\"wp-block-quote\"><p>La soci\u00e9t\u00e9 Super Duty Fans a r\u00e9cemment fait sensation au salon AWFS 2023 avec ses ventilateurs de plafond et de sol uniques et polyvalents. Avec un diam\u00e8tre pouvant atteindre 60 pouces, ces ventilateurs peuvent \u00eatre suspendus \u00e0 plat comme des pales ou \u00e0 des angles compos\u00e9s. De plus, ils sont \u00e9galement disponibles en version portable. Ces ventilateurs peuvent couvrir une surface de 3000 pieds carr\u00e9s et fournir jusqu&#8217;\u00e0 43 000 CFM d&#8217;air. Ils peuvent \u00eatre suspendus \u00e0 des hauteurs allant de 10 \u00e0 40 pieds, offrant ainsi une polyvalence et une facilit\u00e9 d&#8217;utilisation exceptionnelles. Le prix abordable des produits de Super Duty Fans en fait une option attrayante pour les clients. Pour plus d&#8217;informations, vous pouvez contacter Rob, le responsable national des ventes, sur superduityfans.com.<cite>Generated by <a href=\"https:\/\/openai.com\/\">OpenAI<\/a><\/cite><\/p><\/blockquote>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La soci\u00e9t\u00e9 Super Duty Fans a r\u00e9cemment fait sensation au salon AWFS 2023 avec ses ventilateurs de plafond et de sol uniques et polyvalents. Avec un diam\u00e8tre pouvant atteindre 60 pouces, ces ventilateurs peuvent \u00eatre suspendus \u00e0 plat comme des pales ou \u00e0 des angles compos\u00e9s. De plus, ils sont \u00e9galement disponibles en version portable. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":47088,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[357],"tags":[43,138,33],"class_list":["post-47087","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-awfsfair_2023_07","tag-agriculture-forestry-fishery-and-food","tag-usa","tag-machinery-industrial-technology","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[AWFS 2023 - Salon des fournisseurs de menuiserie et d&#039;ameublement] VENTILATEURS - VENTILATEURS SUPER DUTY \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/awfsfair_2023_07\/fans_super-duty-fans\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[AWFS 2023 - Salon des fournisseurs de menuiserie et d&#039;ameublement] VENTILATEURS - VENTILATEURS SUPER DUTY \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"La soci\u00e9t\u00e9 Super Duty Fans a r\u00e9cemment fait sensation au salon AWFS 2023 avec ses ventilateurs de plafond et de sol uniques et polyvalents. Avec un diam\u00e8tre pouvant atteindre 60 pouces, ces ventilateurs peuvent \u00eatre suspendus \u00e0 plat comme des pales ou \u00e0 des angles compos\u00e9s. De plus, ils sont \u00e9galement disponibles en version portable. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/awfsfair_2023_07\/fans_super-duty-fans\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-01T06:39:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/09\/maxresdefault-17.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/awfsfair_2023_07\\\/fans_super-duty-fans\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/awfsfair_2023_07\\\/fans_super-duty-fans\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"[AWFS 2023 - Salon des fournisseurs de menuiserie et d'ameublement] VENTILATEURS - VENTILATEURS SUPER DUTY\",\"datePublished\":\"2023-09-01T06:39:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/awfsfair_2023_07\\\/fans_super-duty-fans\\\/\"},\"wordCount\":141,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/awfsfair_2023_07\\\/fans_super-duty-fans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/maxresdefault-17.jpg\",\"keywords\":[\"Agriculture \\\/ For\u00eats \\\/ P\u00eache et nourriture\",\"Etats-Unis\",\"Machines \\\/ Technologie industrielle\"],\"articleSection\":[\"AWFS 2023 - Salon des fournisseurs de menuiserie et d'ameublement\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/awfsfair_2023_07\\\/fans_super-duty-fans\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/awfsfair_2023_07\\\/fans_super-duty-fans\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/awfsfair_2023_07\\\/fans_super-duty-fans\\\/\",\"name\":\"[AWFS 2023 - Salon des fournisseurs de menuiserie et d'ameublement] VENTILATEURS - VENTILATEURS SUPER DUTY \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/awfsfair_2023_07\\\/fans_super-duty-fans\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/awfsfair_2023_07\\\/fans_super-duty-fans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/maxresdefault-17.jpg\",\"datePublished\":\"2023-09-01T06:39:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/awfsfair_2023_07\\\/fans_super-duty-fans\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/awfsfair_2023_07\\\/fans_super-duty-fans\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/awfsfair_2023_07\\\/fans_super-duty-fans\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/maxresdefault-17.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/maxresdefault-17.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/awfsfair_2023_07\\\/fans_super-duty-fans\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[AWFS 2023 - Salon des fournisseurs de menuiserie et d'ameublement] VENTILATEURS - VENTILATEURS SUPER DUTY\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/gBX8kF4VNhM\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"58\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[AWFS 2023 - Salon des fournisseurs de menuiserie et d'ameublement] VENTILATEURS - VENTILATEURS SUPER DUTY \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/awfsfair_2023_07\/fans_super-duty-fans\/","og_locale":"fr_FR","og_type":"article","og_title":"[AWFS 2023 - Salon des fournisseurs de menuiserie et d'ameublement] VENTILATEURS - VENTILATEURS SUPER DUTY \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"La soci\u00e9t\u00e9 Super Duty Fans a r\u00e9cemment fait sensation au salon AWFS 2023 avec ses ventilateurs de plafond et de sol uniques et polyvalents. Avec un diam\u00e8tre pouvant atteindre 60 pouces, ces ventilateurs peuvent \u00eatre suspendus \u00e0 plat comme des pales ou \u00e0 des angles compos\u00e9s. De plus, ils sont \u00e9galement disponibles en version portable. [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/awfsfair_2023_07\/fans_super-duty-fans\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2023-09-01T06:39:56+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/09\/maxresdefault-17.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/awfsfair_2023_07\/fans_super-duty-fans\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/awfsfair_2023_07\/fans_super-duty-fans\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"[AWFS 2023 - Salon des fournisseurs de menuiserie et d'ameublement] VENTILATEURS - VENTILATEURS SUPER DUTY","datePublished":"2023-09-01T06:39:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/awfsfair_2023_07\/fans_super-duty-fans\/"},"wordCount":141,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/awfsfair_2023_07\/fans_super-duty-fans\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/09\/maxresdefault-17.jpg","keywords":["Agriculture \/ For\u00eats \/ P\u00eache et nourriture","Etats-Unis","Machines \/ Technologie industrielle"],"articleSection":["AWFS 2023 - Salon des fournisseurs de menuiserie et d'ameublement"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/awfsfair_2023_07\/fans_super-duty-fans\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/awfsfair_2023_07\/fans_super-duty-fans\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/awfsfair_2023_07\/fans_super-duty-fans\/","name":"[AWFS 2023 - Salon des fournisseurs de menuiserie et d'ameublement] VENTILATEURS - VENTILATEURS SUPER DUTY \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/awfsfair_2023_07\/fans_super-duty-fans\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/awfsfair_2023_07\/fans_super-duty-fans\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/09\/maxresdefault-17.jpg","datePublished":"2023-09-01T06:39:56+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/awfsfair_2023_07\/fans_super-duty-fans\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/awfsfair_2023_07\/fans_super-duty-fans\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/awfsfair_2023_07\/fans_super-duty-fans\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/09\/maxresdefault-17.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/09\/maxresdefault-17.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/awfsfair_2023_07\/fans_super-duty-fans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"[AWFS 2023 - Salon des fournisseurs de menuiserie et d'ameublement] VENTILATEURS - VENTILATEURS SUPER DUTY"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/gBX8kF4VNhM","og_video_type":"text\/html","og_video_duration":"58","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=gBX8kF4VNhM","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/47087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=47087"}],"version-history":[{"count":0,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/47087\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/47088"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=47087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=47087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=47087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}