{"id":44591,"date":"2023-03-17T02:27:48","date_gmt":"2023-03-17T02:27:48","guid":{"rendered":"https:\/\/france.worldtradeshow.tv\/?p=44591"},"modified":"2023-03-17T02:27:48","modified_gmt":"2023-03-17T02:27:48","slug":"impression-filters_arri","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/exposition-bsc-2023\/impression-filters_arri\/","title":{"rendered":"[Exposition BSC 2023] Filtres d'impressions - ARRI"},"content":{"rendered":"<blockquote class=\"wp-block-quote\"><p>ARRI, l&#8217;un des principaux fabricants d&#8217;appareils photo et d&#8217;\u00e9quipements d&#8217;\u00e9clairage, a d\u00e9voil\u00e9 sa nouvelle gamme de filtres d&#8217;impression pour l&#8217;objectif Signature Prime au BSC Expo 2023. Les filtres, qui sont magn\u00e9tiques et se fixent \u00e0 l&#8217;arri\u00e8re de l&#8217;objectif, sont disponibles en quatre jeux de dioptries positives et quatre ensembles de dioptries n\u00e9gatives, avec des forces variables jusqu&#8217;\u00e0 un positif de 330p et un n\u00e9gatif de 290n. Selon Tom Murphy d&#8217;ARRI, ces filtres permettent aux cin\u00e9astes d'&#8221;int\u00e9grer&#8221; leur choix d&#8217;image au dos du verre, \u00e9liminant ainsi le besoin de les placer devant la matte box.<br \/>Les filtres sont \u00e9galement petits, ce qui r\u00e9duit le risque qu&#8217;ils soient ray\u00e9s, et ils peuvent \u00eatre utilis\u00e9s sur des cardans, des drones et des Steadicam. ARRI est sur le point de sortir des films qui pr\u00e9sentent les diff\u00e9rents effets des filtres sur l&#8217;objectif Signature Prime.<br \/>En plus des filtres d&#8217;impression, ARRI a \u00e9galement pr\u00e9sent\u00e9 son ensemble Signature Zoom, qui se marie parfaitement avec les Signature Primes. La soci\u00e9t\u00e9 a \u00e9galement montr\u00e9 comment faire correspondre le mini LF sur son nouvel appareil photo, l&#8217;Alexa 35.<br \/>Au BSC Expo 2023, ARRI a \u00e9galement pr\u00e9sent\u00e9 son histoire de fabrication d&#8217;appareils photo depuis plus de 100 ans. Le stand pr\u00e9sentait certains de ses anciens appareils photo, dont un Canary de 1927 et un Ariflex 35 de 1937. L&#8217;exposition t\u00e9moigne de l&#8217;engagement de longue date d&#8217;ARRI envers l&#8217;industrie cin\u00e9matographique et de son innovation continue pour am\u00e9liorer le processus de r\u00e9alisation.<br \/><cite>Generated by <a href=\"https:\/\/openai.com\/\">OpenAI<\/a><\/cite><\/p><\/blockquote>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bscexpo_2023_02\/bscexpo_2023_02_08-1.jpg\"><\/div>\n<div class=\"caption_text\">Bonjour, je suis Tom Murphy d&#8217;ARRI, nous avons pens\u00e9 que ce serait une bonne id\u00e9e de vous montrer ce que nous montrons sur le stand \u00e0 la BSC Expo 2023.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bscexpo_2023_02\/bscexpo_2023_02_08-8.jpg\"><\/div>\n<div class=\"caption_text\">La nouveaut\u00e9 que nous pr\u00e9sentons aujourd&#8217;hui sur le stand est notre nouvelle gamme de filtres d&#8217;impression.<br \/>Ils sont pour la signature\u00a0Prime et ils sont un filtre magn\u00e9tique qui va \u00e0 l&#8217;arri\u00e8re.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bscexpo_2023_02\/bscexpo_2023_02_08-15.jpg\"><\/div>\n<div class=\"caption_text\">Nous avons donc quatre ensembles de dioptries positives\u00a0et quatre ensembles de dioptries n\u00e9gatives.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bscexpo_2023_02\/bscexpo_2023_02_08-22.jpg\"><\/div>\n<div class=\"caption_text\">Ils augmentent dans diff\u00e9rentes forces, le plus \u00e9lev\u00e9 \u00e9tant un\u00a0330p positif et un n\u00e9gatif 290n.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bscexpo_2023_02\/bscexpo_2023_02_08-29.jpg\"><\/div>\n<div class=\"caption_text\">La meilleure fa\u00e7on d&#8217;y penser est que le 330p se rapporte \u00e0 une dioptrie positive de 3,3 et le 290n se rapporte \u00e0 une dioptrie n\u00e9gative de 2,9.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bscexpo_2023_02\/bscexpo_2023_02_08-36.jpg\"><\/div>\n<div class=\"caption_text\">Nous avons des films qui sortent au cours des deux prochaines semaines, nous pourrons vous montrer comment ces diff\u00e9rentes dioptries peuvent affecter l&#8217;apparence d&#8217;un Prime signature.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bscexpo_2023_02\/bscexpo_2023_02_08-43.jpg\"><\/div>\n<div class=\"caption_text\">La beaut\u00e9 de ces filtres r\u00e9side dans le fait qu&#8217;ils se placent \u00e0 l&#8217;arri\u00e8re de l&#8217;objectif\u00a0et que vous pr\u00e9parez ensuite votre choix d&#8217;image \u00e0 l&#8217;arri\u00e8re de ce verre.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bscexpo_2023_02\/bscexpo_2023_02_08-50.jpg\"><\/div>\n<div class=\"caption_text\">Tout ce qu&#8217;ils font, c&#8217;est juste se clipser \u00e0 l&#8217;arri\u00e8re, ils sont tr\u00e8s tr\u00e8s petits, donc vous risquez moins de les rayer, cela signifie que vous n&#8217;avez pas besoin de les mettre devant la bo\u00eete de carte.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bscexpo_2023_02\/bscexpo_2023_02_08-57.jpg\"><\/div>\n<div class=\"caption_text\">Et vous pouvez \u00e9galement les piloter sur des drones \u00e0 cardan et Steadicam.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bscexpo_2023_02\/bscexpo_2023_02_08-64.jpg\"><\/div>\n<div class=\"caption_text\">Nous montrons \u00e9galement un certain nombre d&#8217;autres choses dans l&#8217;\u00e9mission, nous avons \u00e9galement notre ensemble de zoom de signature afin qu&#8217;ils s&#8217;associent parfaitement avec les primes de signature et nous essayons \u00e9galement de montrer comment vous pouvez correspondre au mini LF sur notre nouvel appareil photo l&#8217;Alexa 35.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bscexpo_2023_02\/bscexpo_2023_02_08-71.jpg\"><\/div>\n<div class=\"caption_text\">Sur le stand aujourd&#8217;hui, nous montrons \u00e9galement que nous fabriquons des appareils photo depuis plus de 100\u00a0ans, nous avons donc certains de nos anciens appareils photo, nous avons un canari de 1927 et un ariflex 35 de 1937. <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ARRI, l&#8217;un des principaux fabricants d&#8217;appareils photo et d&#8217;\u00e9quipements d&#8217;\u00e9clairage, a d\u00e9voil\u00e9 sa nouvelle gamme de filtres d&#8217;impression pour l&#8217;objectif Signature Prime au BSC Expo 2023. Les filtres, qui sont magn\u00e9tiques et se fixent \u00e0 l&#8217;arri\u00e8re de l&#8217;objectif, sont disponibles en quatre jeux de dioptries positives et quatre ensembles de dioptries n\u00e9gatives, avec des forces [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":44592,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[292],"tags":[30,33,88],"class_list":["post-44591","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-exposition-bsc-2023","tag-hobby-education","tag-machinery-industrial-technology","tag-united-kingdom","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[Exposition BSC 2023] Filtres d&#039;impressions - ARRI \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/exposition-bsc-2023\/impression-filters_arri\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Exposition BSC 2023] Filtres d&#039;impressions - ARRI \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"ARRI, l&#8217;un des principaux fabricants d&#8217;appareils photo et d&#8217;\u00e9quipements d&#8217;\u00e9clairage, a d\u00e9voil\u00e9 sa nouvelle gamme de filtres d&#8217;impression pour l&#8217;objectif Signature Prime au BSC Expo 2023. Les filtres, qui sont magn\u00e9tiques et se fixent \u00e0 l&#8217;arri\u00e8re de l&#8217;objectif, sont disponibles en quatre jeux de dioptries positives et quatre ensembles de dioptries n\u00e9gatives, avec des forces [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/exposition-bsc-2023\/impression-filters_arri\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-17T02:27:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/03\/maxresdefault-91.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/exposition-bsc-2023\\\/impression-filters_arri\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/exposition-bsc-2023\\\/impression-filters_arri\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"[Exposition BSC 2023] Filtres d'impressions - ARRI\",\"datePublished\":\"2023-03-17T02:27:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/exposition-bsc-2023\\\/impression-filters_arri\\\/\"},\"wordCount\":618,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/exposition-bsc-2023\\\/impression-filters_arri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/maxresdefault-91.jpg\",\"keywords\":[\"Hobby \\\/ Education\",\"Machines \\\/ Technologie industrielle\",\"Royaume-Uni\"],\"articleSection\":[\"Exposition BSC 2023\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/exposition-bsc-2023\\\/impression-filters_arri\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/exposition-bsc-2023\\\/impression-filters_arri\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/exposition-bsc-2023\\\/impression-filters_arri\\\/\",\"name\":\"[Exposition BSC 2023] Filtres d'impressions - ARRI \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/exposition-bsc-2023\\\/impression-filters_arri\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/exposition-bsc-2023\\\/impression-filters_arri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/maxresdefault-91.jpg\",\"datePublished\":\"2023-03-17T02:27:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/exposition-bsc-2023\\\/impression-filters_arri\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/exposition-bsc-2023\\\/impression-filters_arri\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/exposition-bsc-2023\\\/impression-filters_arri\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/maxresdefault-91.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/maxresdefault-91.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/exposition-bsc-2023\\\/impression-filters_arri\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Exposition BSC 2023] Filtres d'impressions - ARRI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/vRw8mchp5Ms\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"91\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[Exposition BSC 2023] Filtres d'impressions - ARRI \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/exposition-bsc-2023\/impression-filters_arri\/","og_locale":"fr_FR","og_type":"article","og_title":"[Exposition BSC 2023] Filtres d'impressions - ARRI \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"ARRI, l&#8217;un des principaux fabricants d&#8217;appareils photo et d&#8217;\u00e9quipements d&#8217;\u00e9clairage, a d\u00e9voil\u00e9 sa nouvelle gamme de filtres d&#8217;impression pour l&#8217;objectif Signature Prime au BSC Expo 2023. Les filtres, qui sont magn\u00e9tiques et se fixent \u00e0 l&#8217;arri\u00e8re de l&#8217;objectif, sont disponibles en quatre jeux de dioptries positives et quatre ensembles de dioptries n\u00e9gatives, avec des forces [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/exposition-bsc-2023\/impression-filters_arri\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2023-03-17T02:27:48+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/03\/maxresdefault-91.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/exposition-bsc-2023\/impression-filters_arri\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/exposition-bsc-2023\/impression-filters_arri\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"[Exposition BSC 2023] Filtres d'impressions - ARRI","datePublished":"2023-03-17T02:27:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/exposition-bsc-2023\/impression-filters_arri\/"},"wordCount":618,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/exposition-bsc-2023\/impression-filters_arri\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/03\/maxresdefault-91.jpg","keywords":["Hobby \/ Education","Machines \/ Technologie industrielle","Royaume-Uni"],"articleSection":["Exposition BSC 2023"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/exposition-bsc-2023\/impression-filters_arri\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/exposition-bsc-2023\/impression-filters_arri\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/exposition-bsc-2023\/impression-filters_arri\/","name":"[Exposition BSC 2023] Filtres d'impressions - ARRI \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/exposition-bsc-2023\/impression-filters_arri\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/exposition-bsc-2023\/impression-filters_arri\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/03\/maxresdefault-91.jpg","datePublished":"2023-03-17T02:27:48+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/exposition-bsc-2023\/impression-filters_arri\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/exposition-bsc-2023\/impression-filters_arri\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/exposition-bsc-2023\/impression-filters_arri\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/03\/maxresdefault-91.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/03\/maxresdefault-91.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/exposition-bsc-2023\/impression-filters_arri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"[Exposition BSC 2023] Filtres d'impressions - ARRI"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/vRw8mchp5Ms","og_video_type":"text\/html","og_video_duration":"91","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=vRw8mchp5Ms","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/44591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=44591"}],"version-history":[{"count":0,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/44591\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/44592"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=44591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=44591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=44591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}