{"id":43703,"date":"2023-01-24T07:08:31","date_gmt":"2023-01-24T07:08:31","guid":{"rendered":"https:\/\/france.worldtradeshow.tv\/?p=43703"},"modified":"2023-01-24T07:08:31","modified_gmt":"2023-01-24T07:08:31","slug":"a-fully-automatic-and-interactive-device-handy_handy","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/ces-2023-evenement-technologique-de-la-consumer-technology-association\/a-fully-automatic-and-interactive-device-handy_handy\/","title":{"rendered":"[CES 2023 - \u00c9v\u00e9nement technologique de la Consumer Technology Association] Un appareil enti\u00e8rement automatique et interactif : pratique - PRATIQUE"},"content":{"rendered":"<p>PRATIQUE a expos\u00e9 Un appareil enti\u00e8rement automatique et interactif : pratique \u00e0 CES 2023 &#8211; \u00c9v\u00e9nement technologique de la Consumer Technology Association.<\/p>\n<\/p>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/ces_2023_01\/ces_2023_01_10-1.jpg\"><\/div>\n<div class=\"caption_text\">Salut, je m&#8217;appelle Peter Williamson ou JP.<br \/>Je suis le PDG et co-fondateur de l&#8217;entreprise \u00e0 l&#8217;origine de handy.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/ces_2023_01\/ces_2023_01_10-8.jpg\"><\/div>\n<div class=\"caption_text\">Un masturbateur enti\u00e8rement automatique et interactif ici au CES 2023.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/ces_2023_01\/ces_2023_01_10-15.jpg\"><\/div>\n<div class=\"caption_text\">Il s&#8217;agit d&#8217;un masturbateur universel et inclusif taille unique jusqu&#8217;\u00e0 600 coups par minute.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/ces_2023_01\/ces_2023_01_10-22.jpg\"><\/div>\n<div class=\"caption_text\">11 centim\u00e8tres de longueur de trait, la beaut\u00e9 \u00e0 ce sujet est que vous montez le p\u00e9nis \u00e0 l&#8217;ext\u00e9rieur, donc peu importe s&#8217;il s&#8217;agit d&#8217;un stylo ou d&#8217;une canette, il s&#8217;adaptera.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/ces_2023_01\/ces_2023_01_10-36.jpg\"><\/div>\n<div class=\"caption_text\">Diff\u00e9rentes manches diff\u00e9rentes Sensations\u00a0nous avons donc une vari\u00e9t\u00e9 de manches diff\u00e9rentes.<br \/>Nous pouvons \u00e9galement utiliser des manchons d&#8217;autres marques comme Tenga ou\u00a0Fleshlight go.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/ces_2023_01\/ces_2023_01_10-43.jpg\"><\/div>\n<div class=\"caption_text\">La fa\u00e7on dont vous l&#8217;utilisez en mode hors ligne consiste essentiellement \u00e0 tenir votre os pelvien et \u00e0 le contr\u00f4ler depuis l&#8217;avant du maniable.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/ces_2023_01\/ces_2023_01_10-50.jpg\"><\/div>\n<div class=\"caption_text\">Ils peuvent contr\u00f4ler la vitesse et la longueur des coups jusqu&#8217;\u00e0 800\u00a0coups par minute.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/ces_2023_01\/ces_2023_01_10-57.jpg\"><\/div>\n<div class=\"caption_text\">Donc, le vrai plaisir commence lorsque vous vous connectez\u00a0avec cet appareil.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/ces_2023_01\/ces_2023_01_10-64.jpg\"><\/div>\n<div class=\"caption_text\">Comme vous pouvez le voir sur cette tablette.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/ces_2023_01\/ces_2023_01_10-71.jpg\"><\/div>\n<div class=\"caption_text\">Voyons.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/ces_2023_01\/ces_2023_01_10-78.jpg\"><\/div>\n<div class=\"caption_text\">Vous pouvez contr\u00f4ler \u00e0 distance des unit\u00e9s depuis n&#8217;importe o\u00f9 dans le monde.<br \/>Et d\u00e9sol\u00e9, je dois juste y \u00eatre &#8230; et faire exactement le m\u00eame type de modification de l&#8217;appareil de la vitesse \u00e0 la zone de course.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/ces_2023_01\/ces_2023_01_10-92.jpg\"><\/div>\n<div class=\"caption_text\">Ainsi, votre partenaire \u00e0 l&#8217;autre bout du monde peut essentiellement contr\u00f4ler le maniable.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/ces_2023_01\/ces_2023_01_10-99.jpg\"><\/div>\n<div class=\"caption_text\">Et cr\u00e9ez une session pour vous.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/ces_2023_01\/ces_2023_01_10-106.jpg\"><\/div>\n<div class=\"caption_text\">En plus de cela, nous avons fait \u00e9quipe avec plusieurs partenaires de contenu, de jeux et d&#8217;audio pour adultes, o\u00f9\u00a0la pratique est synchronis\u00e9e avec cela.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/ces_2023_01\/ces_2023_01_10-113.jpg\"><\/div>\n<div class=\"caption_text\">Qu&#8217;est-ce que cela signifie bien si vous regardez ici, cela signifie essentiellement que pour les vid\u00e9os que vous souhaitez regarder, cela se synchronise avec le pratique.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/ces_2023_01\/ces_2023_01_10-127.jpg\"><\/div>\n<div class=\"caption_text\">Nous avons donc plus de\u00a020\u00a0000\u00a0films, de Flats \u00e0 VR, o\u00f9 vous pourrez ensuite d\u00e9couvrir la sensation haptique de la technologie\u00a0immersive.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/ces_2023_01\/ces_2023_01_10-134.jpg\"><\/div>\n<div class=\"caption_text\">Ainsi, avec pratique, vous pouvez l&#8217;utiliser hors ligne et autonome ou vous pouvez le connecter au Wi-Fi et explorer l&#8217;avenir de la sextech.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/ces_2023_01\/ces_2023_01_10-141.jpg\"><\/div>\n<div class=\"caption_text\">Merci. <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>PRATIQUE a expos\u00e9 Un appareil enti\u00e8rement automatique et interactif : pratique \u00e0 CES 2023 &#8211; \u00c9v\u00e9nement technologique de la Consumer Technology Association. Salut, je m&#8217;appelle Peter Williamson ou JP.Je suis le PDG et co-fondateur de l&#8217;entreprise \u00e0 l&#8217;origine de handy. Un masturbateur enti\u00e8rement automatique et interactif ici au CES 2023. Il s&#8217;agit d&#8217;un masturbateur universel [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":43704,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[275],"tags":[138,31,33,36],"class_list":["post-43703","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-ces-2023-evenement-technologique-de-la-consumer-technology-association","tag-usa","tag-information-telecommunication","tag-machinery-industrial-technology","tag-services","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[CES 2023 - \u00c9v\u00e9nement technologique de la Consumer Technology Association] Un appareil enti\u00e8rement automatique et interactif : pratique - PRATIQUE \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/ces-2023-evenement-technologique-de-la-consumer-technology-association\/a-fully-automatic-and-interactive-device-handy_handy\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[CES 2023 - \u00c9v\u00e9nement technologique de la Consumer Technology Association] Un appareil enti\u00e8rement automatique et interactif : pratique - PRATIQUE \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"PRATIQUE a expos\u00e9 Un appareil enti\u00e8rement automatique et interactif : pratique \u00e0 CES 2023 &#8211; \u00c9v\u00e9nement technologique de la Consumer Technology Association. Salut, je m&#8217;appelle Peter Williamson ou JP.Je suis le PDG et co-fondateur de l&#8217;entreprise \u00e0 l&#8217;origine de handy. Un masturbateur enti\u00e8rement automatique et interactif ici au CES 2023. Il s&#8217;agit d&#8217;un masturbateur universel [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/ces-2023-evenement-technologique-de-la-consumer-technology-association\/a-fully-automatic-and-interactive-device-handy_handy\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-24T07:08:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/01\/maxresdefault-37.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/ces-2023-evenement-technologique-de-la-consumer-technology-association\\\/a-fully-automatic-and-interactive-device-handy_handy\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/ces-2023-evenement-technologique-de-la-consumer-technology-association\\\/a-fully-automatic-and-interactive-device-handy_handy\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"[CES 2023 - \u00c9v\u00e9nement technologique de la Consumer Technology Association] Un appareil enti\u00e8rement automatique et interactif : pratique - PRATIQUE\",\"datePublished\":\"2023-01-24T07:08:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/ces-2023-evenement-technologique-de-la-consumer-technology-association\\\/a-fully-automatic-and-interactive-device-handy_handy\\\/\"},\"wordCount\":383,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/ces-2023-evenement-technologique-de-la-consumer-technology-association\\\/a-fully-automatic-and-interactive-device-handy_handy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/maxresdefault-37.jpg\",\"keywords\":[\"Etats-Unis\",\"Information \\\/ T\u00e9l\u00e9communication\",\"Machines \\\/ Technologie industrielle\",\"Prestations de service\"],\"articleSection\":[\"CES 2023 - \u00c9v\u00e9nement technologique de la Consumer Technology Association\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/ces-2023-evenement-technologique-de-la-consumer-technology-association\\\/a-fully-automatic-and-interactive-device-handy_handy\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/ces-2023-evenement-technologique-de-la-consumer-technology-association\\\/a-fully-automatic-and-interactive-device-handy_handy\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/ces-2023-evenement-technologique-de-la-consumer-technology-association\\\/a-fully-automatic-and-interactive-device-handy_handy\\\/\",\"name\":\"[CES 2023 - \u00c9v\u00e9nement technologique de la Consumer Technology Association] Un appareil enti\u00e8rement automatique et interactif : pratique - PRATIQUE \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/ces-2023-evenement-technologique-de-la-consumer-technology-association\\\/a-fully-automatic-and-interactive-device-handy_handy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/ces-2023-evenement-technologique-de-la-consumer-technology-association\\\/a-fully-automatic-and-interactive-device-handy_handy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/maxresdefault-37.jpg\",\"datePublished\":\"2023-01-24T07:08:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/ces-2023-evenement-technologique-de-la-consumer-technology-association\\\/a-fully-automatic-and-interactive-device-handy_handy\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/ces-2023-evenement-technologique-de-la-consumer-technology-association\\\/a-fully-automatic-and-interactive-device-handy_handy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/ces-2023-evenement-technologique-de-la-consumer-technology-association\\\/a-fully-automatic-and-interactive-device-handy_handy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/maxresdefault-37.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/maxresdefault-37.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/ces-2023-evenement-technologique-de-la-consumer-technology-association\\\/a-fully-automatic-and-interactive-device-handy_handy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[CES 2023 - \u00c9v\u00e9nement technologique de la Consumer Technology Association] Un appareil enti\u00e8rement automatique et interactif : pratique - PRATIQUE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/QnTriiQovi0\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"155\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[CES 2023 - \u00c9v\u00e9nement technologique de la Consumer Technology Association] Un appareil enti\u00e8rement automatique et interactif : pratique - PRATIQUE \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/ces-2023-evenement-technologique-de-la-consumer-technology-association\/a-fully-automatic-and-interactive-device-handy_handy\/","og_locale":"fr_FR","og_type":"article","og_title":"[CES 2023 - \u00c9v\u00e9nement technologique de la Consumer Technology Association] Un appareil enti\u00e8rement automatique et interactif : pratique - PRATIQUE \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"PRATIQUE a expos\u00e9 Un appareil enti\u00e8rement automatique et interactif : pratique \u00e0 CES 2023 &#8211; \u00c9v\u00e9nement technologique de la Consumer Technology Association. Salut, je m&#8217;appelle Peter Williamson ou JP.Je suis le PDG et co-fondateur de l&#8217;entreprise \u00e0 l&#8217;origine de handy. Un masturbateur enti\u00e8rement automatique et interactif ici au CES 2023. Il s&#8217;agit d&#8217;un masturbateur universel [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/ces-2023-evenement-technologique-de-la-consumer-technology-association\/a-fully-automatic-and-interactive-device-handy_handy\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2023-01-24T07:08:31+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/01\/maxresdefault-37.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/ces-2023-evenement-technologique-de-la-consumer-technology-association\/a-fully-automatic-and-interactive-device-handy_handy\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/ces-2023-evenement-technologique-de-la-consumer-technology-association\/a-fully-automatic-and-interactive-device-handy_handy\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"[CES 2023 - \u00c9v\u00e9nement technologique de la Consumer Technology Association] Un appareil enti\u00e8rement automatique et interactif : pratique - PRATIQUE","datePublished":"2023-01-24T07:08:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/ces-2023-evenement-technologique-de-la-consumer-technology-association\/a-fully-automatic-and-interactive-device-handy_handy\/"},"wordCount":383,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/ces-2023-evenement-technologique-de-la-consumer-technology-association\/a-fully-automatic-and-interactive-device-handy_handy\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/01\/maxresdefault-37.jpg","keywords":["Etats-Unis","Information \/ T\u00e9l\u00e9communication","Machines \/ Technologie industrielle","Prestations de service"],"articleSection":["CES 2023 - \u00c9v\u00e9nement technologique de la Consumer Technology Association"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/ces-2023-evenement-technologique-de-la-consumer-technology-association\/a-fully-automatic-and-interactive-device-handy_handy\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/ces-2023-evenement-technologique-de-la-consumer-technology-association\/a-fully-automatic-and-interactive-device-handy_handy\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/ces-2023-evenement-technologique-de-la-consumer-technology-association\/a-fully-automatic-and-interactive-device-handy_handy\/","name":"[CES 2023 - \u00c9v\u00e9nement technologique de la Consumer Technology Association] Un appareil enti\u00e8rement automatique et interactif : pratique - PRATIQUE \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/ces-2023-evenement-technologique-de-la-consumer-technology-association\/a-fully-automatic-and-interactive-device-handy_handy\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/ces-2023-evenement-technologique-de-la-consumer-technology-association\/a-fully-automatic-and-interactive-device-handy_handy\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/01\/maxresdefault-37.jpg","datePublished":"2023-01-24T07:08:31+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/ces-2023-evenement-technologique-de-la-consumer-technology-association\/a-fully-automatic-and-interactive-device-handy_handy\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/ces-2023-evenement-technologique-de-la-consumer-technology-association\/a-fully-automatic-and-interactive-device-handy_handy\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/ces-2023-evenement-technologique-de-la-consumer-technology-association\/a-fully-automatic-and-interactive-device-handy_handy\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/01\/maxresdefault-37.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2023\/01\/maxresdefault-37.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/ces-2023-evenement-technologique-de-la-consumer-technology-association\/a-fully-automatic-and-interactive-device-handy_handy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"[CES 2023 - \u00c9v\u00e9nement technologique de la Consumer Technology Association] Un appareil enti\u00e8rement automatique et interactif : pratique - PRATIQUE"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/QnTriiQovi0","og_video_type":"text\/html","og_video_duration":"155","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=QnTriiQovi0","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/43703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=43703"}],"version-history":[{"count":0,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/43703\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/43704"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=43703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=43703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=43703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}