{"id":43029,"date":"2022-11-29T08:03:12","date_gmt":"2022-11-29T08:03:12","guid":{"rendered":"https:\/\/france.worldtradeshow.tv\/?p=43029"},"modified":"2022-11-29T08:03:12","modified_gmt":"2022-11-29T08:03:12","slug":"popcorn_secret-bake","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\/popcorn_secret-bake\/","title":{"rendered":"[TRAFS - commerce de d\u00e9tail, restauration et services d'accueil en tha\u00eflande 2022] Pop corn - Cuisson secr\u00e8te"},"content":{"rendered":"<p>Cuisson secr\u00e8te a expos\u00e9 Pop corn \u00e0 TRAFS &#8211; commerce de d\u00e9tail, restauration et services d&#8217;accueil en tha\u00eflande 2022.<\/p>\n<\/p>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/trafs_2022_10\/trafs_2022_10_13-1.jpg\"><\/div>\n<div class=\"caption_text\">Bonjour, voici notre stand Secret Bake, qui se concentre uniquement sur le pop-corn.<br \/>Il existe maintenant 11 saveurs au total, acceptant d\u00e9sormais la production OEM, \u00e0 la fois au d\u00e9tail et en gros.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/trafs_2022_10\/trafs_2022_10_13-2.jpg\"><\/div>\n<div class=\"caption_text\">Les canaux de contact sont Facebook, Instagram et Line. Vous pouvez nous ajouter.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/trafs_2022_10\/trafs_2022_10_13-3.jpg\"><\/div>\n<div class=\"caption_text\">Notre particularit\u00e9 est d&#8217;utiliser 100% de vrai beurre.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/trafs_2022_10\/trafs_2022_10_13-4.jpg\"><\/div>\n<div class=\"caption_text\">Nous utilisons du ma\u00efs champignon en forme de champignon, sans margarine, sans additifs, sans shortening.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/trafs_2022_10\/trafs_2022_10_13-5.jpg\"><\/div>\n<div class=\"caption_text\">L&#8217;int\u00e9rieur est rempli d&#8217;amandes et de noix de cajou.<br \/>\u00c0 l&#8217;int\u00e9rieur se trouve un capuchon en aluminium comme celui-ci.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/trafs_2022_10\/trafs_2022_10_13-6.jpg\"><\/div>\n<div class=\"caption_text\">Il se conserve deux mois, en tailles S, M, L.<br \/>Une autre diff\u00e9rence est que nos produits utilisent des ingr\u00e9dients 100 % naturels.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/trafs_2022_10\/trafs_2022_10_13-7.jpg\"><\/div>\n<div class=\"caption_text\">Pas de poudre d&#8217;assaisonnement.<br \/>Les best-sellers sont le caramel et le chocolat noir.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/trafs_2022_10\/trafs_2022_10_13-8.jpg\"><\/div>\n<div class=\"caption_text\">Le reste sera du caf\u00e9, de la p\u00e2te de piment avec de la soie de poulet, de la fraise, de la myrtille, du durian, de l&#8217;\u0153uf sal\u00e9, du th\u00e9 vert et du mil.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/trafs_2022_10\/trafs_2022_10_13-9.jpg\"><\/div>\n<div class=\"caption_text\">Il y aura 3-4 autres saveurs \u00e0 l&#8217;avenir. <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cuisson secr\u00e8te a expos\u00e9 Pop corn \u00e0 TRAFS &#8211; commerce de d\u00e9tail, restauration et services d&#8217;accueil en tha\u00eflande 2022. Bonjour, voici notre stand Secret Bake, qui se concentre uniquement sur le pop-corn.Il existe maintenant 11 saveurs au total, acceptant d\u00e9sormais la production OEM, \u00e0 la fois au d\u00e9tail et en gros. Les canaux de contact [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":43030,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[250],"tags":[43,65,37,42],"class_list":["post-43029","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022","tag-agriculture-forestry-fishery-and-food","tag-thailand","tag-transportation-logistics-packaging","tag-living","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[TRAFS - commerce de d\u00e9tail, restauration et services d&#039;accueil en tha\u00eflande 2022] Pop corn - Cuisson secr\u00e8te \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\/popcorn_secret-bake\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[TRAFS - commerce de d\u00e9tail, restauration et services d&#039;accueil en tha\u00eflande 2022] Pop corn - Cuisson secr\u00e8te \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"Cuisson secr\u00e8te a expos\u00e9 Pop corn \u00e0 TRAFS &#8211; commerce de d\u00e9tail, restauration et services d&#8217;accueil en tha\u00eflande 2022. Bonjour, voici notre stand Secret Bake, qui se concentre uniquement sur le pop-corn.Il existe maintenant 11 saveurs au total, acceptant d\u00e9sormais la production OEM, \u00e0 la fois au d\u00e9tail et en gros. Les canaux de contact [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\/popcorn_secret-bake\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-29T08:03:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/11\/maxresdefault-116.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\\\/popcorn_secret-bake\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\\\/popcorn_secret-bake\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"[TRAFS - commerce de d\u00e9tail, restauration et services d'accueil en tha\u00eflande 2022] Pop corn - Cuisson secr\u00e8te\",\"datePublished\":\"2022-11-29T08:03:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\\\/popcorn_secret-bake\\\/\"},\"wordCount\":214,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\\\/popcorn_secret-bake\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/maxresdefault-116.jpg\",\"keywords\":[\"Agriculture \\\/ For\u00eats \\\/ P\u00eache et nourriture\",\"Tha\u00eflande\",\"Transport \\\/ Logistique \\\/ Emballage\",\"Vivant\"],\"articleSection\":[\"TRAFS - commerce de d\u00e9tail. restauration et services d'accueil en tha\u00eflande 2022\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\\\/popcorn_secret-bake\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\\\/popcorn_secret-bake\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\\\/popcorn_secret-bake\\\/\",\"name\":\"[TRAFS - commerce de d\u00e9tail, restauration et services d'accueil en tha\u00eflande 2022] Pop corn - Cuisson secr\u00e8te \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\\\/popcorn_secret-bake\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\\\/popcorn_secret-bake\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/maxresdefault-116.jpg\",\"datePublished\":\"2022-11-29T08:03:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\\\/popcorn_secret-bake\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\\\/popcorn_secret-bake\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\\\/popcorn_secret-bake\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/maxresdefault-116.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/maxresdefault-116.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\\\/popcorn_secret-bake\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[TRAFS - commerce de d\u00e9tail, restauration et services d'accueil en tha\u00eflande 2022] Pop corn - Cuisson secr\u00e8te\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/9uiT5JTx_jI\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"68\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[TRAFS - commerce de d\u00e9tail, restauration et services d'accueil en tha\u00eflande 2022] Pop corn - Cuisson secr\u00e8te \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\/popcorn_secret-bake\/","og_locale":"fr_FR","og_type":"article","og_title":"[TRAFS - commerce de d\u00e9tail, restauration et services d'accueil en tha\u00eflande 2022] Pop corn - Cuisson secr\u00e8te \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"Cuisson secr\u00e8te a expos\u00e9 Pop corn \u00e0 TRAFS &#8211; commerce de d\u00e9tail, restauration et services d&#8217;accueil en tha\u00eflande 2022. Bonjour, voici notre stand Secret Bake, qui se concentre uniquement sur le pop-corn.Il existe maintenant 11 saveurs au total, acceptant d\u00e9sormais la production OEM, \u00e0 la fois au d\u00e9tail et en gros. Les canaux de contact [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\/popcorn_secret-bake\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2022-11-29T08:03:12+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/11\/maxresdefault-116.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\/popcorn_secret-bake\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\/popcorn_secret-bake\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"[TRAFS - commerce de d\u00e9tail, restauration et services d'accueil en tha\u00eflande 2022] Pop corn - Cuisson secr\u00e8te","datePublished":"2022-11-29T08:03:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\/popcorn_secret-bake\/"},"wordCount":214,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\/popcorn_secret-bake\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/11\/maxresdefault-116.jpg","keywords":["Agriculture \/ For\u00eats \/ P\u00eache et nourriture","Tha\u00eflande","Transport \/ Logistique \/ Emballage","Vivant"],"articleSection":["TRAFS - commerce de d\u00e9tail. restauration et services d'accueil en tha\u00eflande 2022"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\/popcorn_secret-bake\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\/popcorn_secret-bake\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\/popcorn_secret-bake\/","name":"[TRAFS - commerce de d\u00e9tail, restauration et services d'accueil en tha\u00eflande 2022] Pop corn - Cuisson secr\u00e8te \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\/popcorn_secret-bake\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\/popcorn_secret-bake\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/11\/maxresdefault-116.jpg","datePublished":"2022-11-29T08:03:12+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\/popcorn_secret-bake\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\/popcorn_secret-bake\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\/popcorn_secret-bake\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/11\/maxresdefault-116.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/11\/maxresdefault-116.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/trafs-commerce-de-detail-restauration-et-services-daccueil-en-thailande-2022\/popcorn_secret-bake\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"[TRAFS - commerce de d\u00e9tail, restauration et services d'accueil en tha\u00eflande 2022] Pop corn - Cuisson secr\u00e8te"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/9uiT5JTx_jI","og_video_type":"text\/html","og_video_duration":"68","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=9uiT5JTx_jI","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/43029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=43029"}],"version-history":[{"count":0,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/43029\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/43030"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=43029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=43029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=43029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}