{"id":42841,"date":"2022-11-21T05:26:52","date_gmt":"2022-11-21T05:26:52","guid":{"rendered":"https:\/\/france.worldtradeshow.tv\/?p=42841"},"modified":"2022-11-21T05:26:52","modified_gmt":"2022-11-21T05:26:52","slug":"dive-solutions_cloud-native-cae-solution","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/bauma-2022\/dive-solutions_cloud-native-cae-solution\/","title":{"rendered":"[Bauma 2022] solutions de plong\u00e9e - Solution CAE native dans le cloud"},"content":{"rendered":"<p>Solution CAE native dans le cloud a expos\u00e9 solutions de plong\u00e9e \u00e0 Bauma 2022.<\/p>\n<\/p>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bauma_2022_10\/bauma_2022_10_04-1.jpg\"><\/div>\n<div class=\"caption_text\">Bonjour, je suis Yannick de Dive Solutions. Ravi de vous rencontrer.<br \/>Nous sommes ici au premier salon mondial bauma de cette ann\u00e9e pour les machines et v\u00e9hicules de construction.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bauma_2022_10\/bauma_2022_10_04-2.jpg\"><\/div>\n<div class=\"caption_text\">Et nous-m\u00eames, nous sommes une spin-off du groupe Bosch et des universit\u00e9s de Berlin.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bauma_2022_10\/bauma_2022_10_04-3.jpg\"><\/div>\n<div class=\"caption_text\">Notre&#8230; disons, notre vision est d&#8217;aider les ing\u00e9nieurs \u00e0 se concentrer uniquement sur l&#8217;ing\u00e9nierie.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bauma_2022_10\/bauma_2022_10_04-4.jpg\"><\/div>\n<div class=\"caption_text\">Ce que nous voulons dire, c&#8217;est que nous voulons vous aider \u00e0 cr\u00e9er des produits de qualit\u00e9 toujours plus rapidement,<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bauma_2022_10\/bauma_2022_10_04-5.jpg\"><\/div>\n<div class=\"caption_text\">comme de plus en plus vite en supprimant toutes les distractions et limites inutiles que vous avez dans la simulation.<br \/>Et c&#8217;est pourquoi nous avons cr\u00e9\u00e9 une solution CAE native dans le cloud.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bauma_2022_10\/bauma_2022_10_04-6.jpg\"><\/div>\n<div class=\"caption_text\">Cela signifie donc qu&#8217;il s&#8217;agit d&#8217;une application Web int\u00e9gr\u00e9e au navigateur.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bauma_2022_10\/bauma_2022_10_04-7.jpg\"><\/div>\n<div class=\"caption_text\">C&#8217;est tr\u00e8s simple, tr\u00e8s intuitif et vous avez toute la puissance des nuages.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bauma_2022_10\/bauma_2022_10_04-8.jpg\"><\/div>\n<div class=\"caption_text\">Et c&#8217;est particuli\u00e8rement utile, par exemple, ici au bauma parce que tous\u00a0les exposants ici.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bauma_2022_10\/bauma_2022_10_04-9.jpg\"><\/div>\n<div class=\"caption_text\">Comme les machines de construction, elles doivent d\u00e9velopper des tendances en mati\u00e8re d&#8217;\u00e9nergie \u00e9lectrique telles que les machines \u00e9lectriques \u00e0 z\u00e9ro \u00e9mission et vous devez donc beaucoup simuler pour cr\u00e9er ces nouveaux produits.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bauma_2022_10\/bauma_2022_10_04-10.jpg\"><\/div>\n<div class=\"caption_text\">\u00c0 titre d&#8217;exemple rapide, vous pouvez \u00e9galement voir ici comment nous vous aidons, par exemple, \u00e0 analyser votre\u00a0bo\u00eete de vitesses, comment l&#8217;huile \u00e9clabousse, quelle est la quantit\u00e9 de chaleur, quelle est l&#8217;efficacit\u00e9, quel est le refroidissement du moteur \u00e9lectrique.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bauma_2022_10\/bauma_2022_10_04-12.jpg\"><\/div>\n<div class=\"caption_text\">C&#8217;est donc \u00e0 propos de nous.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bauma_2022_10\/bauma_2022_10_04-13.jpg\"><\/div>\n<div class=\"caption_text\">Si vous souhaitez en savoir plus sur nous, comment nous pouvons aider\u00a0votre d\u00e9partement de fabrication ou votre d\u00e9partement d&#8217;ing\u00e9nierie \u00e0 acc\u00e9l\u00e9rer le d\u00e9veloppement de leurs produits,<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/bauma_2022_10\/bauma_2022_10_04-14.jpg\"><\/div>\n<div class=\"caption_text\">contactez-nous. Notre site Web est www.dive-solutions.de\/ <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Solution CAE native dans le cloud a expos\u00e9 solutions de plong\u00e9e \u00e0 Bauma 2022. Bonjour, je suis Yannick de Dive Solutions. Ravi de vous rencontrer.Nous sommes ici au premier salon mondial bauma de cette ann\u00e9e pour les machines et v\u00e9hicules de construction. Et nous-m\u00eames, nous sommes une spin-off du groupe Bosch et des universit\u00e9s de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":42842,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[240],"tags":[119,33],"class_list":["post-42841","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-bauma-2022","tag-germany","tag-machinery-industrial-technology","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[Bauma 2022] solutions de plong\u00e9e - Solution CAE native dans le cloud \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/bauma-2022\/dive-solutions_cloud-native-cae-solution\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Bauma 2022] solutions de plong\u00e9e - Solution CAE native dans le cloud \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"Solution CAE native dans le cloud a expos\u00e9 solutions de plong\u00e9e \u00e0 Bauma 2022. Bonjour, je suis Yannick de Dive Solutions. Ravi de vous rencontrer.Nous sommes ici au premier salon mondial bauma de cette ann\u00e9e pour les machines et v\u00e9hicules de construction. Et nous-m\u00eames, nous sommes une spin-off du groupe Bosch et des universit\u00e9s de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/bauma-2022\/dive-solutions_cloud-native-cae-solution\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-21T05:26:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/11\/maxresdefault-68.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/bauma-2022\\\/dive-solutions_cloud-native-cae-solution\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/bauma-2022\\\/dive-solutions_cloud-native-cae-solution\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"[Bauma 2022] solutions de plong\u00e9e - Solution CAE native dans le cloud\",\"datePublished\":\"2022-11-21T05:26:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/bauma-2022\\\/dive-solutions_cloud-native-cae-solution\\\/\"},\"wordCount\":319,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/bauma-2022\\\/dive-solutions_cloud-native-cae-solution\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/maxresdefault-68.jpg\",\"keywords\":[\"Allemagne\",\"Machines \\\/ Technologie industrielle\"],\"articleSection\":[\"Bauma 2022\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/bauma-2022\\\/dive-solutions_cloud-native-cae-solution\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/bauma-2022\\\/dive-solutions_cloud-native-cae-solution\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/bauma-2022\\\/dive-solutions_cloud-native-cae-solution\\\/\",\"name\":\"[Bauma 2022] solutions de plong\u00e9e - Solution CAE native dans le cloud \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/bauma-2022\\\/dive-solutions_cloud-native-cae-solution\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/bauma-2022\\\/dive-solutions_cloud-native-cae-solution\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/maxresdefault-68.jpg\",\"datePublished\":\"2022-11-21T05:26:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/bauma-2022\\\/dive-solutions_cloud-native-cae-solution\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/bauma-2022\\\/dive-solutions_cloud-native-cae-solution\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/bauma-2022\\\/dive-solutions_cloud-native-cae-solution\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/maxresdefault-68.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/maxresdefault-68.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/bauma-2022\\\/dive-solutions_cloud-native-cae-solution\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Bauma 2022] solutions de plong\u00e9e - Solution CAE native dans le cloud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/qKCTzXR4aVY\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"107\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[Bauma 2022] solutions de plong\u00e9e - Solution CAE native dans le cloud \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/bauma-2022\/dive-solutions_cloud-native-cae-solution\/","og_locale":"fr_FR","og_type":"article","og_title":"[Bauma 2022] solutions de plong\u00e9e - Solution CAE native dans le cloud \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"Solution CAE native dans le cloud a expos\u00e9 solutions de plong\u00e9e \u00e0 Bauma 2022. Bonjour, je suis Yannick de Dive Solutions. Ravi de vous rencontrer.Nous sommes ici au premier salon mondial bauma de cette ann\u00e9e pour les machines et v\u00e9hicules de construction. Et nous-m\u00eames, nous sommes une spin-off du groupe Bosch et des universit\u00e9s de [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/bauma-2022\/dive-solutions_cloud-native-cae-solution\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2022-11-21T05:26:52+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/11\/maxresdefault-68.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/bauma-2022\/dive-solutions_cloud-native-cae-solution\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/bauma-2022\/dive-solutions_cloud-native-cae-solution\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"[Bauma 2022] solutions de plong\u00e9e - Solution CAE native dans le cloud","datePublished":"2022-11-21T05:26:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/bauma-2022\/dive-solutions_cloud-native-cae-solution\/"},"wordCount":319,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/bauma-2022\/dive-solutions_cloud-native-cae-solution\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/11\/maxresdefault-68.jpg","keywords":["Allemagne","Machines \/ Technologie industrielle"],"articleSection":["Bauma 2022"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/bauma-2022\/dive-solutions_cloud-native-cae-solution\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/bauma-2022\/dive-solutions_cloud-native-cae-solution\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/bauma-2022\/dive-solutions_cloud-native-cae-solution\/","name":"[Bauma 2022] solutions de plong\u00e9e - Solution CAE native dans le cloud \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/bauma-2022\/dive-solutions_cloud-native-cae-solution\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/bauma-2022\/dive-solutions_cloud-native-cae-solution\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/11\/maxresdefault-68.jpg","datePublished":"2022-11-21T05:26:52+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/bauma-2022\/dive-solutions_cloud-native-cae-solution\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/bauma-2022\/dive-solutions_cloud-native-cae-solution\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/bauma-2022\/dive-solutions_cloud-native-cae-solution\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/11\/maxresdefault-68.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/11\/maxresdefault-68.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/bauma-2022\/dive-solutions_cloud-native-cae-solution\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"[Bauma 2022] solutions de plong\u00e9e - Solution CAE native dans le cloud"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/qKCTzXR4aVY","og_video_type":"text\/html","og_video_duration":"107","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=qKCTzXR4aVY","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/42841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=42841"}],"version-history":[{"count":0,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/42841\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/42842"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=42841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=42841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=42841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}