{"id":42317,"date":"2022-10-18T01:58:30","date_gmt":"2022-10-18T01:58:30","guid":{"rendered":"https:\/\/france.worldtradeshow.tv\/?p=42317"},"modified":"2022-10-18T01:58:30","modified_gmt":"2022-10-18T01:58:30","slug":"cleaning-wipes_core-clean","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\/cleaning-wipes_core-clean\/","title":{"rendered":"[Medicall 2022 - 30e salon indien de l'\u00e9quipement m\u00e9dical (New Delhi)] lingettes de nettoyage - Nettoyage de base"},"content":{"rendered":"<p>Nettoyage de base a expos\u00e9 lingettes de nettoyage \u00e0 Medicall 2022 &#8211; 30e salon indien de l&#8217;\u00e9quipement m\u00e9dical (New Delhi).<\/p>\n<\/p>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/medicall_2022_09\/medicall_2022_09_01-1.jpg\"><\/div>\n<div class=\"caption_text\">Salut, c&#8217;est Yash Gupta, et je suis le fondateur de Core Clean Private Limited.<br \/>Nous sommes la premi\u00e8re entreprise en Inde \u00e0 lancer des canisters brevet\u00e9s.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/medicall_2022_09\/medicall_2022_09_01-2.jpg\"><\/div>\n<div class=\"caption_text\">Pour l&#8217;industrie m\u00e9dicale, l&#8217;industrie des animaux de compagnie,<br \/>lingettes industrielles, lingettes de d\u00e9fense, lingettes automobiles, lingettes \u00e9lectroniques, lingettes pour instruments m\u00e9dicaux.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/medicall_2022_09\/medicall_2022_09_01-3.jpg\"><\/div>\n<div class=\"caption_text\">Nous avons donc class\u00e9 les produits en plusieurs aspects dans lesquels les lingettes d\u00e9sinfectantes peuvent \u00eatre utilis\u00e9es sur le march\u00e9 indien ainsi que sur les march\u00e9s d&#8217;exportation.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/medicall_2022_09\/medicall_2022_09_01-4.jpg\"><\/div>\n<div class=\"caption_text\">Nous poss\u00e9dons une tr\u00e8s bonne pr\u00e9sence en ce moment.<br \/>Nous utilisons des formulations QAC de 5e g\u00e9n\u00e9ration, qui sont brevet\u00e9es et formul\u00e9es aux \u00c9tats-Unis.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/medicall_2022_09\/medicall_2022_09_01-5.jpg\"><\/div>\n<div class=\"caption_text\">Qui sont approuv\u00e9s par le contr\u00f4le central des m\u00e9dicaments contre les maladies et l&#8217;OMS des \u00c9tats-Unis.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/medicall_2022_09\/medicall_2022_09_01-6.jpg\"><\/div>\n<div class=\"caption_text\">Nous avons fait un transfert technologique pour ce brevet particulier.<br \/>Nous sommes la seule entreprise en Inde \u00e0 importer le QAC de 5\u00e8me g\u00e9n\u00e9ration,<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/medicall_2022_09\/medicall_2022_09_01-7.jpg\"><\/div>\n<div class=\"caption_text\">qui est un d\u00e9sinfectant sans alcool, sans parangon, sans sulfate, sans javel,<br \/>qui donne la d\u00e9sinfection de 280 bact\u00e9ries, virus, germes.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/medicall_2022_09\/medicall_2022_09_01-8.jpg\"><\/div>\n<div class=\"caption_text\">Sans provoquer de rouille, de d\u00e9shydratation de la peau, des mains et d&#8217;autres surfaces, qui sont les propri\u00e9t\u00e9s, l&#8217;alcool a,<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/medicall_2022_09\/medicall_2022_09_01-9.jpg\"><\/div>\n<div class=\"caption_text\">qui est un d\u00e9sinfectant de premier plan sur le march\u00e9 indien.<br \/>Notre objectif principal est donc de contr\u00f4ler les infections nosocomiales perfus\u00e9es et le contr\u00f4le des infections dans les h\u00f4pitaux et l&#8217;industrie m\u00e9dicale.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/medicall_2022_09\/medicall_2022_09_01-10.jpg\"><\/div>\n<div class=\"caption_text\">Merci!<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/medicall_2022_09\/medicall_2022_09_01-11.jpg\"><\/div>\n<div class=\"caption_text\">Vous pouvez nous joindre au<br \/>www.thecorecleancompany.com<br \/>Tous les d\u00e9tails sont fournis sur le site Web.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/medicall_2022_09\/medicall_2022_09_01-12.jpg\"><\/div>\n<div class=\"caption_text\">Nous vendons nos produits sur Amazon, Tata, 1MG, BigBasket<br \/>ainsi que plusieurs autres canaux de commerce \u00e9lectronique. <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nettoyage de base a expos\u00e9 lingettes de nettoyage \u00e0 Medicall 2022 &#8211; 30e salon indien de l&#8217;\u00e9quipement m\u00e9dical (New Delhi). Salut, c&#8217;est Yash Gupta, et je suis le fondateur de Core Clean Private Limited.Nous sommes la premi\u00e8re entreprise en Inde \u00e0 lancer des canisters brevet\u00e9s. Pour l&#8217;industrie m\u00e9dicale, l&#8217;industrie des animaux de compagnie,lingettes industrielles, lingettes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":42318,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[218],"tags":[154,34],"class_list":["post-42317","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi","tag-india","tag-medical-care-health","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[Medicall 2022 - 30e salon indien de l&#039;\u00e9quipement m\u00e9dical (New Delhi)] lingettes de nettoyage - Nettoyage de base \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\/cleaning-wipes_core-clean\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Medicall 2022 - 30e salon indien de l&#039;\u00e9quipement m\u00e9dical (New Delhi)] lingettes de nettoyage - Nettoyage de base \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"Nettoyage de base a expos\u00e9 lingettes de nettoyage \u00e0 Medicall 2022 &#8211; 30e salon indien de l&#8217;\u00e9quipement m\u00e9dical (New Delhi). Salut, c&#8217;est Yash Gupta, et je suis le fondateur de Core Clean Private Limited.Nous sommes la premi\u00e8re entreprise en Inde \u00e0 lancer des canisters brevet\u00e9s. Pour l&#8217;industrie m\u00e9dicale, l&#8217;industrie des animaux de compagnie,lingettes industrielles, lingettes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\/cleaning-wipes_core-clean\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-18T01:58:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/10\/maxresdefault-46.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\\\/cleaning-wipes_core-clean\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\\\/cleaning-wipes_core-clean\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"[Medicall 2022 - 30e salon indien de l'\u00e9quipement m\u00e9dical (New Delhi)] lingettes de nettoyage - Nettoyage de base\",\"datePublished\":\"2022-10-18T01:58:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\\\/cleaning-wipes_core-clean\\\/\"},\"wordCount\":321,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\\\/cleaning-wipes_core-clean\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/maxresdefault-46.jpg\",\"keywords\":[\"Inde\",\"Soins m\u00e9dicaux \\\/ Sant\u00e9\"],\"articleSection\":[\"Medicall 2022 - 30e salon indien de l'\u00e9quipement m\u00e9dical (New Delhi)\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\\\/cleaning-wipes_core-clean\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\\\/cleaning-wipes_core-clean\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\\\/cleaning-wipes_core-clean\\\/\",\"name\":\"[Medicall 2022 - 30e salon indien de l'\u00e9quipement m\u00e9dical (New Delhi)] lingettes de nettoyage - Nettoyage de base \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\\\/cleaning-wipes_core-clean\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\\\/cleaning-wipes_core-clean\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/maxresdefault-46.jpg\",\"datePublished\":\"2022-10-18T01:58:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\\\/cleaning-wipes_core-clean\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\\\/cleaning-wipes_core-clean\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\\\/cleaning-wipes_core-clean\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/maxresdefault-46.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/maxresdefault-46.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\\\/cleaning-wipes_core-clean\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Medicall 2022 - 30e salon indien de l'\u00e9quipement m\u00e9dical (New Delhi)] lingettes de nettoyage - Nettoyage de base\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/hegy5K3kFn8\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"85\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[Medicall 2022 - 30e salon indien de l'\u00e9quipement m\u00e9dical (New Delhi)] lingettes de nettoyage - Nettoyage de base \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\/cleaning-wipes_core-clean\/","og_locale":"fr_FR","og_type":"article","og_title":"[Medicall 2022 - 30e salon indien de l'\u00e9quipement m\u00e9dical (New Delhi)] lingettes de nettoyage - Nettoyage de base \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"Nettoyage de base a expos\u00e9 lingettes de nettoyage \u00e0 Medicall 2022 &#8211; 30e salon indien de l&#8217;\u00e9quipement m\u00e9dical (New Delhi). Salut, c&#8217;est Yash Gupta, et je suis le fondateur de Core Clean Private Limited.Nous sommes la premi\u00e8re entreprise en Inde \u00e0 lancer des canisters brevet\u00e9s. Pour l&#8217;industrie m\u00e9dicale, l&#8217;industrie des animaux de compagnie,lingettes industrielles, lingettes [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\/cleaning-wipes_core-clean\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2022-10-18T01:58:30+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/10\/maxresdefault-46.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\/cleaning-wipes_core-clean\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\/cleaning-wipes_core-clean\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"[Medicall 2022 - 30e salon indien de l'\u00e9quipement m\u00e9dical (New Delhi)] lingettes de nettoyage - Nettoyage de base","datePublished":"2022-10-18T01:58:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\/cleaning-wipes_core-clean\/"},"wordCount":321,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\/cleaning-wipes_core-clean\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/10\/maxresdefault-46.jpg","keywords":["Inde","Soins m\u00e9dicaux \/ Sant\u00e9"],"articleSection":["Medicall 2022 - 30e salon indien de l'\u00e9quipement m\u00e9dical (New Delhi)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\/cleaning-wipes_core-clean\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\/cleaning-wipes_core-clean\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\/cleaning-wipes_core-clean\/","name":"[Medicall 2022 - 30e salon indien de l'\u00e9quipement m\u00e9dical (New Delhi)] lingettes de nettoyage - Nettoyage de base \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\/cleaning-wipes_core-clean\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\/cleaning-wipes_core-clean\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/10\/maxresdefault-46.jpg","datePublished":"2022-10-18T01:58:30+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\/cleaning-wipes_core-clean\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\/cleaning-wipes_core-clean\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\/cleaning-wipes_core-clean\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/10\/maxresdefault-46.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/10\/maxresdefault-46.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/medicall-2022-30e-salon-indien-de-lequipement-medical-new-delhi\/cleaning-wipes_core-clean\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"[Medicall 2022 - 30e salon indien de l'\u00e9quipement m\u00e9dical (New Delhi)] lingettes de nettoyage - Nettoyage de base"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/hegy5K3kFn8","og_video_type":"text\/html","og_video_duration":"85","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=hegy5K3kFn8","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/42317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=42317"}],"version-history":[{"count":0,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/42317\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/42318"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=42317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=42317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=42317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}