{"id":42167,"date":"2022-10-04T02:39:34","date_gmt":"2022-10-04T02:39:34","guid":{"rendered":"https:\/\/france.worldtradeshow.tv\/?p=42167"},"modified":"2022-10-04T02:39:34","modified_gmt":"2022-10-04T02:39:34","slug":"pmt-gb-ltd_particle-detection-devices","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/espace-comm-expo-2022\/pmt-gb-ltd_particle-detection-devices\/","title":{"rendered":"[Espace-Comm Expo 2022] PMT GB LTD - Dispositifs de d\u00e9tection de particules"},"content":{"rendered":"<p>Dispositifs de d\u00e9tection de particules a expos\u00e9 PMT GB LTD \u00e0 Espace-Comm Expo 2022.<\/p>\n<\/p>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/space-comm_2022_09\/space-comm_2022_09_03-1.jpg\"><\/div>\n<div class=\"caption_text\">Je m&#8217;appelle Ian Norman, je suis le directeur g\u00e9n\u00e9ral de PMT GB limited.<br \/>Nous sommes impliqu\u00e9s dans le contr\u00f4le de la contamination dans les salles blanches et les environnements contr\u00f4l\u00e9s.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/space-comm_2022_09\/space-comm_2022_09_03-2.jpg\"><\/div>\n<div class=\"caption_text\">Nous travaillons avec certaines des principales soci\u00e9t\u00e9s pharmaceutiques, a\u00e9rospatiales, automobiles et de technologie des dispositifs m\u00e9dicaux au Royaume-Uni.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/space-comm_2022_09\/space-comm_2022_09_03-3.jpg\"><\/div>\n<div class=\"caption_text\">Nos instruments contr\u00f4lent et mesurent l&#8217;environnement dans lequel vous travaillez.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/space-comm_2022_09\/space-comm_2022_09_03-4.jpg\"><\/div>\n<div class=\"caption_text\">Ainsi, ils comptent les particules microbiennes viables et les particules non viables, nous pouvons \u00e9galement compter les particules de surface.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/space-comm_2022_09\/space-comm_2022_09_03-5.jpg\"><\/div>\n<div class=\"caption_text\">En surface, ainsi que dans l&#8217;eau, l&#8217;air, les liquides, les produits chimiques et les huiles.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/space-comm_2022_09\/space-comm_2022_09_03-6.jpg\"><\/div>\n<div class=\"caption_text\">Nous avons donc certains clients comme e2v, moog.<br \/>Ils disposent de nos \u00e9quipements\u00a0qui surveillent leur environnement de production.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/space-comm_2022_09\/space-comm_2022_09_03-7.jpg\"><\/div>\n<div class=\"caption_text\">Nous avons des syst\u00e8mes de surveillance qui comptent les particules et contr\u00f4lent l&#8217;environnement afin qu&#8217;ils sachent s&#8217;ils travaillent dans une salle blanche class\u00e9e ou non.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/space-comm_2022_09\/space-comm_2022_09_03-8.jpg\"><\/div>\n<div class=\"caption_text\">Avec le syst\u00e8me, nous pouvons surveiller les particules montantes.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/space-comm_2022_09\/space-comm_2022_09_03-9.jpg\"><\/div>\n<div class=\"caption_text\">Donc, s&#8217;ils se rapprochent trop\u00a0de leur norme de classification, cela peut arr\u00eater la production, ou ils peuvent alors r\u00e9agir et modifier leurs\u00a0proc\u00e9dures pour r\u00e9duire la quantit\u00e9 de particules.    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dispositifs de d\u00e9tection de particules a expos\u00e9 PMT GB LTD \u00e0 Espace-Comm Expo 2022. Je m&#8217;appelle Ian Norman, je suis le directeur g\u00e9n\u00e9ral de PMT GB limited.Nous sommes impliqu\u00e9s dans le contr\u00f4le de la contamination dans les salles blanches et les environnements contr\u00f4l\u00e9s. Nous travaillons avec certaines des principales soci\u00e9t\u00e9s pharmaceutiques, a\u00e9rospatiales, automobiles et de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":42168,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[212],"tags":[31,33,88],"class_list":["post-42167","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-espace-comm-expo-2022","tag-information-telecommunication","tag-machinery-industrial-technology","tag-united-kingdom","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[Espace-Comm Expo 2022] PMT GB LTD - Dispositifs de d\u00e9tection de particules \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/espace-comm-expo-2022\/pmt-gb-ltd_particle-detection-devices\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Espace-Comm Expo 2022] PMT GB LTD - Dispositifs de d\u00e9tection de particules \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"Dispositifs de d\u00e9tection de particules a expos\u00e9 PMT GB LTD \u00e0 Espace-Comm Expo 2022. Je m&#8217;appelle Ian Norman, je suis le directeur g\u00e9n\u00e9ral de PMT GB limited.Nous sommes impliqu\u00e9s dans le contr\u00f4le de la contamination dans les salles blanches et les environnements contr\u00f4l\u00e9s. Nous travaillons avec certaines des principales soci\u00e9t\u00e9s pharmaceutiques, a\u00e9rospatiales, automobiles et de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/espace-comm-expo-2022\/pmt-gb-ltd_particle-detection-devices\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-04T02:39:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/10\/maxresdefault-12.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/espace-comm-expo-2022\\\/pmt-gb-ltd_particle-detection-devices\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/espace-comm-expo-2022\\\/pmt-gb-ltd_particle-detection-devices\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"[Espace-Comm Expo 2022] PMT GB LTD - Dispositifs de d\u00e9tection de particules\",\"datePublished\":\"2022-10-04T02:39:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/espace-comm-expo-2022\\\/pmt-gb-ltd_particle-detection-devices\\\/\"},\"wordCount\":229,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/espace-comm-expo-2022\\\/pmt-gb-ltd_particle-detection-devices\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/maxresdefault-12.jpg\",\"keywords\":[\"Information \\\/ T\u00e9l\u00e9communication\",\"Machines \\\/ Technologie industrielle\",\"Royaume-Uni\"],\"articleSection\":[\"Espace-Comm Expo 2022\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/espace-comm-expo-2022\\\/pmt-gb-ltd_particle-detection-devices\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/espace-comm-expo-2022\\\/pmt-gb-ltd_particle-detection-devices\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/espace-comm-expo-2022\\\/pmt-gb-ltd_particle-detection-devices\\\/\",\"name\":\"[Espace-Comm Expo 2022] PMT GB LTD - Dispositifs de d\u00e9tection de particules \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/espace-comm-expo-2022\\\/pmt-gb-ltd_particle-detection-devices\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/espace-comm-expo-2022\\\/pmt-gb-ltd_particle-detection-devices\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/maxresdefault-12.jpg\",\"datePublished\":\"2022-10-04T02:39:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/espace-comm-expo-2022\\\/pmt-gb-ltd_particle-detection-devices\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/espace-comm-expo-2022\\\/pmt-gb-ltd_particle-detection-devices\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/espace-comm-expo-2022\\\/pmt-gb-ltd_particle-detection-devices\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/maxresdefault-12.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/maxresdefault-12.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/espace-comm-expo-2022\\\/pmt-gb-ltd_particle-detection-devices\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Espace-Comm Expo 2022] PMT GB LTD - Dispositifs de d\u00e9tection de particules\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/w_UH7Nu1R-0\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"76\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[Espace-Comm Expo 2022] PMT GB LTD - Dispositifs de d\u00e9tection de particules \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/espace-comm-expo-2022\/pmt-gb-ltd_particle-detection-devices\/","og_locale":"fr_FR","og_type":"article","og_title":"[Espace-Comm Expo 2022] PMT GB LTD - Dispositifs de d\u00e9tection de particules \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"Dispositifs de d\u00e9tection de particules a expos\u00e9 PMT GB LTD \u00e0 Espace-Comm Expo 2022. Je m&#8217;appelle Ian Norman, je suis le directeur g\u00e9n\u00e9ral de PMT GB limited.Nous sommes impliqu\u00e9s dans le contr\u00f4le de la contamination dans les salles blanches et les environnements contr\u00f4l\u00e9s. Nous travaillons avec certaines des principales soci\u00e9t\u00e9s pharmaceutiques, a\u00e9rospatiales, automobiles et de [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/espace-comm-expo-2022\/pmt-gb-ltd_particle-detection-devices\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2022-10-04T02:39:34+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/10\/maxresdefault-12.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/espace-comm-expo-2022\/pmt-gb-ltd_particle-detection-devices\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/espace-comm-expo-2022\/pmt-gb-ltd_particle-detection-devices\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"[Espace-Comm Expo 2022] PMT GB LTD - Dispositifs de d\u00e9tection de particules","datePublished":"2022-10-04T02:39:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/espace-comm-expo-2022\/pmt-gb-ltd_particle-detection-devices\/"},"wordCount":229,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/espace-comm-expo-2022\/pmt-gb-ltd_particle-detection-devices\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/10\/maxresdefault-12.jpg","keywords":["Information \/ T\u00e9l\u00e9communication","Machines \/ Technologie industrielle","Royaume-Uni"],"articleSection":["Espace-Comm Expo 2022"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/espace-comm-expo-2022\/pmt-gb-ltd_particle-detection-devices\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/espace-comm-expo-2022\/pmt-gb-ltd_particle-detection-devices\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/espace-comm-expo-2022\/pmt-gb-ltd_particle-detection-devices\/","name":"[Espace-Comm Expo 2022] PMT GB LTD - Dispositifs de d\u00e9tection de particules \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/espace-comm-expo-2022\/pmt-gb-ltd_particle-detection-devices\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/espace-comm-expo-2022\/pmt-gb-ltd_particle-detection-devices\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/10\/maxresdefault-12.jpg","datePublished":"2022-10-04T02:39:34+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/espace-comm-expo-2022\/pmt-gb-ltd_particle-detection-devices\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/espace-comm-expo-2022\/pmt-gb-ltd_particle-detection-devices\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/espace-comm-expo-2022\/pmt-gb-ltd_particle-detection-devices\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/10\/maxresdefault-12.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/10\/maxresdefault-12.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/espace-comm-expo-2022\/pmt-gb-ltd_particle-detection-devices\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"[Espace-Comm Expo 2022] PMT GB LTD - Dispositifs de d\u00e9tection de particules"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/w_UH7Nu1R-0","og_video_type":"text\/html","og_video_duration":"76","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=w_UH7Nu1R-0","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/42167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=42167"}],"version-history":[{"count":0,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/42167\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/42168"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=42167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=42167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=42167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}