{"id":41164,"date":"2022-07-12T11:06:16","date_gmt":"2022-07-12T11:06:16","guid":{"rendered":"https:\/\/france.worldtradeshow.tv\/?p=41164"},"modified":"2022-07-12T11:06:16","modified_gmt":"2022-07-12T11:06:16","slug":"3d-scan-face-sticker_castem-co-ltd","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/semaine-de-levenement-au-japon-2022\/3d-scan-face-sticker_castem-co-ltd\/","title":{"rendered":"[Semaine de l'\u00e9v\u00e9nement au Japon 2022] Autocollant de visage de num\u00e9risation 3D - Castem Co., Ltd."},"content":{"rendered":"<p>Castem Co., Ltd. a expos\u00e9 Autocollant de visage de num\u00e9risation 3D \u00e0 Semaine de l&#8217;\u00e9v\u00e9nement au Japon 2022.<\/p>\n<p>site Internet\uff1a<a href=\"https:\/\/www.castem.co.jp\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.castem.co.jp\/<\/a><\/p>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/eventexpo_2022\/eventexpo_2022_07-1.jpg\"><\/div>\n<div class=\"caption_text\">Ici, nous exploitons une marque appel\u00e9e History Maker, et c&#8217;est une marque qui<br \/>mod\u00e9lise directement le visage, le corps entier et les factures d&#8217;une personne c\u00e9l\u00e8bre \u00e0 partir de la personne elle-m\u00eame, effectue une num\u00e9risation 3D et la commercialise de mani\u00e8re r\u00e9aliste. ..<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/eventexpo_2022\/eventexpo_2022_07-3.jpg\"><\/div>\n<div class=\"caption_text\">Il s&#8217;agit d&#8217;un produit appel\u00e9 autocollant de visage 3D, et m\u00eame si vous le regardez d&#8217;un point de vue global, c&#8217;est un service qui n&#8217;est disponible qu&#8217;ici.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/eventexpo_2022\/eventexpo_2022_07-4.jpg\"><\/div>\n<div class=\"caption_text\">Le service est tel que le visage de la personne est correctement scann\u00e9 en 3D avec un scanner 3D, et<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/eventexpo_2022\/eventexpo_2022_07-5.jpg\"><\/div>\n<div class=\"caption_text\">les donn\u00e9es de forme et de couleur du visage de la personne sont \u00e9galement utilis\u00e9es comme autocollants.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/eventexpo_2022\/eventexpo_2022_07-6.jpg\"><\/div>\n<div class=\"caption_text\">Vraiment, c&#8217;est un produit qui a un grand impact lorsqu&#8217;il est attach\u00e9 \u00e0 un smartphone, et c&#8217;est maintenant un produit qui est devenu un sujet br\u00fblant sur Twitter et SNS.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/eventexpo_2022\/eventexpo_2022_07-8.jpg\"><\/div>\n<div class=\"caption_text\">C&#8217;est un service qui peut \u00eatre fabriqu\u00e9 sur commande, ne n\u00e9cessite pas de frais de moule et peut r\u00e9duire consid\u00e9rablement le co\u00fbt initial et le co\u00fbt initial, donc<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/eventexpo_2022\/eventexpo_2022_07-9.jpg\"><\/div>\n<div class=\"caption_text\">J&#8217;aimerais que vous l&#8217;essayiez d&#8217;abord.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Castem Co., Ltd. a expos\u00e9 Autocollant de visage de num\u00e9risation 3D \u00e0 Semaine de l&#8217;\u00e9v\u00e9nement au Japon 2022. site Internet\uff1ahttps:\/\/www.castem.co.jp\/ Ici, nous exploitons une marque appel\u00e9e History Maker, et c&#8217;est une marque quimod\u00e9lise directement le visage, le corps entier et les factures d&#8217;une personne c\u00e9l\u00e8bre \u00e0 partir de la personne elle-m\u00eame, effectue une num\u00e9risation 3D [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":41165,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[156],"tags":[30,38,33,36,42],"class_list":["post-41164","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-semaine-de-levenement-au-japon-2022","tag-hobby-education","tag-japan","tag-machinery-industrial-technology","tag-services","tag-living","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[Semaine de l&#039;\u00e9v\u00e9nement au Japon 2022] Autocollant de visage de num\u00e9risation 3D - Castem Co., Ltd. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/semaine-de-levenement-au-japon-2022\/3d-scan-face-sticker_castem-co-ltd\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Semaine de l&#039;\u00e9v\u00e9nement au Japon 2022] Autocollant de visage de num\u00e9risation 3D - Castem Co., Ltd. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"Castem Co., Ltd. a expos\u00e9 Autocollant de visage de num\u00e9risation 3D \u00e0 Semaine de l&#8217;\u00e9v\u00e9nement au Japon 2022. site Internet\uff1ahttps:\/\/www.castem.co.jp\/ Ici, nous exploitons une marque appel\u00e9e History Maker, et c&#8217;est une marque quimod\u00e9lise directement le visage, le corps entier et les factures d&#8217;une personne c\u00e9l\u00e8bre \u00e0 partir de la personne elle-m\u00eame, effectue une num\u00e9risation 3D [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/semaine-de-levenement-au-japon-2022\/3d-scan-face-sticker_castem-co-ltd\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-12T11:06:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/07\/maxresdefault-24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/semaine-de-levenement-au-japon-2022\\\/3d-scan-face-sticker_castem-co-ltd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/semaine-de-levenement-au-japon-2022\\\/3d-scan-face-sticker_castem-co-ltd\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"[Semaine de l'\u00e9v\u00e9nement au Japon 2022] Autocollant de visage de num\u00e9risation 3D - Castem Co., Ltd.\",\"datePublished\":\"2022-07-12T11:06:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/semaine-de-levenement-au-japon-2022\\\/3d-scan-face-sticker_castem-co-ltd\\\/\"},\"wordCount\":242,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/semaine-de-levenement-au-japon-2022\\\/3d-scan-face-sticker_castem-co-ltd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/maxresdefault-24.jpg\",\"keywords\":[\"Hobby \\\/ Education\",\"Japon\",\"Machines \\\/ Technologie industrielle\",\"Prestations de service\",\"Vivant\"],\"articleSection\":[\"Semaine de l'\u00e9v\u00e9nement au Japon 2022\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/semaine-de-levenement-au-japon-2022\\\/3d-scan-face-sticker_castem-co-ltd\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/semaine-de-levenement-au-japon-2022\\\/3d-scan-face-sticker_castem-co-ltd\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/semaine-de-levenement-au-japon-2022\\\/3d-scan-face-sticker_castem-co-ltd\\\/\",\"name\":\"[Semaine de l'\u00e9v\u00e9nement au Japon 2022] Autocollant de visage de num\u00e9risation 3D - Castem Co., Ltd. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/semaine-de-levenement-au-japon-2022\\\/3d-scan-face-sticker_castem-co-ltd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/semaine-de-levenement-au-japon-2022\\\/3d-scan-face-sticker_castem-co-ltd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/maxresdefault-24.jpg\",\"datePublished\":\"2022-07-12T11:06:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/semaine-de-levenement-au-japon-2022\\\/3d-scan-face-sticker_castem-co-ltd\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/semaine-de-levenement-au-japon-2022\\\/3d-scan-face-sticker_castem-co-ltd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/semaine-de-levenement-au-japon-2022\\\/3d-scan-face-sticker_castem-co-ltd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/maxresdefault-24.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/maxresdefault-24.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/semaine-de-levenement-au-japon-2022\\\/3d-scan-face-sticker_castem-co-ltd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Semaine de l'\u00e9v\u00e9nement au Japon 2022] Autocollant de visage de num\u00e9risation 3D - Castem Co., Ltd.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/cuAlzU8qB9k\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"71\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[Semaine de l'\u00e9v\u00e9nement au Japon 2022] Autocollant de visage de num\u00e9risation 3D - Castem Co., Ltd. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/semaine-de-levenement-au-japon-2022\/3d-scan-face-sticker_castem-co-ltd\/","og_locale":"fr_FR","og_type":"article","og_title":"[Semaine de l'\u00e9v\u00e9nement au Japon 2022] Autocollant de visage de num\u00e9risation 3D - Castem Co., Ltd. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"Castem Co., Ltd. a expos\u00e9 Autocollant de visage de num\u00e9risation 3D \u00e0 Semaine de l&#8217;\u00e9v\u00e9nement au Japon 2022. site Internet\uff1ahttps:\/\/www.castem.co.jp\/ Ici, nous exploitons une marque appel\u00e9e History Maker, et c&#8217;est une marque quimod\u00e9lise directement le visage, le corps entier et les factures d&#8217;une personne c\u00e9l\u00e8bre \u00e0 partir de la personne elle-m\u00eame, effectue une num\u00e9risation 3D [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/semaine-de-levenement-au-japon-2022\/3d-scan-face-sticker_castem-co-ltd\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2022-07-12T11:06:16+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/07\/maxresdefault-24.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/semaine-de-levenement-au-japon-2022\/3d-scan-face-sticker_castem-co-ltd\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/semaine-de-levenement-au-japon-2022\/3d-scan-face-sticker_castem-co-ltd\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"[Semaine de l'\u00e9v\u00e9nement au Japon 2022] Autocollant de visage de num\u00e9risation 3D - Castem Co., Ltd.","datePublished":"2022-07-12T11:06:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/semaine-de-levenement-au-japon-2022\/3d-scan-face-sticker_castem-co-ltd\/"},"wordCount":242,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/semaine-de-levenement-au-japon-2022\/3d-scan-face-sticker_castem-co-ltd\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/07\/maxresdefault-24.jpg","keywords":["Hobby \/ Education","Japon","Machines \/ Technologie industrielle","Prestations de service","Vivant"],"articleSection":["Semaine de l'\u00e9v\u00e9nement au Japon 2022"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/semaine-de-levenement-au-japon-2022\/3d-scan-face-sticker_castem-co-ltd\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/semaine-de-levenement-au-japon-2022\/3d-scan-face-sticker_castem-co-ltd\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/semaine-de-levenement-au-japon-2022\/3d-scan-face-sticker_castem-co-ltd\/","name":"[Semaine de l'\u00e9v\u00e9nement au Japon 2022] Autocollant de visage de num\u00e9risation 3D - Castem Co., Ltd. \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/semaine-de-levenement-au-japon-2022\/3d-scan-face-sticker_castem-co-ltd\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/semaine-de-levenement-au-japon-2022\/3d-scan-face-sticker_castem-co-ltd\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/07\/maxresdefault-24.jpg","datePublished":"2022-07-12T11:06:16+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/semaine-de-levenement-au-japon-2022\/3d-scan-face-sticker_castem-co-ltd\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/semaine-de-levenement-au-japon-2022\/3d-scan-face-sticker_castem-co-ltd\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/semaine-de-levenement-au-japon-2022\/3d-scan-face-sticker_castem-co-ltd\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/07\/maxresdefault-24.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/07\/maxresdefault-24.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/semaine-de-levenement-au-japon-2022\/3d-scan-face-sticker_castem-co-ltd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"[Semaine de l'\u00e9v\u00e9nement au Japon 2022] Autocollant de visage de num\u00e9risation 3D - Castem Co., Ltd."}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/cuAlzU8qB9k","og_video_type":"text\/html","og_video_duration":"71","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=cuAlzU8qB9k","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/41164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=41164"}],"version-history":[{"count":0,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/41164\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/41165"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=41164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=41164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=41164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}