{"id":40649,"date":"2022-05-25T04:35:46","date_gmt":"2022-05-25T04:35:46","guid":{"rendered":"https:\/\/france.worldtradeshow.tv\/?p=40649"},"modified":"2022-05-25T04:38:45","modified_gmt":"2022-05-25T04:38:45","slug":"_sennheiser-mke-range","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_sennheiser-mke-range\/","title":{"rendered":"[Le salon de la production et de la technologie des m\u00e9dias 2022] Gamme Sennheiser MKE"},"content":{"rendered":"<p>Gamme Sennheiser MKE expos\u00e9 au Le salon de la production et de la technologie des m\u00e9dias 2022.<\/p>\n<\/p>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-001.jpg\"><\/div>\n<div class=\"caption_text\">Bonjour, je m&#8217;appelle Tim Constable, je travaille chez Sennheiser\u00a0au Royaume-Uni.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-008.jpg\"><\/div>\n<div class=\"caption_text\">Je m&#8217;occupe du march\u00e9 de la vid\u00e9o pro pour Sennheiser.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-015.jpg\"><\/div>\n<div class=\"caption_text\">J&#8217;aimerais vous pr\u00e9senter\u00a0deux\u00a0micros que nous avons pr\u00e9sent\u00e9s aujourd&#8217;hui.<br \/>J&#8217;ai le make 200 ici, j&#8217;ai le make 400 ici.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-022.jpg\"><\/div>\n<div class=\"caption_text\">Ce sont tous les deux de tr\u00e8s bons microphones con\u00e7us pour \u00eatre utilis\u00e9s avec un smartphone ou pour entrer dans un appareil photo de style CSC DSLR.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-029.jpg\"><\/div>\n<div class=\"caption_text\">Sur le c\u00f4t\u00e9 gauche, nous avons le Mke200.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-036.jpg\"><\/div>\n<div class=\"caption_text\">C&#8217;est un petit micro compact, vous avez le support de c\u00e2ble qui sort \u00e0 l&#8217;avant.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-043.jpg\"><\/div>\n<div class=\"caption_text\">Un connecteur verrouillable de 3,5\u00a0mil utilise l&#8217;un de ces c\u00e2bles viss\u00e9s \u00e0 l&#8217;avant de votre cam\u00e9ra.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-050.jpg\"><\/div>\n<div class=\"caption_text\">Derri\u00e8re, il est aliment\u00e9 par l&#8217;appareil auquel il est branch\u00e9.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-057.jpg\"><\/div>\n<div class=\"caption_text\">Vous n&#8217;avez donc pas \u00e0 vous soucier des piles.<br \/>Dans le kit, vous obtenez deux\u00a0c\u00e2bles, un pour un appareil photo, puis un autre pour un smartphone et comme vous pouvez le voir, celui du smartphone.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-064.jpg\"><\/div>\n<div class=\"caption_text\">Il y a une belle \u00e9tiquette dessus qui dit smartphone, il est donc facile de choisir le bon c\u00e2ble pour le bon travail.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-071.jpg\"><\/div>\n<div class=\"caption_text\">\u00c9galement dans le kit, vous obtenez une housse en fourrure qui aide \u00e0 la protection contre le vent.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-078.jpg\"><\/div>\n<div class=\"caption_text\">En regardant\u00a0le microphone lui-m\u00eame, vous avez un couvercle en treillis m\u00e9tallique qui agit de la m\u00eame mani\u00e8re qu&#8217;un couvercle en mousse.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-085.jpg\"><\/div>\n<div class=\"caption_text\">Mais il est beaucoup plus durable, il ne va pas s&#8217;effriter et se d\u00e9grader avec le temps, c&#8217;est un m\u00e9tal solide.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-092.jpg\"><\/div>\n<div class=\"caption_text\">Le microphone \u00e0 couvercle m\u00e9tallique se trouve \u00e0 l&#8217;int\u00e9rieur sur une suspension.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-099.jpg\"><\/div>\n<div class=\"caption_text\">Il est donc agr\u00e9able et s\u00e9curis\u00e9 que le microphone tr\u00e8s robuste s&#8217;adapte au-dessus d&#8217;une chaussure froide pour appareil photo.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-106.jpg\"><\/div>\n<div class=\"caption_text\">V\u00e9lo agr\u00e9able et facile \u00e0 utiliser, puis nous avons son grand fr\u00e8re le MKE400.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-113.jpg\"><\/div>\n<div class=\"caption_text\">Cela utilise des piles lui-m\u00eame, donc ce que vous avez, c&#8217;est que vous avez deux\u00a0piles AAA qui vous donnent une autonomie de cent heures,<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-120.jpg\"><\/div>\n<div class=\"caption_text\">Vous avez le connecteur de la boule de casier \u00e0 l&#8217;avant, le c\u00e2ble sort dans la cam\u00e9ra elle-m\u00eame.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-127.jpg\"><\/div>\n<div class=\"caption_text\">Sur le c\u00f4t\u00e9 droit du microphone lui-m\u00eame, nous avons une entr\u00e9e casque avec un contr\u00f4le du volume de l&#8217;autre c\u00f4t\u00e9.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-134.jpg\"><\/div>\n<div class=\"caption_text\">Nous avons un interrupteur marche\/arr\u00eat, un interrupteur de sensibilit\u00e9 et un filtre coupe-bas.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-141.jpg\"><\/div>\n<div class=\"caption_text\">Nous pouvons le d\u00e9ployer pour nous d\u00e9barrasser du bruit du vent.<br \/>Le m\u00eame couvercle en maille m\u00e9tallique \u00e0 l&#8217;avant, le microphone se trouve bien \u00e0 l&#8217;int\u00e9rieur.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-148.jpg\"><\/div>\n<div class=\"caption_text\">Cardio\u00efde plus d&#8217;un style de fusil de chasse alors prenez ce micro un peu plus concentr\u00e9 sur le 200 moi-m\u00eame.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-155.jpg\"><\/div>\n<div class=\"caption_text\">Point de prix sur le MKE 200 87 livres UK.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-162.jpg\"><\/div>\n<div class=\"caption_text\">Et sur le MKE 400, vous regardez 179 livres britanniques.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_06-169.jpg\"><\/div>\n<div class=\"caption_text\">Merci.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Gamme Sennheiser MKE expos\u00e9 au Le salon de la production et de la technologie des m\u00e9dias 2022. Bonjour, je m&#8217;appelle Tim Constable, je travaille chez Sennheiser\u00a0au Royaume-Uni. Je m&#8217;occupe du march\u00e9 de la vid\u00e9o pro pour Sennheiser. J&#8217;aimerais vous pr\u00e9senter\u00a0deux\u00a0micros que nous avons pr\u00e9sent\u00e9s aujourd&#8217;hui.J&#8217;ai le make 200 ici, j&#8217;ai le make 400 ici. Ce [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":40650,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[126],"tags":[31,33,88],"class_list":["post-40649","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-le-salon-de-la-production-et-de-la-technologie-des-medias-2022","tag-information-telecommunication","tag-machinery-industrial-technology","tag-united-kingdom","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[Le salon de la production et de la technologie des m\u00e9dias 2022] Gamme Sennheiser MKE \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_sennheiser-mke-range\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Le salon de la production et de la technologie des m\u00e9dias 2022] Gamme Sennheiser MKE \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"Gamme Sennheiser MKE expos\u00e9 au Le salon de la production et de la technologie des m\u00e9dias 2022. Bonjour, je m&#8217;appelle Tim Constable, je travaille chez Sennheiser\u00a0au Royaume-Uni. Je m&#8217;occupe du march\u00e9 de la vid\u00e9o pro pour Sennheiser. J&#8217;aimerais vous pr\u00e9senter\u00a0deux\u00a0micros que nous avons pr\u00e9sent\u00e9s aujourd&#8217;hui.J&#8217;ai le make 200 ici, j&#8217;ai le make 400 ici. Ce [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_sennheiser-mke-range\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-25T04:35:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-25T04:38:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/05\/maxresdefault-60.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_sennheiser-mke-range\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_sennheiser-mke-range\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"[Le salon de la production et de la technologie des m\u00e9dias 2022] Gamme Sennheiser MKE\",\"datePublished\":\"2022-05-25T04:35:46+00:00\",\"dateModified\":\"2022-05-25T04:38:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_sennheiser-mke-range\\\/\"},\"wordCount\":511,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_sennheiser-mke-range\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/maxresdefault-60.jpg\",\"keywords\":[\"Information \\\/ T\u00e9l\u00e9communication\",\"Machines \\\/ Technologie industrielle\",\"Royaume-Uni\"],\"articleSection\":[\"Le salon de la production et de la technologie des m\u00e9dias 2022\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_sennheiser-mke-range\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_sennheiser-mke-range\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_sennheiser-mke-range\\\/\",\"name\":\"[Le salon de la production et de la technologie des m\u00e9dias 2022] Gamme Sennheiser MKE \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_sennheiser-mke-range\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_sennheiser-mke-range\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/maxresdefault-60.jpg\",\"datePublished\":\"2022-05-25T04:35:46+00:00\",\"dateModified\":\"2022-05-25T04:38:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_sennheiser-mke-range\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_sennheiser-mke-range\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_sennheiser-mke-range\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/maxresdefault-60.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/maxresdefault-60.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_sennheiser-mke-range\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Le salon de la production et de la technologie des m\u00e9dias 2022] Gamme Sennheiser MKE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/gFYg81rutmg\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"173\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[Le salon de la production et de la technologie des m\u00e9dias 2022] Gamme Sennheiser MKE \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_sennheiser-mke-range\/","og_locale":"fr_FR","og_type":"article","og_title":"[Le salon de la production et de la technologie des m\u00e9dias 2022] Gamme Sennheiser MKE \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"Gamme Sennheiser MKE expos\u00e9 au Le salon de la production et de la technologie des m\u00e9dias 2022. Bonjour, je m&#8217;appelle Tim Constable, je travaille chez Sennheiser\u00a0au Royaume-Uni. Je m&#8217;occupe du march\u00e9 de la vid\u00e9o pro pour Sennheiser. J&#8217;aimerais vous pr\u00e9senter\u00a0deux\u00a0micros que nous avons pr\u00e9sent\u00e9s aujourd&#8217;hui.J&#8217;ai le make 200 ici, j&#8217;ai le make 400 ici. Ce [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_sennheiser-mke-range\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2022-05-25T04:35:46+00:00","article_modified_time":"2022-05-25T04:38:45+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/05\/maxresdefault-60.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_sennheiser-mke-range\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_sennheiser-mke-range\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"[Le salon de la production et de la technologie des m\u00e9dias 2022] Gamme Sennheiser MKE","datePublished":"2022-05-25T04:35:46+00:00","dateModified":"2022-05-25T04:38:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_sennheiser-mke-range\/"},"wordCount":511,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_sennheiser-mke-range\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/05\/maxresdefault-60.jpg","keywords":["Information \/ T\u00e9l\u00e9communication","Machines \/ Technologie industrielle","Royaume-Uni"],"articleSection":["Le salon de la production et de la technologie des m\u00e9dias 2022"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_sennheiser-mke-range\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_sennheiser-mke-range\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_sennheiser-mke-range\/","name":"[Le salon de la production et de la technologie des m\u00e9dias 2022] Gamme Sennheiser MKE \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_sennheiser-mke-range\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_sennheiser-mke-range\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/05\/maxresdefault-60.jpg","datePublished":"2022-05-25T04:35:46+00:00","dateModified":"2022-05-25T04:38:45+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_sennheiser-mke-range\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_sennheiser-mke-range\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_sennheiser-mke-range\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/05\/maxresdefault-60.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/05\/maxresdefault-60.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_sennheiser-mke-range\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"[Le salon de la production et de la technologie des m\u00e9dias 2022] Gamme Sennheiser MKE"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/gFYg81rutmg","og_video_type":"text\/html","og_video_duration":"173","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=gFYg81rutmg","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/40649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=40649"}],"version-history":[{"count":0,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/40649\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/40650"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=40649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=40649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=40649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}