{"id":40641,"date":"2022-05-25T04:35:29","date_gmt":"2022-05-25T04:35:29","guid":{"rendered":"https:\/\/france.worldtradeshow.tv\/?p=40641"},"modified":"2022-05-25T04:38:54","modified_gmt":"2022-05-25T04:38:54","slug":"_atomos-connected-range","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_atomos-connected-range\/","title":{"rendered":"[Le salon de la production et de la technologie des m\u00e9dias 2022] Gamme connect\u00e9e Atomos"},"content":{"rendered":"<p>Gamme connect\u00e9e Atomos expos\u00e9 au Le salon de la production et de la technologie des m\u00e9dias 2022.<\/p>\n<\/p>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_02-001.jpg\"><\/div>\n<div class=\"caption_text\">Salut, Paul d&#8217;Atomos, nous sommes ici au Media Production Show \u00e0 Londres.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_02-008.jpg\"><\/div>\n<div class=\"caption_text\">Je veux juste montrer les deux nouveaux produits que nous avons\u00a0lanc\u00e9s par Atomos, de la nouvelle gamme connect\u00e9e.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_02-015.jpg\"><\/div>\n<div class=\"caption_text\">L&#8217;un d&#8217;eux est donc un shogun\u00a0connect\u00e9 enti\u00e8rement int\u00e9gr\u00e9, qui est un \u00e9cran super lumineux de 7\u00a0pouces de 2\u00a0000\u00a0bits,<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_02-022.jpg\"><\/div>\n<div class=\"caption_text\">avec tout un tas de connectivit\u00e9 pour la connectivit\u00e9 locale en eux-m\u00eames et \u00e9galement la connectivit\u00e9 Internet.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_02-029.jpg\"><\/div>\n<div class=\"caption_text\">Donc, ce que nous avons \u00e0 ce sujet, nous avons le Wi-Fi 6, nous avons l&#8217;Ethernet gig-e.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_02-036.jpg\"><\/div>\n<div class=\"caption_text\">Et puis, pour la connectivit\u00e9 locale entre les appareils, nous avons\u00a0la synchronisation air-glue, c&#8217;est-\u00e0-dire notre technologie de contr\u00f4le de synchronisation exclusive int\u00e9gr\u00e9e \u00e0 tous les nouveaux produits Atomos\u00a0connect.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_02-043.jpg\"><\/div>\n<div class=\"caption_text\">Il s&#8217;agit d&#8217;une synchronisation de code temporel sans fil \u00e0 tr\u00e8s longue port\u00e9e et peut contr\u00f4ler les m\u00e9canismes\u00a0pour tout connecter ensemble localement sur le plateau\u00a0.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_02-050.jpg\"><\/div>\n<div class=\"caption_text\">Ainsi, vous obtenez le meilleur des deux mondes.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_02-057.jpg\"><\/div>\n<div class=\"caption_text\">Connectivit\u00e9\u00a0sur le plateau dans des zones tr\u00e8s difficiles, comme lors d&#8217;un salon professionnel o\u00f9 la RF est assez difficile.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_02-064.jpg\"><\/div>\n<div class=\"caption_text\">Ensuite, nous avons la synchronisation air-colle qui est la synchronisation RF longue port\u00e9e qui est excellente dans des endroits comme celui-ci o\u00f9 la RF est tr\u00e8s difficile.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_02-071.jpg\"><\/div>\n<div class=\"caption_text\">Il fait tr\u00e8s bien de garder tout\u00a0le code temporel synchronis\u00e9 et verrouill\u00e9 ensemble sur des centaines de m\u00e8tres.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_02-078.jpg\"><\/div>\n<div class=\"caption_text\">Nous pouvons nous connecter au monde ext\u00e9rieur avec le Wi-Fi et Ethernet,<br \/>pour se connecter aux nouveaux services cloud Atomos tels que le studio cloud Atomos,<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_02-085.jpg\"><\/div>\n<div class=\"caption_text\">o\u00f9 nous pouvons connecter la cam\u00e9ra au cloud, encadrer la cam\u00e9ra IO au cloud avec lequel nous lan\u00e7ons en juin.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/mediaproductionshow_2022\/mediaproductionshow_2022_02-092.jpg\"><\/div>\n<div class=\"caption_text\">Ainsi que le streaming vers votre service pr\u00e9f\u00e9r\u00e9 comme YouTube ou Twitch\u00a0ou tout service RTMPS que vous souhaitez configurer.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Gamme connect\u00e9e Atomos expos\u00e9 au Le salon de la production et de la technologie des m\u00e9dias 2022. Salut, Paul d&#8217;Atomos, nous sommes ici au Media Production Show \u00e0 Londres. Je veux juste montrer les deux nouveaux produits que nous avons\u00a0lanc\u00e9s par Atomos, de la nouvelle gamme connect\u00e9e. L&#8217;un d&#8217;eux est donc un shogun\u00a0connect\u00e9 enti\u00e8rement int\u00e9gr\u00e9, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":40642,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[126],"tags":[31,33,88],"class_list":["post-40641","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-le-salon-de-la-production-et-de-la-technologie-des-medias-2022","tag-information-telecommunication","tag-machinery-industrial-technology","tag-united-kingdom","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[Le salon de la production et de la technologie des m\u00e9dias 2022] Gamme connect\u00e9e Atomos \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_atomos-connected-range\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Le salon de la production et de la technologie des m\u00e9dias 2022] Gamme connect\u00e9e Atomos \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"Gamme connect\u00e9e Atomos expos\u00e9 au Le salon de la production et de la technologie des m\u00e9dias 2022. Salut, Paul d&#8217;Atomos, nous sommes ici au Media Production Show \u00e0 Londres. Je veux juste montrer les deux nouveaux produits que nous avons\u00a0lanc\u00e9s par Atomos, de la nouvelle gamme connect\u00e9e. L&#8217;un d&#8217;eux est donc un shogun\u00a0connect\u00e9 enti\u00e8rement int\u00e9gr\u00e9, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_atomos-connected-range\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-25T04:35:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-25T04:38:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/05\/maxresdefault-56.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_atomos-connected-range\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_atomos-connected-range\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"[Le salon de la production et de la technologie des m\u00e9dias 2022] Gamme connect\u00e9e Atomos\",\"datePublished\":\"2022-05-25T04:35:29+00:00\",\"dateModified\":\"2022-05-25T04:38:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_atomos-connected-range\\\/\"},\"wordCount\":341,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_atomos-connected-range\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/maxresdefault-56.jpg\",\"keywords\":[\"Information \\\/ T\u00e9l\u00e9communication\",\"Machines \\\/ Technologie industrielle\",\"Royaume-Uni\"],\"articleSection\":[\"Le salon de la production et de la technologie des m\u00e9dias 2022\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_atomos-connected-range\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_atomos-connected-range\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_atomos-connected-range\\\/\",\"name\":\"[Le salon de la production et de la technologie des m\u00e9dias 2022] Gamme connect\u00e9e Atomos \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_atomos-connected-range\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_atomos-connected-range\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/maxresdefault-56.jpg\",\"datePublished\":\"2022-05-25T04:35:29+00:00\",\"dateModified\":\"2022-05-25T04:38:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_atomos-connected-range\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_atomos-connected-range\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_atomos-connected-range\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/maxresdefault-56.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/maxresdefault-56.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\\\/_atomos-connected-range\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Le salon de la production et de la technologie des m\u00e9dias 2022] Gamme connect\u00e9e Atomos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/CrLjDv52PeQ\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"104\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[Le salon de la production et de la technologie des m\u00e9dias 2022] Gamme connect\u00e9e Atomos \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_atomos-connected-range\/","og_locale":"fr_FR","og_type":"article","og_title":"[Le salon de la production et de la technologie des m\u00e9dias 2022] Gamme connect\u00e9e Atomos \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"Gamme connect\u00e9e Atomos expos\u00e9 au Le salon de la production et de la technologie des m\u00e9dias 2022. Salut, Paul d&#8217;Atomos, nous sommes ici au Media Production Show \u00e0 Londres. Je veux juste montrer les deux nouveaux produits que nous avons\u00a0lanc\u00e9s par Atomos, de la nouvelle gamme connect\u00e9e. L&#8217;un d&#8217;eux est donc un shogun\u00a0connect\u00e9 enti\u00e8rement int\u00e9gr\u00e9, [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_atomos-connected-range\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2022-05-25T04:35:29+00:00","article_modified_time":"2022-05-25T04:38:54+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/05\/maxresdefault-56.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_atomos-connected-range\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_atomos-connected-range\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"[Le salon de la production et de la technologie des m\u00e9dias 2022] Gamme connect\u00e9e Atomos","datePublished":"2022-05-25T04:35:29+00:00","dateModified":"2022-05-25T04:38:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_atomos-connected-range\/"},"wordCount":341,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_atomos-connected-range\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/05\/maxresdefault-56.jpg","keywords":["Information \/ T\u00e9l\u00e9communication","Machines \/ Technologie industrielle","Royaume-Uni"],"articleSection":["Le salon de la production et de la technologie des m\u00e9dias 2022"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_atomos-connected-range\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_atomos-connected-range\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_atomos-connected-range\/","name":"[Le salon de la production et de la technologie des m\u00e9dias 2022] Gamme connect\u00e9e Atomos \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_atomos-connected-range\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_atomos-connected-range\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/05\/maxresdefault-56.jpg","datePublished":"2022-05-25T04:35:29+00:00","dateModified":"2022-05-25T04:38:54+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_atomos-connected-range\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_atomos-connected-range\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_atomos-connected-range\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/05\/maxresdefault-56.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/05\/maxresdefault-56.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-de-la-production-et-de-la-technologie-des-medias-2022\/_atomos-connected-range\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"[Le salon de la production et de la technologie des m\u00e9dias 2022] Gamme connect\u00e9e Atomos"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/CrLjDv52PeQ","og_video_type":"text\/html","og_video_duration":"104","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=CrLjDv52PeQ","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/40641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=40641"}],"version-history":[{"count":0,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/40641\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/40642"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=40641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=40641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=40641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}