{"id":40593,"date":"2022-05-23T12:24:24","date_gmt":"2022-05-23T12:24:24","guid":{"rendered":"https:\/\/france.worldtradeshow.tv\/?p=40593"},"modified":"2022-05-23T12:24:24","modified_gmt":"2022-05-23T12:24:24","slug":"_revolution-works-revos-ebike-conversion-kit","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-du-cycle-2022\/_revolution-works-revos-ebike-conversion-kit\/","title":{"rendered":"[Le Salon du Cycle 2022] Kit de conversion pour v\u00e9lo \u00e9lectrique Revolution Works Revos"},"content":{"rendered":"<p>Kit de conversion pour v\u00e9lo \u00e9lectrique Revolution Works Revos expos\u00e9 au Le Salon du Cycle 2022.<\/p>\n<\/p>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/cycleshow_2022\/cycleshow_2022_04-01.jpg\"><\/div>\n<div class=\"caption_text\">Salut, je travaille pour Revolution Works Limited, nous sommes bas\u00e9s \u00e0 Bristol.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/cycleshow_2022\/cycleshow_2022_04-08.jpg\"><\/div>\n<div class=\"caption_text\">ne des choses que nous fabriquons est un kit de conversion e-Bike appel\u00e9 Revos.<br \/>Le voil\u00e0, c&#8217;est \u00e7a, mont\u00e9 ici sur un poteau.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/cycleshow_2022\/cycleshow_2022_04-15.jpg\"><\/div>\n<div class=\"caption_text\">Cela s&#8217;adapte sur votre v\u00e9lo et tourne sur la roue du v\u00e9lo et fait avancer le v\u00e9lo.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/cycleshow_2022\/cycleshow_2022_04-22.jpg\"><\/div>\n<div class=\"caption_text\">Il est tr\u00e8s l\u00e9ger, le kit complet p\u00e8se 2,7 kg.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/cycleshow_2022\/cycleshow_2022_04-29.jpg\"><\/div>\n<div class=\"caption_text\">La taille de la batterie est de 200Wh et son co\u00fbt est de 595.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/cycleshow_2022\/cycleshow_2022_04-36.jpg\"><\/div>\n<div class=\"caption_text\">Voir l&#8217;unit\u00e9 d&#8217;entra\u00eenement mont\u00e9e sur le v\u00e9lo et qui fait tourner la roue arri\u00e8re.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/cycleshow_2022\/cycleshow_2022_04-43.jpg\"><\/div>\n<div class=\"caption_text\">C&#8217;est la batterie qui s&#8217;embo\u00eete dans un porte-bidon et le porte-bidon s&#8217;embo\u00eete sur le porte-bouteille sur deux plots qui y tiennent.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/cycleshow_2022\/cycleshow_2022_04-50.jpg\"><\/div>\n<div class=\"caption_text\">Vous pouvez retirer la batterie avec une cl\u00e9 ici et la serrure.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/cycleshow_2022\/cycleshow_2022_04-57.jpg\"><\/div>\n<div class=\"caption_text\">La batterie est de 200 Wh et p\u00e8se un peu moins d&#8217;un kg.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/cycleshow_2022\/cycleshow_2022_04-64.jpg\"><\/div>\n<div class=\"caption_text\">L&#8217;autre chose qui doit \u00eatre r\u00e9par\u00e9e est le capteur et le disque du capteur, donc c&#8217;est tr\u00e8s facile \u00e0 installer.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/cycleshow_2022\/cycleshow_2022_04-71.jpg\"><\/div>\n<div class=\"caption_text\">Nous pouvons l&#8217;installer en 10 minutes environ, si vous le faites pour la premi\u00e8re fois, cela prendra environ une demi-heure.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/www.tenji.tv\/wp-content\/uploads\/video_img\/cycleshow_2022\/cycleshow_2022_04-78.jpg\"><\/div>\n<div class=\"caption_text\">Mais apr\u00e8s cela, vous avez transform\u00e9 votre v\u00e9lo en v\u00e9lo \u00e9lectrique et vous avez toujours le v\u00e9lo que vous aimez.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Kit de conversion pour v\u00e9lo \u00e9lectrique Revolution Works Revos expos\u00e9 au Le Salon du Cycle 2022. Salut, je travaille pour Revolution Works Limited, nous sommes bas\u00e9s \u00e0 Bristol. ne des choses que nous fabriquons est un kit de conversion e-Bike appel\u00e9 Revos.Le voil\u00e0, c&#8217;est \u00e7a, mont\u00e9 ici sur un poteau. Cela s&#8217;adapte sur votre v\u00e9lo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":40594,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[124],"tags":[30,88],"class_list":["post-40593","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-le-salon-du-cycle-2022","tag-hobby-education","tag-united-kingdom","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[Le Salon du Cycle 2022] Kit de conversion pour v\u00e9lo \u00e9lectrique Revolution Works Revos \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-du-cycle-2022\/_revolution-works-revos-ebike-conversion-kit\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Le Salon du Cycle 2022] Kit de conversion pour v\u00e9lo \u00e9lectrique Revolution Works Revos \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"Kit de conversion pour v\u00e9lo \u00e9lectrique Revolution Works Revos expos\u00e9 au Le Salon du Cycle 2022. Salut, je travaille pour Revolution Works Limited, nous sommes bas\u00e9s \u00e0 Bristol. ne des choses que nous fabriquons est un kit de conversion e-Bike appel\u00e9 Revos.Le voil\u00e0, c&#8217;est \u00e7a, mont\u00e9 ici sur un poteau. Cela s&#8217;adapte sur votre v\u00e9lo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-du-cycle-2022\/_revolution-works-revos-ebike-conversion-kit\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-23T12:24:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/05\/maxresdefault-46.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-du-cycle-2022\\\/_revolution-works-revos-ebike-conversion-kit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-du-cycle-2022\\\/_revolution-works-revos-ebike-conversion-kit\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"[Le Salon du Cycle 2022] Kit de conversion pour v\u00e9lo \u00e9lectrique Revolution Works Revos\",\"datePublished\":\"2022-05-23T12:24:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-du-cycle-2022\\\/_revolution-works-revos-ebike-conversion-kit\\\/\"},\"wordCount\":254,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-du-cycle-2022\\\/_revolution-works-revos-ebike-conversion-kit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/maxresdefault-46.jpg\",\"keywords\":[\"Hobby \\\/ Education\",\"Royaume-Uni\"],\"articleSection\":[\"Le Salon du Cycle 2022\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-du-cycle-2022\\\/_revolution-works-revos-ebike-conversion-kit\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-du-cycle-2022\\\/_revolution-works-revos-ebike-conversion-kit\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-du-cycle-2022\\\/_revolution-works-revos-ebike-conversion-kit\\\/\",\"name\":\"[Le Salon du Cycle 2022] Kit de conversion pour v\u00e9lo \u00e9lectrique Revolution Works Revos \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-du-cycle-2022\\\/_revolution-works-revos-ebike-conversion-kit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-du-cycle-2022\\\/_revolution-works-revos-ebike-conversion-kit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/maxresdefault-46.jpg\",\"datePublished\":\"2022-05-23T12:24:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-du-cycle-2022\\\/_revolution-works-revos-ebike-conversion-kit\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-du-cycle-2022\\\/_revolution-works-revos-ebike-conversion-kit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-du-cycle-2022\\\/_revolution-works-revos-ebike-conversion-kit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/maxresdefault-46.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/maxresdefault-46.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/le-salon-du-cycle-2022\\\/_revolution-works-revos-ebike-conversion-kit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Le Salon du Cycle 2022] Kit de conversion pour v\u00e9lo \u00e9lectrique Revolution Works Revos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/KACdSaUdoiM\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"89\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[Le Salon du Cycle 2022] Kit de conversion pour v\u00e9lo \u00e9lectrique Revolution Works Revos \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-du-cycle-2022\/_revolution-works-revos-ebike-conversion-kit\/","og_locale":"fr_FR","og_type":"article","og_title":"[Le Salon du Cycle 2022] Kit de conversion pour v\u00e9lo \u00e9lectrique Revolution Works Revos \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"Kit de conversion pour v\u00e9lo \u00e9lectrique Revolution Works Revos expos\u00e9 au Le Salon du Cycle 2022. Salut, je travaille pour Revolution Works Limited, nous sommes bas\u00e9s \u00e0 Bristol. ne des choses que nous fabriquons est un kit de conversion e-Bike appel\u00e9 Revos.Le voil\u00e0, c&#8217;est \u00e7a, mont\u00e9 ici sur un poteau. Cela s&#8217;adapte sur votre v\u00e9lo [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-du-cycle-2022\/_revolution-works-revos-ebike-conversion-kit\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2022-05-23T12:24:24+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/05\/maxresdefault-46.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-du-cycle-2022\/_revolution-works-revos-ebike-conversion-kit\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-du-cycle-2022\/_revolution-works-revos-ebike-conversion-kit\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"[Le Salon du Cycle 2022] Kit de conversion pour v\u00e9lo \u00e9lectrique Revolution Works Revos","datePublished":"2022-05-23T12:24:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-du-cycle-2022\/_revolution-works-revos-ebike-conversion-kit\/"},"wordCount":254,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-du-cycle-2022\/_revolution-works-revos-ebike-conversion-kit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/05\/maxresdefault-46.jpg","keywords":["Hobby \/ Education","Royaume-Uni"],"articleSection":["Le Salon du Cycle 2022"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-du-cycle-2022\/_revolution-works-revos-ebike-conversion-kit\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-du-cycle-2022\/_revolution-works-revos-ebike-conversion-kit\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-du-cycle-2022\/_revolution-works-revos-ebike-conversion-kit\/","name":"[Le Salon du Cycle 2022] Kit de conversion pour v\u00e9lo \u00e9lectrique Revolution Works Revos \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-du-cycle-2022\/_revolution-works-revos-ebike-conversion-kit\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-du-cycle-2022\/_revolution-works-revos-ebike-conversion-kit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/05\/maxresdefault-46.jpg","datePublished":"2022-05-23T12:24:24+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-du-cycle-2022\/_revolution-works-revos-ebike-conversion-kit\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-du-cycle-2022\/_revolution-works-revos-ebike-conversion-kit\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-du-cycle-2022\/_revolution-works-revos-ebike-conversion-kit\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/05\/maxresdefault-46.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/05\/maxresdefault-46.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/le-salon-du-cycle-2022\/_revolution-works-revos-ebike-conversion-kit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"[Le Salon du Cycle 2022] Kit de conversion pour v\u00e9lo \u00e9lectrique Revolution Works Revos"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/KACdSaUdoiM","og_video_type":"text\/html","og_video_duration":"89","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=KACdSaUdoiM","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/40593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=40593"}],"version-history":[{"count":0,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/40593\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/40594"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=40593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=40593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=40593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}