{"id":39687,"date":"2022-03-25T08:30:00","date_gmt":"2022-03-25T08:30:00","guid":{"rendered":"https:\/\/france.worldtradeshow.tv\/estar_energica\/"},"modified":"2022-04-13T08:00:32","modified_gmt":"2022-04-13T08:00:32","slug":"estar_energica","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/49e-salon-de-la-moto-de-tokyo\/estar_energica\/","title":{"rendered":"[49e Salon de la moto de Tokyo] \u00c9nerg\u00e9tique - Estar"},"content":{"rendered":"<p>Estar a expos\u00e9 \u00c9nerg\u00e9tique \u00e0 49e Salon de la moto de Tokyo.<\/p>\n<p>site Internet\uff1a<a href=\"https:\/\/estar-kobe.co.jp\/\" target=\"_blank\" rel=\"noopener\">https:\/\/estar-kobe.co.jp\/<\/a><\/p>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/tenji.tv\/wp-content\/uploads\/video_img\/tmcs_2022\/tmcs_2022_03-01.jpg\"><\/div>\n<div class=\"caption_text\">Ce v\u00e9lo est utilis\u00e9 MOTO-E, une course de v\u00e9los \u00e9lectriques, parall\u00e8lement au Grand Prix MOTO, que nous connaissons et aimons tous.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/tenji.tv\/wp-content\/uploads\/video_img\/tmcs_2022\/tmcs_2022_03-08.jpg\"><\/div>\n<div class=\"caption_text\">MOTO-E se tient en Europe, et c&#8217;est la vraie voiture qui court dans la course.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/tenji.tv\/wp-content\/uploads\/video_img\/tmcs_2022\/tmcs_2022_03-15.jpg\"><\/div>\n<div class=\"caption_text\">Ce mod\u00e8le s&#8217;appelle EGO.<br \/>\u00c0 ce stade, il peut parcourir 420 km sur une seule charge.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/tenji.tv\/wp-content\/uploads\/video_img\/tmcs_2022\/tmcs_2022_03-22.jpg\"><\/div>\n<div class=\"caption_text\">Le couple de puissance est tr\u00e8s fort puisqu&#8217;il s&#8217;agit d&#8217;un v\u00e9lo \u00e9lectrique, et le temps pour atteindre 100KM est de 2,6 secondes.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/tenji.tv\/wp-content\/uploads\/video_img\/tmcs_2022\/tmcs_2022_03-36.jpg\"><\/div>\n<div class=\"caption_text\">Comme il s&#8217;agit d&#8217;un v\u00e9lo \u00e9lectrique, il n&#8217;a pas d&#8217;embrayage, ce qui peut sembler \u00e9trange \u00e0 ceux d&#8217;entre vous qui roulent sur des v\u00e9los \u00e0 essence.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/tenji.tv\/wp-content\/uploads\/video_img\/tmcs_2022\/tmcs_2022_03-43.jpg\"><\/div>\n<div class=\"caption_text\">Par contre, une fois qu&#8217;on s&#8217;habitue \u00e0 rouler, cela devient tr\u00e8s facile.<br \/>J&#8217;esp\u00e8re que tout le monde fera d\u00e9sormais l&#8217;exp\u00e9rience de l&#8217;\u00e9lectricit\u00e9 parmi les s\u00e9lections. Merci en avance.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Estar a expos\u00e9 \u00c9nerg\u00e9tique \u00e0 49e Salon de la moto de Tokyo. site Internet\uff1ahttps:\/\/estar-kobe.co.jp\/ Ce v\u00e9lo est utilis\u00e9 MOTO-E, une course de v\u00e9los \u00e9lectriques, parall\u00e8lement au Grand Prix MOTO, que nous connaissons et aimons tous. MOTO-E se tient en Europe, et c&#8217;est la vraie voiture qui court dans la course. Ce mod\u00e8le s&#8217;appelle EGO.\u00c0 ce [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":39688,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[81],"tags":[30,38,37],"class_list":["post-39687","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-49e-salon-de-la-moto-de-tokyo","tag-hobby-education","tag-japan","tag-transportation-logistics-packaging","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[49e Salon de la moto de Tokyo] \u00c9nerg\u00e9tique - Estar \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/49e-salon-de-la-moto-de-tokyo\/estar_energica\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[49e Salon de la moto de Tokyo] \u00c9nerg\u00e9tique - Estar \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"Estar a expos\u00e9 \u00c9nerg\u00e9tique \u00e0 49e Salon de la moto de Tokyo. site Internet\uff1ahttps:\/\/estar-kobe.co.jp\/ Ce v\u00e9lo est utilis\u00e9 MOTO-E, une course de v\u00e9los \u00e9lectriques, parall\u00e8lement au Grand Prix MOTO, que nous connaissons et aimons tous. MOTO-E se tient en Europe, et c&#8217;est la vraie voiture qui court dans la course. Ce mod\u00e8le s&#8217;appelle EGO.\u00c0 ce [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/49e-salon-de-la-moto-de-tokyo\/estar_energica\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-25T08:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-13T08:00:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/04\/maxresdefault-30.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/49e-salon-de-la-moto-de-tokyo\\\/estar_energica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/49e-salon-de-la-moto-de-tokyo\\\/estar_energica\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"[49e Salon de la moto de Tokyo] \u00c9nerg\u00e9tique - Estar\",\"datePublished\":\"2022-03-25T08:30:00+00:00\",\"dateModified\":\"2022-04-13T08:00:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/49e-salon-de-la-moto-de-tokyo\\\/estar_energica\\\/\"},\"wordCount\":179,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/49e-salon-de-la-moto-de-tokyo\\\/estar_energica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/maxresdefault-30.jpg\",\"keywords\":[\"Hobby \\\/ Education\",\"Japon\",\"Transport \\\/ Logistique \\\/ Emballage\"],\"articleSection\":[\"49e Salon de la moto de Tokyo\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/49e-salon-de-la-moto-de-tokyo\\\/estar_energica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/49e-salon-de-la-moto-de-tokyo\\\/estar_energica\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/49e-salon-de-la-moto-de-tokyo\\\/estar_energica\\\/\",\"name\":\"[49e Salon de la moto de Tokyo] \u00c9nerg\u00e9tique - Estar \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/49e-salon-de-la-moto-de-tokyo\\\/estar_energica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/49e-salon-de-la-moto-de-tokyo\\\/estar_energica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/maxresdefault-30.jpg\",\"datePublished\":\"2022-03-25T08:30:00+00:00\",\"dateModified\":\"2022-04-13T08:00:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/49e-salon-de-la-moto-de-tokyo\\\/estar_energica\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/49e-salon-de-la-moto-de-tokyo\\\/estar_energica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/49e-salon-de-la-moto-de-tokyo\\\/estar_energica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/maxresdefault-30.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/maxresdefault-30.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/49e-salon-de-la-moto-de-tokyo\\\/estar_energica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[49e Salon de la moto de Tokyo] \u00c9nerg\u00e9tique - Estar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[49e Salon de la moto de Tokyo] \u00c9nerg\u00e9tique - Estar \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/49e-salon-de-la-moto-de-tokyo\/estar_energica\/","og_locale":"fr_FR","og_type":"article","og_title":"[49e Salon de la moto de Tokyo] \u00c9nerg\u00e9tique - Estar \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"Estar a expos\u00e9 \u00c9nerg\u00e9tique \u00e0 49e Salon de la moto de Tokyo. site Internet\uff1ahttps:\/\/estar-kobe.co.jp\/ Ce v\u00e9lo est utilis\u00e9 MOTO-E, une course de v\u00e9los \u00e9lectriques, parall\u00e8lement au Grand Prix MOTO, que nous connaissons et aimons tous. MOTO-E se tient en Europe, et c&#8217;est la vraie voiture qui court dans la course. Ce mod\u00e8le s&#8217;appelle EGO.\u00c0 ce [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/49e-salon-de-la-moto-de-tokyo\/estar_energica\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2022-03-25T08:30:00+00:00","article_modified_time":"2022-04-13T08:00:32+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/04\/maxresdefault-30.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/49e-salon-de-la-moto-de-tokyo\/estar_energica\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/49e-salon-de-la-moto-de-tokyo\/estar_energica\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"[49e Salon de la moto de Tokyo] \u00c9nerg\u00e9tique - Estar","datePublished":"2022-03-25T08:30:00+00:00","dateModified":"2022-04-13T08:00:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/49e-salon-de-la-moto-de-tokyo\/estar_energica\/"},"wordCount":179,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/49e-salon-de-la-moto-de-tokyo\/estar_energica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/04\/maxresdefault-30.jpg","keywords":["Hobby \/ Education","Japon","Transport \/ Logistique \/ Emballage"],"articleSection":["49e Salon de la moto de Tokyo"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/49e-salon-de-la-moto-de-tokyo\/estar_energica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/49e-salon-de-la-moto-de-tokyo\/estar_energica\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/49e-salon-de-la-moto-de-tokyo\/estar_energica\/","name":"[49e Salon de la moto de Tokyo] \u00c9nerg\u00e9tique - Estar \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/49e-salon-de-la-moto-de-tokyo\/estar_energica\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/49e-salon-de-la-moto-de-tokyo\/estar_energica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/04\/maxresdefault-30.jpg","datePublished":"2022-03-25T08:30:00+00:00","dateModified":"2022-04-13T08:00:32+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/49e-salon-de-la-moto-de-tokyo\/estar_energica\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/49e-salon-de-la-moto-de-tokyo\/estar_energica\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/49e-salon-de-la-moto-de-tokyo\/estar_energica\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/04\/maxresdefault-30.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/04\/maxresdefault-30.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/49e-salon-de-la-moto-de-tokyo\/estar_energica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"[49e Salon de la moto de Tokyo] \u00c9nerg\u00e9tique - Estar"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]}},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=-sfq7kNzRxQ","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/39687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=39687"}],"version-history":[{"count":0,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/39687\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/39688"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=39687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=39687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=39687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}