{"id":39662,"date":"2022-03-10T08:30:00","date_gmt":"2022-03-10T08:30:00","guid":{"rendered":"https:\/\/france.worldtradeshow.tv\/testonic_air-max\/"},"modified":"2022-04-08T07:35:46","modified_gmt":"2022-04-08T07:35:46","slug":"testonic_air-max","status":"publish","type":"post","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\/testonic_air-max\/","title":{"rendered":"[KIMES 2022 - Salon cor\u00e9en international de l'\u00e9quipement m\u00e9dical et hospitalier] AIR MAX - TESTONIQUE"},"content":{"rendered":"<p>TESTONIQUE a expos\u00e9 AIR MAX \u00e0 KIMES 2022 &#8211; Salon cor\u00e9en international de l&#8217;\u00e9quipement m\u00e9dical et hospitalier.<\/p>\n<\/p>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/tenji.tv\/wp-content\/uploads\/video_img\/kimes_2022\/kimes_2022_04-01.jpg\"><\/div>\n<div class=\"caption_text\">Bonjour, notre soci\u00e9t\u00e9 s&#8217;appelle Testonic Co., Ltd.<br \/>Notre entreprise est une entreprise qui d\u00e9veloppe et produit des tapis d&#8217;aspiration<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/tenji.tv\/wp-content\/uploads\/video_img\/kimes_2022\/kimes_2022_04-08.jpg\"><\/div>\n<div class=\"caption_text\">qui \u00e9limine les substances \u00e9trang\u00e8res, les poussi\u00e8res fines, les virus, etc. qui p\u00e9n\u00e8trent dans la pi\u00e8ce en \u00e9tant tach\u00e9s de chaussures.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/tenji.tv\/wp-content\/uploads\/video_img\/kimes_2022\/kimes_2022_04-15.jpg\"><\/div>\n<div class=\"caption_text\">Nous d\u00e9veloppons cela depuis plus de 10 ans.<br \/>Il existe des entreprises similaires au Japon et aux \u00c9tats-Unis, mais le produit que nous avons d\u00e9velopp\u00e9 est beaucoup vendu car il a une bien meilleure puissance d&#8217;aspiration et d&#8217;\u00e9limination.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/tenji.tv\/wp-content\/uploads\/video_img\/kimes_2022\/kimes_2022_04-29.jpg\"><\/div>\n<div class=\"caption_text\">Il est actuellement utilis\u00e9 \u00e0 la station foresti\u00e8re de S\u00e9oul et \u00e0 la station Suyu, et nous pr\u00e9voyons de l&#8217;\u00e9tendre cette ann\u00e9e \u00e0 d&#8217;autres stations en Cor\u00e9e.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/tenji.tv\/wp-content\/uploads\/video_img\/kimes_2022\/kimes_2022_04-36.jpg\"><\/div>\n<div class=\"caption_text\">Notre site Web est maintenant disponible en japonais, chinois et anglais, vous pouvez donc nous contacter.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/tenji.tv\/wp-content\/uploads\/video_img\/kimes_2022\/kimes_2022_04-43.jpg\"><\/div>\n<div class=\"caption_text\">L&#8217;adresse e-mail du support client est \u00e9crite sur notre site Web. Si vous nous contactez, nous pouvons vous r\u00e9pondre \u00e0 tout moment.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/tenji.tv\/wp-content\/uploads\/video_img\/kimes_2022\/kimes_2022_04-50.jpg\"><\/div>\n<div class=\"caption_text\">Beaucoup de nos clients recherchent nos produits car les n\u00f4tres se sont av\u00e9r\u00e9s tr\u00e8s efficaces pour \u00e9liminer les virus \u00e0 l&#8217;\u00e8re With Corona.<\/div>\n<\/div>\n<div class=\"caption_box\">\n<div class=\"caption_img\"><img decoding=\"async\" src=\"https:\/\/tenji.tv\/wp-content\/uploads\/video_img\/kimes_2022\/kimes_2022_04-57.jpg\"><\/div>\n<div class=\"caption_text\">J&#8217;esp\u00e8re que nous pourrons faire un bon produit ensemble.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>TESTONIQUE a expos\u00e9 AIR MAX \u00e0 KIMES 2022 &#8211; Salon cor\u00e9en international de l&#8217;\u00e9quipement m\u00e9dical et hospitalier. Bonjour, notre soci\u00e9t\u00e9 s&#8217;appelle Testonic Co., Ltd.Notre entreprise est une entreprise qui d\u00e9veloppe et produit des tapis d&#8217;aspiration qui \u00e9limine les substances \u00e9trang\u00e8res, les poussi\u00e8res fines, les virus, etc. qui p\u00e9n\u00e8trent dans la pi\u00e8ce en \u00e9tant tach\u00e9s de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":39663,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[80],"tags":[46,34],"class_list":["post-39662","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier","tag-korea","tag-medical-care-health","post_format-post-format-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[KIMES 2022 - Salon cor\u00e9en international de l&#039;\u00e9quipement m\u00e9dical et hospitalier] AIR MAX - TESTONIQUE \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\/testonic_air-max\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[KIMES 2022 - Salon cor\u00e9en international de l&#039;\u00e9quipement m\u00e9dical et hospitalier] AIR MAX - TESTONIQUE \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"TESTONIQUE a expos\u00e9 AIR MAX \u00e0 KIMES 2022 &#8211; Salon cor\u00e9en international de l&#8217;\u00e9quipement m\u00e9dical et hospitalier. Bonjour, notre soci\u00e9t\u00e9 s&#8217;appelle Testonic Co., Ltd.Notre entreprise est une entreprise qui d\u00e9veloppe et produit des tapis d&#8217;aspiration qui \u00e9limine les substances \u00e9trang\u00e8res, les poussi\u00e8res fines, les virus, etc. qui p\u00e9n\u00e8trent dans la pi\u00e8ce en \u00e9tant tach\u00e9s de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\/testonic_air-max\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tenji.tv\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-10T08:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-08T07:35:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/04\/maxresdefault-23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\\\/testonic_air-max\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\\\/testonic_air-max\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"headline\":\"[KIMES 2022 - Salon cor\u00e9en international de l'\u00e9quipement m\u00e9dical et hospitalier] AIR MAX - TESTONIQUE\",\"datePublished\":\"2022-03-10T08:30:00+00:00\",\"dateModified\":\"2022-04-08T07:35:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\\\/testonic_air-max\\\/\"},\"wordCount\":234,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\\\/testonic_air-max\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/maxresdefault-23.jpg\",\"keywords\":[\"Cor\u00e9e\",\"Soins m\u00e9dicaux \\\/ Sant\u00e9\"],\"articleSection\":[\"KIMES 2022 - Salon cor\u00e9en international de l'\u00e9quipement m\u00e9dical et hospitalier\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\\\/testonic_air-max\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\\\/testonic_air-max\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\\\/testonic_air-max\\\/\",\"name\":\"[KIMES 2022 - Salon cor\u00e9en international de l'\u00e9quipement m\u00e9dical et hospitalier] AIR MAX - TESTONIQUE \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\\\/testonic_air-max\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\\\/testonic_air-max\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/maxresdefault-23.jpg\",\"datePublished\":\"2022-03-10T08:30:00+00:00\",\"dateModified\":\"2022-04-08T07:35:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\\\/testonic_air-max\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\\\/testonic_air-max\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\\\/testonic_air-max\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/maxresdefault-23.jpg\",\"contentUrl\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/maxresdefault-23.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\\\/testonic_air-max\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[KIMES 2022 - Salon cor\u00e9en international de l'\u00e9quipement m\u00e9dical et hospitalier] AIR MAX - TESTONIQUE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#\\\/schema\\\/person\\\/a9d7eceb3b29066a8084fc2872dbed3f\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g\",\"caption\":\"user\"},\"sameAs\":[\"http:\"]}]}<\/script>\n<meta property=\"og:video\" content=\"https:\/\/www.youtube.com\/embed\/DzlnAFuXwbg\" \/>\n<meta property=\"og:video:type\" content=\"text\/html\" \/>\n<meta property=\"og:video:duration\" content=\"69\" \/>\n<meta property=\"og:video:width\" content=\"480\" \/>\n<meta property=\"og:video:height\" content=\"270\" \/>\n<meta property=\"ya:ovs:adult\" content=\"false\" \/>\n<meta property=\"ya:ovs:allow_embed\" content=\"true\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[KIMES 2022 - Salon cor\u00e9en international de l'\u00e9quipement m\u00e9dical et hospitalier] AIR MAX - TESTONIQUE \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\/testonic_air-max\/","og_locale":"fr_FR","og_type":"article","og_title":"[KIMES 2022 - Salon cor\u00e9en international de l'\u00e9quipement m\u00e9dical et hospitalier] AIR MAX - TESTONIQUE \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","og_description":"TESTONIQUE a expos\u00e9 AIR MAX \u00e0 KIMES 2022 &#8211; Salon cor\u00e9en international de l&#8217;\u00e9quipement m\u00e9dical et hospitalier. Bonjour, notre soci\u00e9t\u00e9 s&#8217;appelle Testonic Co., Ltd.Notre entreprise est une entreprise qui d\u00e9veloppe et produit des tapis d&#8217;aspiration qui \u00e9limine les substances \u00e9trang\u00e8res, les poussi\u00e8res fines, les virus, etc. qui p\u00e9n\u00e8trent dans la pi\u00e8ce en \u00e9tant tach\u00e9s de [&hellip;]","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\/testonic_air-max\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","article_publisher":"https:\/\/www.facebook.com\/tenji.tv","article_published_time":"2022-03-10T08:30:00+00:00","article_modified_time":"2022-04-08T07:35:46+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/04\/maxresdefault-23.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","twitter_creator":"@tenjitv","twitter_site":"@tenjitv","twitter_misc":{"\u00c9crit par":"user","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\/testonic_air-max\/#article","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\/testonic_air-max\/"},"author":{"name":"user","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"headline":"[KIMES 2022 - Salon cor\u00e9en international de l'\u00e9quipement m\u00e9dical et hospitalier] AIR MAX - TESTONIQUE","datePublished":"2022-03-10T08:30:00+00:00","dateModified":"2022-04-08T07:35:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\/testonic_air-max\/"},"wordCount":234,"commentCount":0,"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\/testonic_air-max\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/04\/maxresdefault-23.jpg","keywords":["Cor\u00e9e","Soins m\u00e9dicaux \/ Sant\u00e9"],"articleSection":["KIMES 2022 - Salon cor\u00e9en international de l'\u00e9quipement m\u00e9dical et hospitalier"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\/testonic_air-max\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\/testonic_air-max\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\/testonic_air-max\/","name":"[KIMES 2022 - Salon cor\u00e9en international de l'\u00e9quipement m\u00e9dical et hospitalier] AIR MAX - TESTONIQUE \u2013 Vid\u00e9o du Salon | WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\/testonic_air-max\/#primaryimage"},"image":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\/testonic_air-max\/#primaryimage"},"thumbnailUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/04\/maxresdefault-23.jpg","datePublished":"2022-03-10T08:30:00+00:00","dateModified":"2022-04-08T07:35:46+00:00","author":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f"},"breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\/testonic_air-max\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.worldtradeshow.tv\/french\/video\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\/testonic_air-max\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\/testonic_air-max\/#primaryimage","url":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/04\/maxresdefault-23.jpg","contentUrl":"https:\/\/www.worldtradeshow.tv\/french\/wp-content\/uploads\/2022\/04\/maxresdefault-23.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/kimes-2022-salon-coreen-international-de-lequipement-medical-et-hospitalier\/testonic_air-max\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"[KIMES 2022 - Salon cor\u00e9en international de l'\u00e9quipement m\u00e9dical et hospitalier] AIR MAX - TESTONIQUE"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.worldtradeshow.tv\/french\/#\/schema\/person\/a9d7eceb3b29066a8084fc2872dbed3f","name":"user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b4c9a289323b21a01c3e940f150eb9b8c542587f1abfd8f0e1cc1ffc5e475514?s=96&d=mm&r=g","caption":"user"},"sameAs":["http:"]}]},"og_video":"https:\/\/www.youtube.com\/embed\/DzlnAFuXwbg","og_video_type":"text\/html","og_video_duration":"69","og_video_width":"480","og_video_height":"270","ya_ovs_adult":"false","ya_ovs_allow_embed":"true"},"cmb2":{"poster_feature_image":{"vid_m_player_background":"on","vid_m_poster_image":"","vid_m_poster_image_id":""},"gif_feature_image":{"vid_m_gif_image":"","vid_m_gif_image_id":""},"video_movie_settings":{"vid_m_director":"","vid_m_actor":"","vid_m_imdb_ratings":"","vid_m_amazon_associates":"","vid_m_vid_tmdb_movie":"","vid_m_vid_tmdb_tv_shows":"","vid_m_vid_tmdb_thumb":"backdrop_sizes"},"vid_ads_m_videoads_settings_post":{"vid_ads_m_video_ads":"","vid_ads_m_video_ads_type":"","vid_ads_m_group_google_ima":"","vid_ads_m_group_image":"","vid_ads_m_group_html5_video":"","vid_ads_m_group_html":"","vid_ads_m_vpaid_mode":"","vid_ads_m_vast_preroll":"","vid_ads_m_vast_postroll":"","vid_ads_m_vast_pauseroll":"","vid_ads_m_vast_midroll":"","vid_ads_m_group_dynamic":"","vid_ads_m_time_to_show_ads":"","vid_ads_m_time_skip_ads":"","vid_ads_m_time_to_hide_ads":""},"feature_image_settings":{"feature_image_position":""},"video_player_settings":{"single_video_style":"","video_player_position":"","vm_video_url_btn_choose":"","vm_video_url_btn_choose_id":"","vm_video_url":"https:\/\/www.youtube.com\/watch?v=DzlnAFuXwbg","vm_video_ratio":"16:9","vm_video_ratio_mobile":"16:9","video_player_library":"","plyr_player":"","video_streaming":"","vm_video_shortcode":"","vm_video_timelapse":"","vm_media_subtitles":"","vm_media_sources":"","vid_vtt_preview":"","vid_vtt_preview_vtt_file":"","vid_vtt_preview_vtt_file_id":"","vid_vtt_preview_sprite_image":"","vid_vtt_preview_sprite_image_id":"","vid_auto_play":"","vid_preview_mode":"","vm_video_trailer_manl_url":"","vm_screenshot_preview":"","vid_tags":"","vid_p_sync_playlist":"","vid_c_sync_channel":"","get_post_format":"","multiple_links_structure":"default","multi_links_title":"","original_video_title":"","multi_links_series":"","vm_video_multi_links":"","vm_duration":"","vid_social_locker":"","vid_locker_mode":"social","vid_social_locker_id":"","vid_social_email_locker_id":"","vid_social_signin_locker_id":"","sv_login_to_watch":"","vid_membership_action":"content-video","vm_video_trailer_url":"","vid_download_type":"free","vid_download_target":"download","vid_woo_product":"","vid_download_mode":"","vid_download_mode_trailer":"","vm_media_download":"","user_rating":"","user_rating_position":"","user_rating_mode":"","user_rating_multi_sets":"","ads_above_single_player":""},"video_auto_fetch_settings":{"vm_video_fetch":"on"},"video_fake_views_likes":{"vm_fake_views":"","vm_fake_likes":"","vm_fake_dislikes":""},"gallery_settings":{"gallery_position":""},"quote_settings":{"quote_position":""},"post_options":{"main_layout":"","main_logo":"","main_logo_id":"","main_logo_retina":"","main_logo_retina_id":"","main_logo_mobile":"","main_logo_mobile_id":"","main_logo_mobile_retina":"","main_logo_mobile_retina_id":"","sticky_logo":"","sticky_logo_id":"","sticky_logo_retina":"","sticky_logo_retina_id":"","main_nav_layout":"","header_background":"","theme_sidebar":"","single_post_comment_type":"","theme_background":""}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/39662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/comments?post=39662"}],"version-history":[{"count":0,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts\/39662\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media\/39663"}],"wp:attachment":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/media?parent=39662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories?post=39662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/tags?post=39662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}