{"id":800,"count":10,"description":"","link":"https:\/\/www.worldtradeshow.tv\/french\/video\/category\/caferes-japan-2026-japan\/","name":"CAFERES JAPAN 2026","slug":"caferes-japan-2026-japan","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CAFERES JAPAN 2026 Salons et Vid\u00e9os | Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez les salons en CAFERES JAPAN 2026. Explorez les nouveaux produits, innovations et opportunit\u00e9s commerciales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.worldtradeshow.tv\/french\/video\/category\/caferes-japan-2026-japan\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CAFERES JAPAN 2026 Salons et Vid\u00e9os | Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez les salons en CAFERES JAPAN 2026. Explorez les nouveaux produits, innovations et opportunit\u00e9s commerciales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.worldtradeshow.tv\/french\/video\/category\/caferes-japan-2026-japan\/\" \/>\n<meta property=\"og:site_name\" content=\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@tenjitv\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/category\\\/caferes-japan-2026-japan\\\/\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/category\\\/caferes-japan-2026-japan\\\/\",\"name\":\"CAFERES JAPAN 2026 Salons et Vid\u00e9os | Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\"},\"description\":\"D\u00e9couvrez les salons en CAFERES JAPAN 2026. Explorez les nouveaux produits, innovations et opportunit\u00e9s commerciales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/category\\\/caferes-japan-2026-japan\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/video\\\/category\\\/caferes-japan-2026-japan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CAFERES JAPAN 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/#website\",\"url\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/\",\"name\":\"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV\",\"description\":\"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.worldtradeshow.tv\\\/french\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CAFERES JAPAN 2026 Salons et Vid\u00e9os | Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez les salons en CAFERES JAPAN 2026. Explorez les nouveaux produits, innovations et opportunit\u00e9s commerciales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.worldtradeshow.tv\/french\/video\/category\/caferes-japan-2026-japan\/","og_locale":"fr_FR","og_type":"article","og_title":"CAFERES JAPAN 2026 Salons et Vid\u00e9os | Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","og_description":"D\u00e9couvrez les salons en CAFERES JAPAN 2026. Explorez les nouveaux produits, innovations et opportunit\u00e9s commerciales.","og_url":"https:\/\/www.worldtradeshow.tv\/french\/video\/category\/caferes-japan-2026-japan\/","og_site_name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","twitter_card":"summary_large_image","twitter_site":"@tenjitv","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/category\/caferes-japan-2026-japan\/","url":"https:\/\/www.worldtradeshow.tv\/french\/video\/category\/caferes-japan-2026-japan\/","name":"CAFERES JAPAN 2026 Salons et Vid\u00e9os | Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","isPartOf":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/#website"},"description":"D\u00e9couvrez les salons en CAFERES JAPAN 2026. Explorez les nouveaux produits, innovations et opportunit\u00e9s commerciales.","breadcrumb":{"@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/category\/caferes-japan-2026-japan\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.worldtradeshow.tv\/french\/video\/category\/caferes-japan-2026-japan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.worldtradeshow.tv\/french\/"},{"@type":"ListItem","position":2,"name":"CAFERES JAPAN 2026"}]},{"@type":"WebSite","@id":"https:\/\/www.worldtradeshow.tv\/french\/#website","url":"https:\/\/www.worldtradeshow.tv\/french\/","name":"Vid\u00e9os de Salons Internationaux et Nouveaux Produits \u2013 WorldTradeShow.TV","description":"D\u00e9couvrez des vid\u00e9os de salons internationaux et de nouveaux produits en fran\u00e7ais","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.worldtradeshow.tv\/french\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories\/800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.worldtradeshow.tv\/french\/wp-json\/wp\/v2\/posts?categories=800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}